{"id":7568,"date":"2026-01-06T07:26:09","date_gmt":"2026-01-06T07:26:09","guid":{"rendered":"https:\/\/demo.rstheme.com\/wordpress\/brickz\/?page_id=7568"},"modified":"2026-07-09T10:00:31","modified_gmt":"2026-07-09T02:00:31","slug":"smart-construction-onepage","status":"publish","type":"page","link":"https:\/\/warehousetentpro.com\/index.php\/smart-construction-onepage\/","title":{"rendered":"Smart Construction Onepage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7568\" class=\"elementor elementor-7568\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30b9f42b e-con-full e-flex e-con e-parent\" data-id=\"30b9f42b\" data-element_type=\"container\" data-e-type=\"container\" id=\"home\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26cb791f gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-slider_revolution\" data-id=\"26cb791f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"slider_01-1\" data-id=\"1\" id=\"SR7_1_1\" data-version=\"6.7.58\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-1\" data-key=\"1\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-1-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/shoulderstorage.com\/wp-content\/uploads\/2025\/12\/slider_0002.jpg\" alt=\"\" title=\"slider_0002\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-1-0\" class=\"sr7-layer\">Delivering Quality Construction<\/sr7-txt>\n\t\t\t\t\t\t\t<h1 id=\"SR7_1_1-1-1\" class=\"sr7-layer\">Built With Strength and Precision<\/h1>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-1-4\" class=\"sr7-layer\">We believe that every business is uniquids our approach is never one size fits all We tailor our strategies to fit your goals hub.<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-1-7\" class=\"sr7-layer\"><div class=\"rs-button style1 btn-marketing-style1\"><a class=\"rs-btn anim-dir-angle\" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/contact-us\/\" style=\"gap: 6px;\"><span class=\"rs-btn-active\"><span>Service Request<\/span><\/span><em style=\"width: 19px;height:19px;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"19\" viewBox=\"0 0 22 22\" fill=\"none\"><path d=\"M14.6703 8.6295L6.78054 16.5192L5.48438 15.2231L13.3732 7.33333H6.42029V5.5H16.5036V15.5833H14.6703V8.6295Z\" fill=\"white\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"22\" viewBox=\"0 0 22 22\" fill=\"none\"><path d=\"M14.6703 8.6295L6.78054 16.5192L5.48438 15.2231L13.3732 7.33333H6.42029V5.5H16.5036V15.5833H14.6703V8.6295Z\" fill=\"white\"><\/path><\/svg><\/em><\/a><br \/>\n<\/div><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-2\" data-key=\"2\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-2-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/shoulderstorage.com\/wp-content\/uploads\/2025\/12\/slider_0002.jpg\" alt=\"\" title=\"slider_0002\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-2-0\" class=\"sr7-layer\">Your Vision Our Expertise<\/sr7-txt>\n\t\t\t\t\t\t\t<h1 id=\"SR7_1_1-2-1\" class=\"sr7-layer\">Built Modern Excellence and Precision<\/h1>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-2-4\" class=\"sr7-layer\">We believe that every business is uniquids our approach is never one size fits all We tailor our strategies to fit your goals hub.<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-2-7\" class=\"sr7-layer\"><div class=\"rs-button style1 btn-marketing-style1\"><a class=\"rs-btn anim-dir-angle\" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/contact-us\/\" style=\"gap: 6px;\"><span class=\"rs-btn-active\"><span>Service Request<\/span><\/span><em style=\"width: 19px;height:19px;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"19\" viewBox=\"0 0 22 22\" fill=\"none\"><path d=\"M14.6703 8.6295L6.78054 16.5192L5.48438 15.2231L13.3732 7.33333H6.42029V5.5H16.5036V15.5833H14.6703V8.6295Z\" fill=\"white\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"22\" viewBox=\"0 0 22 22\" fill=\"none\"><path d=\"M14.6703 8.6295L6.78054 16.5192L5.48438 15.2231L13.3732 7.33333H6.42029V5.5H16.5036V15.5833H14.6703V8.6295Z\" fill=\"white\"><\/path><\/svg><\/em><\/a><br \/>\n<\/div><\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-8\" data-key=\"8\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_1_1\"] = {cn:100,state:false,fn: function() { if (window._tpt!==undefined && window._tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_1_1\",el:[960,820,768,747],type:'standard',shdw:'0',gh:[960,820,768,747],gw:[1770,1024,778,480],vpt:['-200px'],size:{fullWidth:true, fullHeight:false},mh:'0',onh:0,onw:0,bg:{color:'transparent'}});   SR7.PMH[\"SR7_1_1\"].state=true;} else if(SR7.PMH[\"SR7_1_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_1_1\"].fn,19);}};SR7.PMH[\"SR7_1_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e013248 e-flex e-con-boxed e-con e-parent\" data-id=\"e013248\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47eb470 e-con-full e-flex e-con e-child\" data-id=\"47eb470\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aaaac61 elementor-widget-laptop__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"aaaac61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"423\" height=\"453\" viewBox=\"0 0 423 453\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M62.609 210.138L46.656 194.185C43.976 191.511 43.976 187.167 46.656 184.487C49.33 181.812 53.674 181.812 56.348 184.487L67.068 195.212L94.156 163.6C96.622 160.729 100.948 160.394 103.831 162.861C106.702 165.321 107.037 169.653 104.57 172.524L72.659 209.756C70.063 212.787 65.426 212.954 62.609 210.138ZM124.42 129.061C124.42 125.278 127.481 122.205 131.276 122.205L370.582 122.199C374.377 122.199 377.438 125.271 377.438 129.055C377.438 132.838 374.377 135.911 370.582 135.911L131.276 135.917C127.482 135.916 124.421 132.844 124.42 129.061ZM46.654 136.565C43.974 133.885 43.974 129.547 46.654 126.867C49.328 124.198 53.672 124.198 56.346 126.867L67.066 137.587L94.154 105.981C96.62 103.11 100.946 102.775 103.829 105.242C106.7 107.708 107.035 112.034 104.568 114.911L72.657 152.131C70.048 155.182 65.42 155.332 62.607 152.524L46.654 136.565ZM359.557 415.937H357.945L357.943 349.878H359.555C386.47 349.877 408.384 364.698 408.385 382.909C408.386 401.12 386.473 415.936 359.557 415.937ZM306.614 340.43C304.384 341.164 302.675 342.972 302.092 345.247C299.903 353.784 296.501 361.974 291.996 369.575C290.801 371.597 290.725 374.092 291.788 376.189L302 396.225L285.47 412.75L265.439 402.539C263.342 401.476 260.847 401.551 258.826 402.747C251.225 407.252 243.035 410.649 234.498 412.844C232.222 413.427 230.409 415.137 229.681 417.367L222.733 438.738L199.364 438.739L192.415 417.368C191.693 415.138 189.874 413.429 187.598 412.846C179.067 410.657 170.888 407.256 163.264 402.751C161.243 401.555 158.747 401.48 156.668 402.543L136.632 412.755L120.095 396.231L130.3 376.194C131.374 374.097 131.293 371.614 130.092 369.58C125.598 361.979 122.196 353.789 120.001 345.252C119.423 342.976 117.72 341.168 115.484 340.435L94.113 333.499V320.59L145.715 320.589C145.703 320.993 145.698 321.403 145.698 321.808C145.699 357.838 175.012 387.161 211.054 387.16C247.084 387.159 276.407 357.834 276.406 321.804C276.406 321.4 276.389 320.99 276.377 320.585L327.984 320.584V333.493L306.614 340.43ZM196.62 170.073C206.192 168.411 215.884 168.408 225.459 170.072L225.461 234.074C225.461 235.472 224.283 236.65 222.885 236.65L199.21 236.651C197.812 236.651 196.622 235.473 196.622 234.075L196.62 170.073ZM126.618 253.259C126.618 258.405 127.08 263.534 127.999 268.559L294.09 268.555C301.716 227.088 277.624 187.281 239.171 173.653L239.172 234.074C239.172 243.044 231.872 250.356 222.884 250.356L199.209 250.357C190.222 250.357 182.909 243.045 182.909 234.075L182.908 173.654C150.153 185.265 126.617 216.571 126.618 253.259ZM74.51 306.878C72.968 306.878 71.657 305.573 71.656 304.025V285.126C71.656 283.584 72.967 282.273 74.509 282.273L347.58 282.266C349.134 282.266 350.439 283.577 350.439 285.119V304.018C350.439 305.566 349.134 306.871 347.58 306.871L74.51 306.878ZM262.693 321.804C262.693 321.4 262.676 320.99 262.664 320.585L159.426 320.588C158.599 349.296 182.021 373.448 211.052 373.447C239.522 373.446 262.694 350.273 262.693 321.804ZM13.713 303.148C13.713 321.048 38.579 336.174 68.001 336.173H80.402V320.59H74.511C65.379 320.59 57.946 313.163 57.945 304.025V285.126C57.945 275.994 65.378 268.561 74.51 268.56L114.098 268.559C104.805 208.923 150.889 155.12 211.049 155.119C235.966 155.118 258.741 164.457 276.074 179.821L370.585 179.819C374.38 179.819 377.441 182.88 377.441 186.675C377.441 190.458 374.38 193.531 370.585 193.531L288.856 193.533C304.997 214.493 312.257 241.381 307.993 268.555L347.581 268.554C356.719 268.554 364.152 275.987 364.152 285.119V304.018C364.152 313.155 356.719 320.583 347.582 320.584H341.697V336.167H359.556C378.017 336.167 395.918 342.096 408.386 353.58L408.38 126.502C408.38 108.597 383.514 93.471 354.08 93.471L62.537 93.478C44.17 93.478 26.073 87.545 13.707 76.077L13.713 303.148ZM62.535 13.707H64.135L64.137 79.766H62.537C35.61 79.767 13.708 64.952 13.707 46.747C13.706 28.529 35.608 13.707 62.535 13.707ZM401.066 92.556C388.417 84.302 371.73 79.757 354.079 79.758L77.848 79.765L77.846 6.856C77.846 3.067 74.785 0 70.99 0H62.534C46.24 0 30.836 4.604 19.163 12.962C6.809 21.817 0 33.82 0 46.746L0.00600052 303.148C0.00600052 316.196 7.463 328.25 21.019 337.092C33.668 345.346 50.361 349.885 68 349.884L100.201 349.883L107.744 352.332C109.881 359.592 112.787 366.598 116.408 373.246L105.614 394.432C104.268 397.083 104.782 400.295 106.879 402.397L130.457 425.968C132.554 428.07 135.771 428.584 138.41 427.227L159.601 416.437C166.261 420.064 173.261 422.969 180.51 425.106L187.863 447.713C188.776 450.537 191.409 452.449 194.378 452.449L227.716 452.448C230.685 452.448 233.319 450.536 234.237 447.712L241.578 425.105C248.838 422.968 255.838 420.062 262.492 416.435L283.678 427.224C286.329 428.581 289.54 428.067 291.643 425.965L315.214 402.393C317.316 400.291 317.819 397.079 316.473 394.428L305.683 373.254C309.31 366.589 312.215 359.588 314.352 352.328L321.895 349.879L344.236 349.878L344.238 422.793C344.238 426.588 347.305 429.649 351.094 429.649H359.556C375.844 429.649 391.248 425.051 402.915 416.687C415.286 407.826 422.096 395.835 422.096 382.909L422.09 126.501C422.091 113.453 414.622 101.393 401.066 92.556Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Quality Workmanship<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Provide our people with a meaningful experience that helps and guide growth.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85de58d elementor-widget-laptop__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"85de58d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"482\" height=\"482\" viewBox=\"0 0 482 482\" fill=\"none\"><path d=\"M62.3757 137.84H419.626C422.936 137.84 425.626 135.15 425.626 131.84V89.9C425.626 86.59 422.936 83.9 419.626 83.9H380.966V47.95C380.966 44.64 378.276 41.95 374.966 41.95H336.306V6C336.306 2.69 333.616 0 330.306 0H151.696C148.386 0 145.696 2.69 145.696 6V41.95H107.036C103.726 41.95 101.036 44.64 101.036 47.95V83.9H62.3757C59.0657 83.9 56.3757 86.59 56.3757 89.9V131.85C56.3757 135.16 59.0657 137.84 62.3757 137.84ZM235.006 95.9V125.85H157.696V95.9H235.006ZM279.666 53.95V83.9H202.356V53.95H279.666ZM324.316 95.9V125.85H247.006V95.9H324.316ZM413.636 125.84H336.326V95.9H413.636V125.84ZM368.976 83.9H291.666V53.95H368.976V83.9ZM324.316 41.95H247.006V12H324.316V41.95ZM157.696 12H235.006V41.95H157.696V12ZM113.036 53.95H190.346V83.9H113.036V53.95ZM68.3757 95.9H145.686V125.85H68.3757V95.9ZM481.536 332.97L413.186 169.44C412.576 167.97 411.396 166.81 409.926 166.2C408.456 165.6 406.806 165.6 405.336 166.21L333.056 196.42C329.996 197.7 328.556 201.21 329.836 204.27L334.516 215.48C312.736 206.28 289.126 197.89 264.116 190.47C262.846 190.09 261.496 190.15 260.266 190.62C256.676 192 253.126 193.34 249.616 194.66C230.506 201.88 212.446 208.7 194.406 218.83C192.716 219.78 191.586 221.48 191.376 223.41C191.216 224.87 191.046 226.29 190.866 227.72L144.236 218.36L152.146 199.41C152.756 197.94 152.766 196.29 152.156 194.82C151.556 193.35 150.386 192.18 148.916 191.56L76.5857 161.36C73.5257 160.08 70.0157 161.53 68.7357 164.59L0.465694 328.15C-0.814306 331.21 0.635694 334.72 3.69569 336L76.0257 366.2C76.7657 366.51 77.5557 366.66 78.3357 366.66C79.1057 366.66 79.8857 366.51 80.6157 366.21C82.0857 365.61 83.2557 364.44 83.8757 362.97L91.7457 344.11L113.526 359.23L100.306 373.29C96.9957 376.82 95.2457 381.43 95.3957 386.28C95.5457 391.13 97.5657 395.63 101.096 398.94L111.366 408.59C113.726 410.81 116.536 412.25 119.476 412.97C118.296 418.91 120.086 425.31 124.816 429.76L135.086 439.41C138.586 442.7 143.056 444.33 147.516 444.33C150.516 444.33 153.516 443.59 156.206 442.12C157.176 444.31 158.576 446.31 160.366 448L170.636 457.65C174.136 460.94 178.606 462.57 183.066 462.57C185.586 462.57 188.096 462.04 190.436 461C191.386 463.36 192.836 465.57 194.806 467.42L205.076 477.07C208.576 480.36 213.046 481.99 217.506 481.99C222.346 481.99 227.166 480.07 230.736 476.28L249.256 456.58L267.776 472.95C271.226 476 275.516 477.49 279.786 477.49C284.816 477.49 289.816 475.42 293.396 471.37L302.726 460.81C304.526 458.78 305.756 456.45 306.486 454.01C308.366 454.64 310.316 454.97 312.276 454.97C317.306 454.97 322.306 452.9 325.886 448.85L335.216 438.29C336.876 436.41 338.076 434.28 338.826 432.04C341.116 433.02 343.546 433.53 345.986 433.53C351.016 433.53 356.016 431.46 359.596 427.41L368.926 416.85C372.136 413.22 373.736 408.56 373.436 403.71C373.346 402.31 373.086 400.95 372.706 399.64C375.566 398.65 378.226 396.95 380.376 394.53L389.706 383.97C396.336 376.47 395.626 364.98 388.126 358.35L383.506 354.27L390.556 349.52L398.196 367.8C398.806 369.27 399.986 370.43 401.456 371.04C402.186 371.34 402.956 371.49 403.736 371.49C404.526 371.49 405.306 371.34 406.046 371.03L478.326 340.82C481.376 339.54 482.816 336.03 481.536 332.97ZM75.1157 352.81L13.8557 327.23L77.5157 174.75L138.776 200.33L75.1157 352.81ZM109.316 390.21C106.846 387.89 106.726 383.99 109.046 381.52L140.206 348.37C142.496 345.93 146.256 345.76 148.766 347.97L159.326 357.31C160.676 358.5 161.316 359.84 161.396 361.63C161.476 363.42 160.966 364.81 159.746 366.12L128.286 399.59C125.966 402.06 122.066 402.18 119.596 399.86L109.316 390.21ZM143.306 430.68L133.036 421.03C131.846 419.91 131.166 418.39 131.106 416.74C131.056 415.09 131.646 413.53 132.766 412.34L137.016 407.82L137.026 407.81L168.476 374.35C168.476 374.35 168.476 374.34 168.486 374.34L176.086 366.26C177.306 364.97 178.926 364.31 180.566 364.31C182.016 364.31 183.466 364.82 184.646 365.86L195.206 375.19C196.536 376.37 197.196 377.74 197.276 379.51C197.356 381.31 196.846 382.7 195.616 384.01L159.586 422.35C159.586 422.35 159.586 422.35 159.576 422.36L152.006 430.41C149.676 432.88 145.776 433 143.306 430.68ZM178.846 448.92L168.576 439.27C167.386 438.15 166.706 436.63 166.656 434.98C166.606 433.33 167.196 431.77 168.316 430.58L198.846 398.1C201.136 395.66 204.896 395.49 207.406 397.7L217.966 407.03C219.316 408.22 219.956 409.56 220.036 411.35C220.116 413.15 219.606 414.54 218.376 415.85L187.546 448.64C185.226 451.12 181.326 451.24 178.846 448.92ZM221.976 468.07C219.656 470.54 215.756 470.66 213.276 468.34L203.006 458.69C200.536 456.37 200.416 452.47 202.736 449.99L227.106 424.07C227.276 423.89 227.426 423.69 227.586 423.5L227.616 423.52C229.906 421.08 233.666 420.91 236.176 423.12L246.736 432.46C248.066 433.64 248.726 435.01 248.806 436.78C248.886 438.58 248.376 439.97 247.146 441.28L221.976 468.07ZM380.706 376.04L371.376 386.6C369.126 389.14 365.236 389.38 362.696 387.14L292.566 325.15C290.086 322.96 286.296 323.19 284.096 325.67C281.896 328.15 282.136 331.94 284.616 334.14L354.746 396.13C355.756 397.03 356.856 397.77 357.996 398.4C358.336 399.08 358.796 399.71 359.406 400.24C360.626 401.32 361.356 402.82 361.466 404.47C361.566 406.12 361.026 407.7 359.946 408.92L350.616 419.48C348.366 422.02 344.476 422.26 341.936 420.02L258.236 346.05C255.756 343.86 251.966 344.09 249.766 346.57C247.576 349.05 247.806 352.84 250.286 355.04L325.696 421.69C328.236 423.94 328.476 427.83 326.226 430.37L316.896 440.93C314.646 443.47 310.756 443.71 308.216 441.47L235.716 377.39C233.236 375.19 229.436 375.43 227.246 377.91C225.056 380.39 225.286 384.18 227.766 386.38L293.196 444.22C295.736 446.47 295.976 450.36 293.736 452.9L284.406 463.46C282.156 466 278.266 466.24 275.726 464L257.366 447.77C259.816 444.44 261.016 440.51 260.816 436.27C260.586 431.25 258.466 426.84 254.706 423.51L244.146 414.17C240.626 411.05 236.256 409.56 231.926 409.61C231.426 405.1 229.386 401.13 225.926 398.07L215.366 388.74C213.326 386.94 211.006 385.69 208.576 384.95C209.126 383.06 209.376 381.07 209.276 379C209.046 373.98 206.936 369.57 203.166 366.24L192.606 356.91C186.686 351.68 178.406 350.97 171.876 354.58C170.846 352.25 169.316 350.14 167.296 348.36L156.736 339.03C149.336 332.49 138.246 333 131.486 340.2L121.856 350.45L96.4957 332.85L139.556 229.72L189.296 239.71C185.236 266.75 179.026 287.23 170.416 301.96C169.146 304.14 167.596 308.75 171.546 315.05C173.776 318.6 177.126 320.89 181.246 321.67L196.196 324.5C205.546 326.27 214.436 324.1 221.926 318.23C234.266 308.55 239.096 295.69 236.596 279.02L266.566 267L380.186 367.43C382.706 369.6 382.946 373.5 380.706 376.04ZM374.206 346.08L271.716 255.49C270.016 253.99 267.616 253.57 265.506 254.42L227.526 269.65C224.786 270.75 223.256 273.67 223.906 276.54C227.196 291.1 224.296 301.03 214.486 308.72C209.736 312.44 204.326 313.76 198.396 312.64L183.446 309.81C182.626 309.66 182.116 309.3 181.676 308.6C181.326 308.04 181.146 307.65 181.056 307.4C191.686 288.94 198.856 262.87 202.946 227.82C219.346 218.92 236.136 212.58 253.846 205.89C256.756 204.79 259.686 203.68 262.646 202.55C290.926 211.02 317.326 220.74 341.206 231.48L385.816 338.23L374.206 346.08ZM406.946 357.64L343.226 205.18L404.436 179.6L468.156 332.06L406.946 357.64Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Project Management<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Provide our people with a meaningful experience that helps and guide growth.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-807a0f5 elementor-widget-laptop__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"807a0f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M511.996 50.8416C512.027 43.8883 509.26 37.2146 504.315 32.3244L479.672 7.68033C474.805 2.75977 468.17 -0.00588751 461.249 9.41072e-06H461.164C454.284 0.0042215 447.696 2.77156 442.876 7.68033L331.091 119.466H110.933V25.6002C110.933 11.4611 99.4709 9.41072e-06 85.3326 9.41072e-06H68.2661C30.5814 0.0421303 0.0421209 30.5814 0 68.2661V445.872C2.13553 483.269 33.2847 512.385 70.7411 511.996H486.396C500.535 511.996 511.996 500.535 511.996 486.396V145.066C511.996 130.928 500.535 119.466 486.396 119.466H453.97L504.316 69.1195C509.215 64.2975 511.981 57.7157 511.996 50.8416ZM305.321 213.332C303.514 213.578 301.699 212.943 300.44 211.625C299.169 210.363 298.542 208.593 298.733 206.813L301.967 177.8C302.103 177.193 302.274 176.594 302.479 176.008L336.092 209.62C335.537 209.74 335.033 210.013 334.453 210.081L305.321 213.332ZM350.026 199.397L312.684 162.046L405.697 69.0344L443.021 106.35L350.026 199.397ZM417.729 56.9592L430.384 44.3128L467.691 81.6285L455.045 94.2833L417.729 56.9592ZM17.0665 68.2661C17.0952 40.0013 40.0013 17.0943 68.2661 17.0665H85.3326C90.0451 17.0665 93.8663 20.8869 93.8663 25.5994V366.93C93.8663 371.642 90.0459 375.463 85.3326 375.463H68.2661C48.6622 375.457 30.006 383.895 17.0665 398.622V68.2661ZM486.396 136.532C491.109 136.532 494.93 140.353 494.93 145.066V486.396C494.93 491.109 491.11 494.93 486.396 494.93H70.7411C42.5707 495.404 18.9712 473.717 17.0665 445.607V443.73C17.0952 415.465 40.0013 392.559 68.2661 392.53H85.3326C99.4709 392.53 110.932 381.069 110.932 366.931V136.532H314.024L294.645 155.911C289.235 161.242 285.831 168.277 285.011 175.828L281.777 204.9C281.51 207.736 281.78 210.595 282.57 213.331H136.532C131.82 213.331 127.999 217.152 127.999 221.865C127.999 226.577 131.819 230.398 136.532 230.398H162.132V460.796C162.132 465.509 165.953 469.33 170.666 469.33C175.379 469.33 179.2 465.509 179.2 460.796V341.331H273.065V409.597H213.332C208.62 409.597 204.799 413.417 204.799 418.129C204.799 422.842 208.62 426.663 213.332 426.663H383.997C393.423 426.663 401.064 419.022 401.064 409.597V281.598C401.064 276.886 397.243 273.064 392.531 273.064C387.818 273.064 383.997 276.885 383.997 281.598V324.264H179.199V230.399H304.706C305.539 230.4 306.371 230.355 307.198 230.262L336.356 226.943C343.757 226.103 350.664 222.814 355.983 217.599L436.947 136.533L486.396 136.532ZM383.997 341.331V409.597H290.131V341.331H383.997ZM492.284 57.019L479.757 69.5542L442.45 32.2469L454.985 19.7117C456.625 18.0286 458.873 17.075 461.223 17.0665C463.616 17.0724 465.905 18.0378 467.58 19.7463L492.259 44.3735C493.975 46.0634 494.938 48.3733 494.93 50.7817C494.922 53.1321 493.969 55.3805 492.284 57.019Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Certified Professionals<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Provide our people with a meaningful experience that helps and guide growth.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e29c12d e-flex e-con-boxed e-con e-parent\" data-id=\"1e29c12d\" data-element_type=\"container\" data-e-type=\"container\" id=\"about\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-343f1fc9 e-con-full e-flex e-con e-child\" data-id=\"343f1fc9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60653a80 gsap-move-no elementor-widget elementor-widget-rs-image\" data-id=\"60653a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n\n\n        <div class=\"rs-image     scroll_reveal reveal_left\" >\n\n\n                                                        <img decoding=\"async\" class=\"rs-multi-image  reverse- blend_unset\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/hm_00002.jpg\" alt=\"hm_00002\"\/>\n                                <\/div>   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d624547 e-con-full e-flex e-con e-child\" data-id=\"5d624547\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3889b5 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"2c3889b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>About Brickz Construction\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"0.8\" data-delay=\"0.02\">Experts Modern Construction Service &amp; Solutions<\/h2>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43c288b elementor-widget__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"43c288b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Our data analysis tools and techniques help you turn complex data into clear, strategic insights that improve performance and guide growth.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb91a50 e-con-full e-flex e-con e-child\" data-id=\"eb91a50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c07a9d8 e-con-full e-flex e-con e-child\" data-id=\"c07a9d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e629ae4 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-tab-advanced\" data-id=\"e629ae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-tab-advanced.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <div class=\"rstab-main horizontal tab_e629ae4 auto_switch_no full_tab_item  style1\">\n            <nav class=\"tab-menu-wrapper\">\n                <div class=\"nav nav-tabs none\" id=\"nav-tab-e629ae4\" role=\"tablist\">\n                                            <button class=\"nav-link active count_number_no\" id=\"nav-home-1-3286043\" data-bs-toggle=\"tab\" data-bs-target=\"#tab1-3286043\" type=\"button\" role=\"tab\" aria-controls=\"nav-home-1-3286043\" aria-selected=\"true\">\n                                                            <span class=\"nav-btn-icon\">\n                                    <i aria-hidden=\"true\" class=\"ri-arrow-right-line\"><\/i>                                <\/span>\n                                                        <span class=\"text-part\">\n                                Mision                            <\/span>\n                        <\/button>\n\n                                            <button class=\"nav-link  count_number_no\" id=\"nav-home-2-3286043\" data-bs-toggle=\"tab\" data-bs-target=\"#tab2-3286043\" type=\"button\" role=\"tab\" aria-controls=\"nav-home-2-3286043\" aria-selected=\"true\">\n                                                            <span class=\"nav-btn-icon\">\n                                    <i aria-hidden=\"true\" class=\"ri-arrow-right-line\"><\/i>                                <\/span>\n                                                        <span class=\"text-part\">\n                                Vision                            <\/span>\n                        <\/button>\n\n                                            <button class=\"nav-link  count_number_no\" id=\"nav-home-3-3286043\" data-bs-toggle=\"tab\" data-bs-target=\"#tab3-3286043\" type=\"button\" role=\"tab\" aria-controls=\"nav-home-3-3286043\" aria-selected=\"true\">\n                                                            <span class=\"nav-btn-icon\">\n                                    <i aria-hidden=\"true\" class=\"ri-arrow-right-line\"><\/i>                                <\/span>\n                                                        <span class=\"text-part\">\n                                Core Value                            <\/span>\n                        <\/button>\n\n                                    <\/div>\n            <\/nav>\n            <div class=\"tab-content\" id=\"nav-tabContent-e629ae4\">\n                                    <div class=\"tab-pane fade show active\" id=\"tab1-3286043\" role=\"tabpanel\" aria-labelledby=\"nav-home-1-3286043\">\n                                                                                                                <div class=\"content--teb-area full-sec\">\n                                    \n                                    <div class=\"content--left-area\">\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                        \n                                        <div class=\"desc_btn_wrapper\">\n                                                                                            <p>Our vision is to be the most trusted\u00a0 impactful business consulting firm globally, known for trans forming companies.<\/p>                                                                                    <\/div>\n                                        \n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Regulatory Investigations<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Anit- Competitive Conduct\n<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                            \n                                            <\/div>\n\n                                    <div class=\"tab-pane fade \" id=\"tab2-3286043\" role=\"tabpanel\" aria-labelledby=\"nav-home-2-3286043\">\n                                                                                                                <div class=\"content--teb-area full-sec\">\n                                    \n                                    <div class=\"content--left-area\">\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                        \n                                        <div class=\"desc_btn_wrapper\">\n                                                                                            <p>Our vision is to be the most trusted\u00a0 impactful business consulting firm globally, known for trans forming companies.<\/p>                                                                                    <\/div>\n                                        \n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Regulatory Investigations<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Anit- Competitive Conduct\n<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                            \n                                            <\/div>\n\n                                    <div class=\"tab-pane fade \" id=\"tab3-3286043\" role=\"tabpanel\" aria-labelledby=\"nav-home-3-3286043\">\n                                                                                                                <div class=\"content--teb-area full-sec\">\n                                    \n                                    <div class=\"content--left-area\">\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                        \n                                        <div class=\"desc_btn_wrapper\">\n                                                                                            <p>Our vision is to be the most trusted\u00a0 impactful business consulting firm globally, known for trans forming companies.<\/p>                                                                                    <\/div>\n                                        \n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Regulatory Investigations<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Anit- Competitive Conduct\n<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                            \n                                            <\/div>\n\n                            <\/div>\n        <\/div>\n        \n        <div class=\"accordion tab-menu-wrapper accordion-menu-wrapper rs_horizontal\" id=\"accordionExample-e629ae4\">\n\n                            <div class=\"accordion-item nav-tabs\">\n                    \n                    <div class=\"accordion-headerd\" id=\"heading_1-3286043\">\n                        <button class=\"nav-link accordion-button collapsed show\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_1-3286043\" aria-expanded=\"true\" aria-controls=\"collapse_1-3286043\">\n                            <span class=\"nav-btn-icon\">\n                                <i aria-hidden=\"true\" class=\"ri-arrow-right-line\"><\/i>                            <\/span>\n\n                            <span class=\"text-part\">\n                                Mision                            <\/span>\n                        <\/button>\n                    <\/div>\n\n                    <div id=\"collapse_1-3286043\" class=\"accordion-collapse collapse show\" aria-labelledby=\"heading_1-3286043\" data-bs-parent=\"#accordionExample-e629ae4\">\n                        <div class=\"tab-pane\">\n                                                                                                                            <div class=\"content--teb-area full-sec\">\n                                    \n                                    <div class=\"content--left-area\">\n\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                <div class=\"desc_btn_wrapper\">\n                                                                                            <p>Our vision is to be the most trusted\u00a0 impactful business consulting firm globally, known for trans forming companies.<\/p>                                                                                    <\/div>\n\n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Regulatory Investigations<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Anit- Competitive Conduct\n<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"accordion-item nav-tabs\">\n                    \n                    <div class=\"accordion-headerd\" id=\"heading_2-3286043\">\n                        <button class=\"nav-link accordion-button collapsed \" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_2-3286043\" aria-expanded=\"true\" aria-controls=\"collapse_2-3286043\">\n                            <span class=\"nav-btn-icon\">\n                                <i aria-hidden=\"true\" class=\"ri-arrow-right-line\"><\/i>                            <\/span>\n\n                            <span class=\"text-part\">\n                                Vision                            <\/span>\n                        <\/button>\n                    <\/div>\n\n                    <div id=\"collapse_2-3286043\" class=\"accordion-collapse collapse \" aria-labelledby=\"heading_2-3286043\" data-bs-parent=\"#accordionExample-e629ae4\">\n                        <div class=\"tab-pane\">\n                                                                                                                            <div class=\"content--teb-area full-sec\">\n                                    \n                                    <div class=\"content--left-area\">\n\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                <div class=\"desc_btn_wrapper\">\n                                                                                            <p>Our vision is to be the most trusted\u00a0 impactful business consulting firm globally, known for trans forming companies.<\/p>                                                                                    <\/div>\n\n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Regulatory Investigations<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Anit- Competitive Conduct\n<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"accordion-item nav-tabs\">\n                    \n                    <div class=\"accordion-headerd\" id=\"heading_3-3286043\">\n                        <button class=\"nav-link accordion-button collapsed \" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_3-3286043\" aria-expanded=\"true\" aria-controls=\"collapse_3-3286043\">\n                            <span class=\"nav-btn-icon\">\n                                <i aria-hidden=\"true\" class=\"ri-arrow-right-line\"><\/i>                            <\/span>\n\n                            <span class=\"text-part\">\n                                Core Value                            <\/span>\n                        <\/button>\n                    <\/div>\n\n                    <div id=\"collapse_3-3286043\" class=\"accordion-collapse collapse \" aria-labelledby=\"heading_3-3286043\" data-bs-parent=\"#accordionExample-e629ae4\">\n                        <div class=\"tab-pane\">\n                                                                                                                            <div class=\"content--teb-area full-sec\">\n                                    \n                                    <div class=\"content--left-area\">\n\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                <div class=\"desc_btn_wrapper\">\n                                                                                            <p>Our vision is to be the most trusted\u00a0 impactful business consulting firm globally, known for trans forming companies.<\/p>                                                                                    <\/div>\n\n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Regulatory Investigations<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Anit- Competitive Conduct\n<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfd5ac1 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-button\" data-id=\"cfd5ac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rs-button style1 unique-39000\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t\t\t<a class=\"rs-btn anim-dir-angle \" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/about-us\/\" >\t\r\n\t\t\t\t\t<span class=\"rs-btn-active\"><span>Discover More<\/span> <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<em>\r\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>\t\t\t\t\t\t<\/em>\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50fc971 e-con-full e-flex e-con e-child\" data-id=\"50fc971\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31cbcdf gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-image\" data-id=\"31cbcdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n\n\n        <div class=\"rs-image      \" >\n\n\n                                                        <img decoding=\"async\" class=\"rs-multi-image  reverse- blend_unset\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/about_tab00001.jpg\" alt=\"about_tab00001\"\/>\n                                <\/div>   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf07e6d gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"cf07e6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Our data analysis tools and techniques help you turn complex data.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da0c594 elementor-widget__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-counter\" data-id=\"da0c594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"counter-top-area\">\r\n\t\t\t\t<div class=\"rs-counter-list\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"id-da0c594 rs-counter odometer\">25<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"title\">Years Of Experience<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\tvar delay = 0;\r\n\t\t\t\tsetTimeout(function() {\r\n\t\t\t\t\t$(\".odometer.id-da0c594\").each(function () {\r\n\t\t\t\t\t\tvar countNumber = 25;\r\n\t\t\t\t\t\tcountNumber = countNumber.toString();\r\n\t\t\t\t\t\tvar digits = countNumber.length;\r\n\t\t\t\t\t\tvar zeros = \"0\".repeat(digits);\r\n\t\t\t\t\t\t$(this).html(zeros);\r\n\t\t\t\t\t});\r\n\t\t\t\t\r\n\t\t\t\t\t$('.odometer.id-da0c594').appear(function () {\r\n\t\t\t\t\t\t$(this).each(function () {\r\n\t\t\t\t\t\t\tvar countNumber = 25;\r\n\t\t\t\t\t\t\t$(this).html(countNumber);\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t});\r\n\t\t\t\t}, delay);\r\n\t\t\t});\r\n\r\n\t\t<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1052de9 e-con-full e-flex e-con e-parent\" data-id=\"1052de9\" data-element_type=\"container\" data-e-type=\"container\" id=\"services\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97e97c0 elementor-widget__width-initial elementor-widget-mobile__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"97e97c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1 center  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Our Providing Services<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"1\" data-delay=\"0.06\">Innovative design reliable construction Services for every project<\/h2>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a3f7ea4 e-flex e-con-boxed e-con e-child\" data-id=\"a3f7ea4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac444d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet_extra__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"5ac444d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner link clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\"><path d=\"M22.537 10.2831H14.537C13.71 10.2831 13.037 10.9561 13.037 11.7831V16.2831H1.537C0.71 16.2831 0.037 16.9561 0.037 17.7831V19.2831C0.037 21.4891 1.831 23.2831 4.037 23.2831H20.037C22.243 23.2831 24.037 21.4891 24.037 19.2831V11.7831C24.037 10.9561 23.364 10.2831 22.537 10.2831ZM14.037 11.7831C14.037 11.5071 14.262 11.2831 14.537 11.2831H22.537C22.812 11.2831 23.037 11.5071 23.037 11.7831V16.2831H14.037V11.7831ZM16.037 17.2831V22.2831H8.037V17.2831H16.037ZM1.037 19.2831V17.7831C1.037 17.5071 1.261 17.2831 1.537 17.2831H7.037V22.2831H4.037C2.383 22.2831 1.037 20.9371 1.037 19.2831ZM23.037 19.2831C23.037 20.9371 21.691 22.2831 20.037 22.2831H17.037V17.2831H23.037V19.2831ZM1.11 7.07207L7.147 10.3431C7.502 10.4961 7.877 10.5721 8.251 10.5721C8.787 10.5721 9.319 10.4171 9.782 10.1121C10.568 9.59507 11.037 8.72507 11.037 7.78407V5.78407H13.1C13.323 6.64607 14.107 7.28407 15.037 7.28407H20.037C21.14 7.28407 22.037 6.38707 22.037 5.28407C22.037 4.18107 21.14 3.28407 20.037 3.28407H15.037C14.107 3.28407 13.323 3.92207 13.1 4.78407H11.037V2.78407C11.037 1.84307 10.568 0.973068 9.782 0.456068C8.996 -0.0609317 8.012 -0.147932 7.106 0.244068L1.117 3.49107C0.428 3.83907 0 4.52607 0 5.28307C0 6.04007 0.425 6.72207 1.11 7.07207ZM15.037 4.28307H20.037C20.589 4.28307 21.037 4.73207 21.037 5.28307C21.037 5.83407 20.589 6.28307 20.037 6.28307H15.037C14.485 6.28307 14.037 5.83407 14.037 5.28307C14.037 4.73207 14.485 4.28307 15.037 4.28307ZM1.581 4.37607L7.542 1.14107C7.774 1.04107 8.015 0.992068 8.254 0.992068C8.595 0.992068 8.931 1.09307 9.232 1.29007C9.743 1.62707 10.037 2.17107 10.037 2.78307V7.78307C10.037 8.39507 9.744 8.93907 9.232 9.27607C8.72 9.61207 8.104 9.66507 7.583 9.44407L1.581 6.19007C1.581 6.19007 1.573 6.18607 1.569 6.18307C1.213 6.00307 1 5.66607 1 5.28307C1 4.90007 1.212 4.56307 1.581 4.37607Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\">\r\n\r\n                        <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/general-contracting\/\" >\r\n                            General Contracting                        <\/a>\r\n                    <\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Orci varius natoque penatibus et magnis dis parturient montes, nascetur ridiculus must lectus congue create meaningful.             <\/div>\r\n                    <ul class=\"service_grid_list \">\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Tailored Business Strategies                    <\/li>\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Industry-Specific Expertise                    <\/li>\r\n                            <\/ul>\r\n                    <div class=\"btn-part\">\r\n                                <a class=\"services-btn icon-right anim-dir-angle\" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/general-contracting\/\" >\r\n                    <span class=\"rs-btn-text\"><span>Explore More<\/span><\/span>                        <em>\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                        <\/em>\r\n                                    <\/a>\r\n            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a339f8 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet_extra__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"3a339f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner link clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M213.333 298.667V0H53.3333C23.936 0 0 23.9147 0 53.3333V458.667C0 488.085 23.936 512 53.3333 512H458.667C488.085 512 512 488.085 512 458.667V298.667H213.333ZM490.667 458.667C490.667 476.309 476.309 490.667 458.667 490.667H53.3333C35.6907 490.667 21.3333 476.309 21.3333 458.667V53.3333C21.3333 35.6907 35.6907 21.3333 53.3333 21.3333H192V85.3333H106.667V106.667H192V192H106.667V213.333H192V298.667H106.667V320H192V405.333H213.333V320H298.667V405.333H320V320H405.333V405.333H426.667V320H490.667V458.667Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\">\r\n\r\n                        <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/planning-design-build\/\" >\r\n                            Planning, Design &amp; Build                        <\/a>\r\n                    <\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Orci varius natoque penatibus et magnis dis parturient montes, nascetur ridiculus must lectus congue create meaningful.             <\/div>\r\n                    <ul class=\"service_grid_list \">\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Tailored Business Strategies                    <\/li>\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Industry-Specific Expertise                    <\/li>\r\n                            <\/ul>\r\n                    <div class=\"btn-part\">\r\n                                <a class=\"services-btn icon-right anim-dir-angle\" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/planning-design-build\/\" >\r\n                    <span class=\"rs-btn-text\"><span>Explore More<\/span><\/span>                        <em>\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                        <\/em>\r\n                                    <\/a>\r\n            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec851d6 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet_extra__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"ec851d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner link clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M17.1247 12.8851C16.0767 11.8411 14.4427 11.7371 13.2697 12.5631L7.99967 7.29314V4.00014C7.99967 3.16614 7.55067 2.38914 6.82767 1.97214L3.84667 0.252136C3.11067 -0.173864 2.17767 -0.0498638 1.57667 0.551136L0.550665 1.57714C-0.0503345 2.17814 -0.173335 3.11014 0.250665 3.84714L1.96967 6.82814C2.38667 7.55114 3.16367 8.00014 3.99867 8.00014H7.29167L12.5587 13.2671C12.1947 13.7731 11.9917 14.3731 11.9917 15.0081C11.9917 15.8101 12.3047 16.5631 12.8737 17.1291L18.8947 23.1221C19.4587 23.6841 20.2277 24.0001 21.0217 24.0001C21.9997 24.0001 22.8127 23.5521 23.3537 22.8941C24.3167 21.7191 24.1817 19.9111 23.0447 18.7771L17.1247 12.8851ZM2.83567 6.32814L1.11667 3.34714C0.917665 3.00214 0.975665 2.56614 1.25667 2.28514L2.28267 1.25914C2.56367 0.978136 3.00267 0.921136 3.34567 1.11814L6.32567 2.83814C6.74067 3.07714 6.99767 3.52414 6.99767 4.00114V7.00114H3.99767C3.51967 7.00114 3.07467 6.74314 2.83467 6.32914L2.83567 6.32814ZM22.5797 22.2591C22.2127 22.7061 21.6947 22.9691 21.1217 22.9971C20.5517 23.0231 20.0007 22.8121 19.5997 22.4131L13.5787 16.4201C13.2007 16.0431 12.9917 15.5411 12.9917 15.0081C12.9917 14.4741 13.1997 13.9721 13.5787 13.5931C13.9707 13.2031 14.4847 13.0081 14.9977 13.0081C15.5107 13.0081 16.0257 13.2031 16.4177 13.5931L22.3367 19.4851C23.1127 20.2581 23.2187 21.4771 22.5777 22.2581L22.5797 22.2591ZM9.27767 5.39614C10.0627 2.69414 12.3527 0.625136 15.1107 0.124136C16.2057 -0.0738637 17.2977 -0.0348637 18.3547 0.240136C18.8527 0.370136 19.2307 0.743136 19.3667 1.23914C19.5007 1.73014 19.3667 2.24014 19.0087 2.60114L15.4657 6.17414C14.8197 6.82014 14.8197 7.87014 15.4647 8.51514C16.1097 9.16014 17.1587 9.15914 17.8037 8.51514L21.3607 4.92814C21.7177 4.56614 22.2237 4.42914 22.7167 4.55914C23.2147 4.69114 23.5917 5.06814 23.7267 5.56814C24.0107 6.62714 24.0577 7.72014 23.8657 8.82014C23.5297 10.7511 22.3977 12.5141 20.7587 13.6581C20.6717 13.7191 20.5717 13.7481 20.4727 13.7481C20.3147 13.7481 20.1597 13.6741 20.0617 13.5341C19.9037 13.3071 19.9587 12.9961 20.1857 12.8381C21.6077 11.8461 22.5897 10.3191 22.8797 8.64914C23.0467 7.69414 23.0057 6.74514 22.7597 5.82914C22.7017 5.61314 22.5307 5.54614 22.4597 5.52714C22.3907 5.50614 22.2167 5.48314 22.0697 5.63214L18.5107 9.22114C17.4757 10.2581 15.7927 10.2591 14.7567 9.22314C14.2557 8.72214 13.9797 8.05614 13.9797 7.34614C13.9797 6.63614 14.2557 5.97114 14.7567 5.47014L18.2987 1.89814C18.4477 1.74714 18.4207 1.57214 18.4017 1.50314C18.3827 1.43314 18.3147 1.26314 18.1027 1.20714C17.1857 0.970136 16.2407 0.936136 15.2897 1.10814C12.9017 1.54214 10.9187 3.33414 10.2387 5.67414C10.1617 5.93914 9.88767 6.09214 9.61867 6.01514C9.35367 5.93814 9.20167 5.66114 9.27867 5.39514L9.27767 5.39614ZM10.6067 16.9491C10.8017 17.1451 10.8017 17.4621 10.6067 17.6571L5.12467 23.1231C4.56067 23.6851 3.79167 24.0011 2.99767 24.0011C2.00067 24.0011 1.20667 23.5541 0.666665 22.8961C-0.297334 21.7211 -0.162334 19.9131 0.974666 18.7791L7.95167 11.8221C8.14767 11.6291 8.46367 11.6281 8.65867 11.8221C8.85367 12.0181 8.85367 12.3351 8.65867 12.5301L1.68167 19.4871C0.905666 20.2601 0.799666 21.4791 1.44067 22.2601C1.80767 22.7071 2.32567 22.9691 2.89867 22.9971C3.47767 23.0371 4.01967 22.8121 4.41967 22.4131L9.90167 16.9471C10.0967 16.7541 10.4137 16.7531 10.6087 16.9471L10.6067 16.9491Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\">\r\n\r\n                        <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/renovation-remodeling\/\" >\r\n                            Renovation &amp; Remodeling                        <\/a>\r\n                    <\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Orci varius natoque penatibus et magnis dis parturient montes, nascetur ridiculus must lectus congue create meaningful.             <\/div>\r\n                    <ul class=\"service_grid_list \">\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Tailored Business Strategies                    <\/li>\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Industry-Specific Expertise                    <\/li>\r\n                            <\/ul>\r\n                    <div class=\"btn-part\">\r\n                                <a class=\"services-btn icon-right anim-dir-angle\" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/renovation-remodeling\/\" >\r\n                    <span class=\"rs-btn-text\"><span>Explore More<\/span><\/span>                        <em>\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                        <\/em>\r\n                                    <\/a>\r\n            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82c217f elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet_extra__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"82c217f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner link clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M1.97186 7H2.98286L2.98486 8C2.98486 11.309 5.67586 14 8.98486 14C12.2939 14 14.9849 11.309 14.9849 7.999L14.9829 7H15.9709C16.2469 7 16.4709 6.776 16.4709 6.5C16.4709 6.224 16.2469 6 15.9709 6H14.9809V5.49C14.9749 2.463 12.5069 0 9.47986 0H8.47986C7.00886 0 5.62686 0.573 4.58786 1.614C3.54786 2.655 2.97686 4.038 2.97986 5.51V6H1.97186C1.69586 6 1.47186 6.224 1.47186 6.5C1.47186 6.776 1.69586 7 1.97186 7ZM13.9849 8C13.9849 10.757 11.7419 13 8.98486 13C6.22786 13 3.98486 10.757 3.98486 7.999L3.98286 7H13.9829L13.9849 8ZM3.97986 5.508C3.97786 4.305 4.44486 3.172 5.29586 2.32C5.77586 1.839 6.35086 1.496 6.97186 1.275V4C6.97186 4.276 7.19586 4.5 7.47186 4.5C7.74786 4.5 7.97186 4.276 7.97186 4V1.05C8.14086 1.031 8.30786 1 8.47986 1H9.47986C9.64786 1 9.80786 1.032 9.97186 1.05V4C9.97186 4.276 10.1959 4.5 10.4719 4.5C10.7479 4.5 10.9719 4.276 10.9719 4V1.274C12.7159 1.893 13.9769 3.541 13.9799 5.492V6H3.98086L3.97986 5.508ZM12.2929 16.714C11.2519 16.24 10.1389 16 8.98486 16C4.75186 16 1.24386 19.307 0.998857 23.529C0.983857 23.795 0.762857 24 0.499857 24C0.489857 24 0.479857 24 0.470857 24C0.194857 23.984 -0.0151432 23.748 0.000856791 23.472C0.275857 18.722 4.22286 15.001 8.98486 15.001C10.2829 15.001 11.5349 15.272 12.7069 15.805C12.9579 15.919 13.0689 16.216 12.9549 16.467C12.8409 16.719 12.5449 16.827 12.2929 16.714ZM22.4999 14H18.4999C17.6729 14 16.9999 14.673 16.9999 15.5V17H15.4999C14.6729 17 13.9999 17.673 13.9999 18.5V20H12.4999C11.6729 20 10.9999 20.673 10.9999 21.5V22.5C10.9999 23.327 11.6729 24 12.4999 24H22.4999C23.3269 24 23.9999 23.327 23.9999 22.5V15.5C23.9999 14.673 23.3269 14 22.4999 14ZM22.9999 18V20H20.9999V18H22.9999ZM17.9999 15.5C17.9999 15.225 18.2249 15 18.4999 15H22.4999C22.7749 15 22.9999 15.225 22.9999 15.5V17H17.9999V15.5ZM14.9999 18.5C14.9999 18.225 15.2249 18 15.4999 18H19.9999V20H14.9999V18.5ZM11.9999 22.5V21.5C11.9999 21.225 12.2239 21 12.4999 21H16.9999V23H12.4999C12.2239 23 11.9999 22.775 11.9999 22.5ZM22.9999 22.5C22.9999 22.775 22.7749 23 22.4999 23H17.9999V21H22.9999V22.5Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\">\r\n\r\n                        <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/project-management\/\" >\r\n                            Project Management                        <\/a>\r\n                    <\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Orci varius natoque penatibus et magnis dis parturient montes, nascetur ridiculus must lectus congue create meaningful.             <\/div>\r\n                    <ul class=\"service_grid_list \">\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Tailored Business Strategies                    <\/li>\r\n                                    <li>\r\n                        \t\t\t\t\t\t\t<div class=\"list-icon-wrap\">\r\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n                                                Industry-Specific Expertise                    <\/li>\r\n                            <\/ul>\r\n                    <div class=\"btn-part\">\r\n                                <a class=\"services-btn icon-right anim-dir-angle\" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/service\/project-management\/\" >\r\n                    <span class=\"rs-btn-text\"><span>Explore More<\/span><\/span>                        <em>\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                        <\/em>\r\n                                    <\/a>\r\n            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5409b3 e-flex e-con-boxed e-con e-child\" data-id=\"f5409b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c10d976 elementor-widget__width-auto gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"c10d976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle2\">\r\n\r\n\t\t\t\t\t\t\t            <div class=\"address-icon icon_1 elementor-repeater-item-a863b1d\">\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M0.50204 0.439454C0.811629 0.16438 1.28548 0.192407 1.56063 0.501954L5.56063 5.00195C5.81308 5.28608 5.81308 5.71392 5.56063 5.99805L1.56063 10.498C1.28548 10.8076 0.811629 10.8356 0.50204 10.5605C0.192493 10.2854 0.164466 9.81154 0.43954 9.50195L3.99618 5.5L0.43954 1.49805C0.164466 1.18846 0.192493 0.714606 0.50204 0.439454Z\" fill=\"#AB052D\"><\/path><\/svg>\t\t            <\/div>\r\n\t\t            \r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"des\">\r\n\t\t\t\t\t\t\t\t\t\t\tFacing obstacles in business growth?\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2b0b12 elementor-widget__width-auto gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"a2b0b12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle2\">\r\n\r\n\t\t\t\t\t\r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/services\/\" >\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"des\">\r\n\t\t\t\t\t\t\t\t\t\t\t\tView All Services\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7769a70d e-flex e-con-boxed e-con e-parent\" data-id=\"7769a70d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/demo.rstheme.com\\\/wordpress\\\/brickz\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/video.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f1891ca e-flex e-con-boxed e-con e-parent\" data-id=\"5f1891ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-333e26ba e-con-full e-flex e-con e-child\" data-id=\"333e26ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7261c5f0 e-con-full e-flex e-con e-child\" data-id=\"7261c5f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39648ebd elementor-widget-mobile__width-initial gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"39648ebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t<h4 class=\"title  \">Have a Project in Mind? Let's Talk\n<\/h4>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eafaed0 elementor-absolute elementor-hidden-mobile gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-image\" data-id=\"4eafaed0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"rs-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n\n\n        <div class=\"rs-image      \" >\n\n\n                                                        <img decoding=\"async\" class=\"rs-multi-image  reverse- blend_unset\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/envlope.svg\" alt=\"envlope.svg\"\/>\n                                <\/div>   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78123fdd gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-cf7\" data-id=\"78123fdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f477-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"477\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/7568#wpcf7-f477-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"477\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f477-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your email address..\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<div class=\"form-btn-area anim-dir-angle\">\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Let\u2019s Join\" \/>\n<em> \n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\"><path d=\"M9.67029 3.6295L1.78054 11.5192L0.484375 10.2231L8.37321 2.33333H1.42029V0.5H11.5036V10.5833H9.67029V3.6295Z\" fill=\"#2B3944\"><\/path><\/svg> \n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\"><path d=\"M9.67029 3.6295L1.78054 11.5192L0.484375 10.2231L8.37321 2.33333H1.42029V0.5H11.5036V10.5833H9.67029V3.6295Z\" fill=\"#2B3944\"><\/path><\/svg> <\/em>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5acfe2ba e-con-full e-flex e-con e-child\" data-id=\"5acfe2ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48549935 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"48549935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                                                <div class=\"image_style media-cmn\">\r\n                            <img decoding=\"async\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/cta-author.png\" alt=\"cta-author.png\" \/>\r\n                        <\/div>\r\n                                                <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Contact Our Experts<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                We provide the best services to ensuring your outstanding growth Lorem ipsum dolor sit.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d486fde e-flex e-con-boxed e-con e-parent\" data-id=\"d486fde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8f474bc e-con-full e-flex e-con e-child\" data-id=\"8f474bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5d81c6e5 e-con-full e-flex e-con e-child\" data-id=\"5d81c6e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a683c73 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"3a683c73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Work Process\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"1\" data-delay=\"0.06\">Our Work Process<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>We support businesses in tech, retail, real estate, finance, healthcare, and more providing custom strategies that work in your world.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d710a7d e-con-full e-flex e-con e-child\" data-id=\"d710a7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bca80e gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-image\" data-id=\"5bca80e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n\n\n        <div class=\"rs-image      \" >\n\n\n                                                        <img decoding=\"async\" class=\"rs-multi-image  reverse- blend_unset\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/process.jpg\" alt=\"process\"\/>\n                                <\/div>   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa448e2 e-con-full e-flex e-con e-child\" data-id=\"aa448e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79f4c53 elementor-widget__width-auto gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"79f4c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle2\">\r\n\r\n\t\t\t\t\t\t\t            <div class=\"address-icon icon_1 elementor-repeater-item-a863b1d\">\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M0.50204 0.439454C0.811629 0.16438 1.28548 0.192407 1.56063 0.501954L5.56063 5.00195C5.81308 5.28608 5.81308 5.71392 5.56063 5.99805L1.56063 10.498C1.28548 10.8076 0.811629 10.8356 0.50204 10.5605C0.192493 10.2854 0.164466 9.81154 0.43954 9.50195L3.99618 5.5L0.43954 1.49805C0.164466 1.18846 0.192493 0.714606 0.50204 0.439454Z\" fill=\"#AB052D\"><\/path><\/svg>\t\t            <\/div>\r\n\t\t            \r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"des\">\r\n\t\t\t\t\t\t\t\t\t\t\tHave a Project in Mind?\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d9c76 elementor-widget__width-auto elementor-widget-mobile__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"c2d9c76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle2\">\r\n\r\n\t\t\t\t\t\r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/services\/\" >\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"des\">\r\n\t\t\t\t\t\t\t\t\t\t\t\tView All Services\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc25ce5 e-con-full e-flex e-con e-child\" data-id=\"cc25ce5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-430553e e-con-full e-flex e-con e-child\" data-id=\"430553e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c208cf3 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"c208cf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n            <div class=\"numbering\">\r\n            <span>01<\/span>\r\n        <\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 40 40\"><path d=\"M32.1852 24.9574C28.1952 24.9574 24.9607 28.1919 24.9607 32.1819C24.9607 36.1719 28.1952 39.4063 32.1852 39.4063C36.1752 39.4063 39.4096 36.1719 39.4096 32.1819C39.4048 28.1938 36.1733 24.9623 32.1852 24.9574ZM32.1852 38.0928C28.9206 38.0928 26.2743 35.4465 26.2743 32.1819C26.2743 28.9173 28.9206 26.271 32.1852 26.271C35.4498 26.271 38.0961 28.9173 38.0961 32.1819C38.0926 35.4449 35.4482 38.0893 32.1852 38.0928ZM13.7957 24.9574H7.88475V18.0049L9.82238 19.9422C10.0798 20.1914 10.4897 20.1876 10.743 19.9342C10.8648 19.8125 10.9339 19.6478 10.9354 19.4757C10.9369 19.3035 10.8707 19.1376 10.7511 19.0138L7.69232 15.955C7.56912 15.832 7.40211 15.7629 7.22798 15.7629C7.05386 15.7629 6.88685 15.832 6.76365 15.955L3.70524 19.0137C3.58564 19.1376 3.51945 19.3034 3.52094 19.4755C3.52243 19.6477 3.59147 19.8123 3.71321 19.934C3.83494 20.0559 3.99968 20.125 4.17191 20.1265C4.34414 20.128 4.51007 20.0618 4.63391 19.9421L6.57122 18.0049V24.9573H0.660299C0.486113 24.9573 0.319061 25.0265 0.195893 25.1497C0.0727252 25.2729 0.00353013 25.4399 0.00353013 25.6141V38.7495C0.00353013 38.9237 0.0727252 39.0907 0.195893 39.2139C0.319061 39.3371 0.486113 39.4062 0.660299 39.4062H13.7957C13.9699 39.4062 14.1369 39.3371 14.2601 39.2139C14.3832 39.0907 14.4524 38.9237 14.4524 38.7495V25.6141C14.4524 25.4399 14.3832 25.2729 14.2601 25.1497C14.1369 25.0265 13.9699 24.9574 13.7957 24.9574ZM13.1389 38.0928H1.31707V26.271H13.1389V38.0928ZM19.7396 3.7016C19.6585 3.61782 19.5567 3.55711 19.4444 3.5257C19.3321 3.49428 19.2135 3.49329 19.1008 3.52283C18.988 3.55237 18.8851 3.61137 18.8027 3.69378C18.7202 3.77619 18.6612 3.87905 18.6316 3.99181C18.6021 4.10457 18.6032 4.22317 18.6347 4.33539C18.6662 4.44762 18.727 4.54943 18.8109 4.63035L20.7481 6.5679H14.4191C14.0679 2.72194 10.7539 -0.168084 6.89582 0.00760134C3.03772 0.183287 0 3.36262 0 7.22467C0 11.0867 3.03756 14.266 6.89574 14.4417C10.7539 14.6174 14.0679 11.7275 14.419 7.88144H20.7481L18.8109 9.81907C18.727 9.89998 18.6662 10.0018 18.6347 10.114C18.6032 10.2262 18.6021 10.3448 18.6316 10.4575C18.6612 10.5703 18.7203 10.6732 18.8027 10.7556C18.8852 10.8381 18.988 10.8971 19.1008 10.9267C19.2136 10.9562 19.3322 10.9551 19.4445 10.9236C19.5567 10.8921 19.6586 10.8313 19.7396 10.7474L22.7981 7.689C22.8591 7.62804 22.9075 7.55565 22.9405 7.47598C22.9735 7.3963 22.9905 7.31091 22.9905 7.22467C22.9905 7.13843 22.9735 7.05303 22.9405 6.97336C22.9075 6.89369 22.8591 6.8213 22.7981 6.76033L19.7396 3.7016ZM7.22798 13.1356C3.96335 13.1356 1.31707 10.4893 1.31707 7.22467C1.31707 3.96012 3.96335 1.31375 7.22798 1.31375C10.4926 1.31375 13.1389 3.96012 13.1389 7.22467C13.1354 10.4877 10.491 13.1321 7.22798 13.1356ZM39.7591 6.71641L32.6002 0.87117C32.4829 0.775205 32.3361 0.722773 32.1846 0.722773C32.0331 0.722773 31.8862 0.775205 31.769 0.87117L24.6102 6.71641C24.5348 6.77797 24.4741 6.8555 24.4324 6.94341C24.3907 7.03131 24.3691 7.12738 24.3691 7.22467C24.3691 7.32197 24.3907 7.41806 24.4324 7.50597C24.4741 7.59389 24.5348 7.67144 24.6102 7.73301L31.5284 13.3812V21.4017L29.5911 19.464C29.4674 19.3439 29.3013 19.2772 29.1287 19.2785C28.9562 19.2797 28.7911 19.3488 28.6691 19.4708C28.5472 19.5928 28.4781 19.7579 28.4768 19.9304C28.4756 20.103 28.5422 20.269 28.6624 20.3928L31.7209 23.4515C31.8441 23.5745 32.0111 23.6436 32.1852 23.6436C32.3593 23.6436 32.5263 23.5745 32.6495 23.4515L35.7083 20.3928C35.8285 20.269 35.8951 20.103 35.8939 19.9304C35.8926 19.7579 35.8236 19.5928 35.7016 19.4708C35.5796 19.3488 35.4145 19.2797 35.242 19.2785C35.0695 19.2772 34.9034 19.3439 34.7796 19.464L32.842 21.4017V13.3812L39.7592 7.73301C39.8345 7.67137 39.8951 7.5938 39.9367 7.5059C39.9784 7.41799 40 7.32194 40 7.22467C40 7.12741 39.9784 7.03137 39.9367 6.94348C39.8951 6.85559 39.8344 6.77804 39.7591 6.71641ZM32.1852 12.2213L26.0655 7.22467L32.1852 2.22805L38.3049 7.22467L32.1852 12.2213Z\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Planning &amp; Consultation<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                We begin by understanding your current with state goals and the futuer challenges.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-582a7dd e-con-full e-flex e-con e-child\" data-id=\"582a7dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b297e9 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"3b297e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n            <div class=\"numbering\">\r\n            <span>02<\/span>\r\n        <\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 40 40\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.9059 19.3622L30.0736 23.1145H25.7383L27.9059 19.3622ZM24.7116 24.3005H31.1001C31.5435 24.3005 31.8415 23.8062 31.6084 23.4134L28.4192 17.8821C28.1977 17.4949 27.6195 17.4859 27.3927 17.8821L24.1984 23.4134C23.9679 23.8107 24.2684 24.3005 24.7116 24.3005ZM26.396 10.243C26.5938 10.0439 26.8291 9.88597 27.0882 9.77817C27.3473 9.67037 27.6252 9.61487 27.9059 9.61487C28.1865 9.61487 28.4644 9.67037 28.7235 9.77817C28.9827 9.88597 29.2179 10.0439 29.4158 10.243C30.248 11.0752 30.248 12.4257 29.4158 13.2578C28.5836 14.09 27.2282 14.09 26.396 13.2578C25.5638 12.4256 25.5638 11.0751 26.396 10.243ZM27.9059 15.0666C28.753 15.0666 29.6052 14.7427 30.2529 14.0949C31.5435 12.8043 31.5435 10.6965 30.2529 9.40577C28.9573 8.11015 26.8544 8.11015 25.5588 9.40577C24.2682 10.6964 24.2682 12.8043 25.5588 14.0949C26.2066 14.7428 27.0538 15.0666 27.9059 15.0666ZM20.755 13.8458H16.5692V9.65499H20.755V13.8458ZM21.348 8.47394H15.9762C15.8982 8.47371 15.821 8.48889 15.749 8.5186C15.6769 8.54832 15.6115 8.59199 15.5564 8.64709C15.5013 8.7022 15.4576 8.76766 15.4279 8.8397C15.3982 8.91175 15.383 8.98895 15.3832 9.06689V14.4337C15.383 14.5117 15.3982 14.5889 15.4279 14.6609C15.4576 14.733 15.5013 14.7984 15.5564 14.8535C15.6115 14.9086 15.6769 14.9523 15.749 14.982C15.821 15.0117 15.8982 15.0269 15.9762 15.0267H21.348C21.672 15.0267 21.941 14.7626 21.941 14.4337V9.06689C21.941 8.73803 21.6719 8.47394 21.348 8.47394ZM0.926918 9.95393C0.926918 10.2779 1.19101 10.5419 1.51995 10.5419C1.84388 10.5419 2.10797 10.2779 2.10797 9.95393V1.91108H29.1218C29.1997 1.91131 29.2769 1.89613 29.349 1.86642C29.421 1.8367 29.4865 1.79304 29.5416 1.73793C29.5967 1.68283 29.6404 1.61737 29.6701 1.54532C29.6998 1.47328 29.715 1.39607 29.7148 1.31813C29.715 1.24019 29.6999 1.16296 29.6702 1.0909C29.6404 1.01884 29.5968 0.953368 29.5416 0.898252C29.4865 0.843135 29.4211 0.799462 29.349 0.769745C29.2769 0.740029 29.1997 0.724857 29.1218 0.725101H1.51995C1.442 0.724857 1.36478 0.740029 1.29272 0.769745C1.22066 0.799462 1.15519 0.843135 1.10007 0.898252C1.04495 0.953368 1.00128 1.01884 0.971563 1.0909C0.941847 1.16296 0.926674 1.24019 0.926918 1.31813V9.95393ZM39.5166 6.02226C39.5166 5.69332 39.2475 5.42923 38.9236 5.42923C38.8457 5.42898 38.7685 5.44416 38.6964 5.47387C38.6244 5.50359 38.5589 5.54726 38.5038 5.60238C38.4487 5.6575 38.405 5.72297 38.3753 5.79503C38.3455 5.86709 38.3304 5.94431 38.3306 6.02226V33.031H25.8927C25.5688 33.031 25.3047 33.3002 25.3047 33.6241C25.3047 33.9529 25.5688 34.2171 25.8927 34.2171H38.9236C39.2476 34.2171 39.5166 33.953 39.5166 33.6241V6.02226ZM20.7351 25.5014C21.8065 25.5014 22.6736 26.4283 22.6736 27.5645V29.1491H32.5303C33.7512 29.1491 34.7478 28.1525 34.7478 26.9316V7.74143C34.7478 6.52052 33.7512 5.52392 32.5303 5.52392H7.48987C6.26896 5.52392 5.27236 6.52052 5.27236 7.74143V12.5901H10.9083C11.9548 12.5901 12.8069 13.4422 12.8069 14.4887V15.4554C13.8035 15.5402 14.5859 16.4321 14.5859 17.5135V23.0697C15.6844 22.5789 16.8969 23.2318 17.2071 24.4052C18.2857 23.8553 19.579 24.4826 19.903 25.7008C20.1607 25.5695 20.4459 25.5011 20.7351 25.5014ZM21.4476 30.7786C21.2034 36.29 19.6636 38.1387 15.3382 38.0889C10.8832 38.0441 10.5993 35.6124 10.1707 31.9347C10.1258 31.5511 10.081 31.1524 10.0312 30.7537C10.0312 30.7437 10.0262 30.7387 10.0262 30.7288C9.72718 28.9698 8.86514 27.7438 7.39509 26.9814C5.52861 26.0116 5.70708 24.7888 6.93661 24.7888C7.25051 24.7888 7.61932 24.8735 8.01796 25.0678L10.9979 26.7222C11.3983 26.9416 11.8799 26.6444 11.8799 26.204L11.8899 17.5134C11.8899 17.035 12.2387 16.6314 12.6473 16.6314C13.0609 16.6314 13.4047 17.035 13.4047 17.5134V24.9732C13.4047 25.2971 13.6688 25.5612 13.9976 25.5612C14.3216 25.5612 14.5857 25.2971 14.5857 24.9732C14.5857 24.4948 14.9345 24.0911 15.3431 24.0911C15.7567 24.0911 16.1005 24.4948 16.1005 24.9732V26.2688C16.1003 26.3467 16.1154 26.4239 16.1452 26.496C16.1749 26.568 16.2186 26.6335 16.2737 26.6886C16.3288 26.7437 16.3943 26.7874 16.4663 26.8171C16.5384 26.8468 16.6156 26.862 16.6935 26.8617C17.0175 26.8617 17.2815 26.5976 17.2815 26.2688C17.2815 25.7904 17.6304 25.3868 18.039 25.3868C18.4526 25.3868 18.7964 25.7904 18.7964 26.2688V27.5644C18.7961 27.6423 18.8113 27.7195 18.841 27.7916C18.8708 27.8636 18.9144 27.9291 18.9695 27.9842C19.0246 28.0393 19.0901 28.083 19.1621 28.1127C19.2342 28.1424 19.3114 28.1576 19.3893 28.1573C19.7132 28.1573 19.9773 27.8933 19.9773 27.5644C19.9773 27.086 20.3262 26.6824 20.7348 26.6824C21.1433 26.6824 21.4922 27.086 21.4922 27.5644C21.4925 28.5383 21.5079 29.423 21.4476 30.7786ZM2.382 33.9629C1.98837 33.9629 1.66445 33.639 1.66445 33.2403V14.4887C1.66445 14.0949 1.98837 13.7711 2.382 13.7711H10.9082C11.3019 13.7711 11.6258 14.095 11.6258 14.4887V15.7594C11.0776 16.1281 10.7089 16.7759 10.7089 17.5135L10.694 25.2025L8.58107 24.0264C8.57113 24.0214 8.56611 24.0214 8.55617 24.0165C6.88179 23.1893 5.48153 23.7324 5.00818 24.6644C4.5248 25.6162 4.90848 27.0213 6.84694 28.028C7.98311 28.6209 8.62094 29.5379 8.86012 30.9183C8.90993 31.307 8.95481 31.6956 8.9996 32.0694C9.06938 32.7122 9.14409 33.35 9.2438 33.963L2.382 33.9629ZM32.5302 30.3351C34.4039 30.3351 35.9287 28.8053 35.9287 26.9316V7.74143C35.9287 5.86773 34.4039 4.34287 32.5302 4.34287H7.48978C5.61609 4.34287 4.09122 5.86773 4.09122 7.74143V12.5901H2.382C1.3355 12.5901 0.483398 13.4422 0.483398 14.4887V33.2403C0.483398 34.2917 1.3355 35.1439 2.382 35.1439H9.488C10.1145 37.567 11.5138 39.275 15.4728 39.275C21.3509 39.275 22.4911 35.5511 22.6486 30.3352L32.5302 30.3351Z\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Design &amp; Engineering<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                We begin by understanding your current with state goals and the futuer challenges.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0be13f9 e-con-full e-flex e-con e-child\" data-id=\"0be13f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef26736 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"ef26736\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n            <div class=\"numbering\">\r\n            <span>03<\/span>\r\n        <\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 42 38\"><path d=\"M28.7586 31.3881C27.724 31.9585 26.6291 32.4122 25.4941 32.7407C25.4779 32.7454 25.4637 32.7552 25.4537 32.7688C25.4437 32.7824 25.4385 32.799 25.4389 32.8158V37.2317C25.4385 37.3764 25.3808 37.515 25.2785 37.6173C25.1761 37.7195 25.0374 37.7771 24.8927 37.7773H17.1068C16.9621 37.777 16.8234 37.7194 16.7211 37.6171C16.6188 37.5148 16.5612 37.3761 16.5608 37.2314V32.8158C16.5613 32.799 16.5561 32.7824 16.5461 32.7688C16.5361 32.7553 16.5219 32.7454 16.5057 32.7407C15.3707 32.4122 14.2758 31.9585 13.2412 31.3881C13.2264 31.3797 13.2093 31.3765 13.1925 31.3789C13.1757 31.3813 13.1602 31.3892 13.1483 31.4013L10.0254 34.5243C9.92242 34.6261 9.78346 34.6832 9.63866 34.6832C9.49386 34.6832 9.3549 34.6261 9.25194 34.5243L3.74601 29.0188C3.6441 28.9163 3.58689 28.7776 3.58689 28.6331C3.58689 28.4885 3.6441 28.3499 3.74601 28.2474L6.87164 25.1244C6.88331 25.1123 6.89086 25.0968 6.89324 25.0802C6.89562 25.0635 6.89269 25.0465 6.88488 25.0316C6.31336 23.9974 5.8595 22.9024 5.53179 21.7672C5.52738 21.7507 5.51762 21.7361 5.50403 21.7257C5.49044 21.7153 5.47379 21.7097 5.45668 21.7098H1.03855C0.966856 21.7098 0.895857 21.6957 0.829613 21.6683C0.76337 21.6409 0.703179 21.6007 0.652483 21.55C0.601787 21.4993 0.56158 21.4391 0.534159 21.3728C0.506738 21.3066 0.492642 21.2356 0.492676 21.1639V17.2716C0.492994 17.1269 0.550607 16.9883 0.65291 16.886C0.755213 16.7837 0.893874 16.7261 1.03855 16.7257H4.67654C4.69706 16.7257 4.71673 16.7176 4.73123 16.7031C4.74574 16.6886 4.75389 16.6689 4.75389 16.6484V14.0979C4.75731 12.9221 5.22607 11.7955 6.05769 10.9643C6.88931 10.133 8.01617 9.66487 9.19196 9.66203H12.894C13.4984 9.66327 14.0962 9.78802 14.6507 10.0286C15.2052 10.2692 15.7047 10.6205 16.1185 11.0611C16.1318 11.0742 16.1492 11.0822 16.1678 11.0837C16.1864 11.0853 16.2049 11.0803 16.2202 11.0697C17.0238 10.5188 17.9755 10.2245 18.9497 10.2254H23.0496C24.0239 10.2245 24.9756 10.5188 25.7792 11.0697C25.7945 11.0803 25.813 11.0852 25.8316 11.0836C25.8501 11.0821 25.8675 11.0741 25.8808 11.0611C26.2947 10.6205 26.7942 10.2691 27.3487 10.0286C27.9032 9.78797 28.501 9.66324 29.1055 9.66203H32.8076C33.9833 9.66491 35.1102 10.1331 35.9418 10.9643C36.7734 11.7955 37.2421 12.9221 37.2456 14.0979V16.6484C37.2456 16.6689 37.2537 16.6886 37.2682 16.7031C37.2827 16.7176 37.3024 16.7257 37.3229 16.7257H40.9609C41.1056 16.7261 41.2442 16.7837 41.3465 16.886C41.4488 16.9883 41.5065 17.1269 41.5068 17.2716V21.1638C41.5068 21.2355 41.4927 21.3065 41.4653 21.3728C41.4379 21.439 41.3977 21.4992 41.347 21.5499C41.2963 21.6006 41.2361 21.6408 41.1698 21.6682C41.1036 21.6956 41.0326 21.7097 40.9609 21.7097H36.5429C36.5257 21.7096 36.5091 21.7152 36.4955 21.7256C36.4818 21.7359 36.4721 21.7506 36.4677 21.7671C36.1402 22.9024 35.6865 23.9974 35.1151 25.0316C35.1073 25.0465 35.1043 25.0635 35.1067 25.0802C35.1091 25.0968 35.1166 25.1123 35.1283 25.1244L38.2513 28.2474C38.3022 28.2979 38.3427 28.3579 38.3703 28.4241C38.3979 28.4903 38.4121 28.5614 38.4121 28.6331C38.4121 28.7048 38.3979 28.7758 38.3703 28.842C38.3427 28.9082 38.3022 28.9683 38.2513 29.0188L32.7479 34.5243C32.645 34.6261 32.506 34.6832 32.3612 34.6832C32.2164 34.6832 32.0775 34.6261 31.9745 34.5243L28.8515 31.4013C28.8397 31.3892 28.8242 31.3813 28.8074 31.3789C28.7906 31.3765 28.7734 31.3797 28.7586 31.3881ZM5.92521 16.7257H14.0189C14.0393 16.7255 14.0589 16.7173 14.0733 16.7028C14.0878 16.6884 14.096 16.6688 14.0962 16.6484V15.0792C14.0955 13.9031 14.5247 12.7672 15.3031 11.8855C15.3156 11.8705 15.3222 11.8515 15.3218 11.832C15.3214 11.8125 15.3139 11.7938 15.3008 11.7794C14.99 11.4541 14.6165 11.1953 14.2027 11.0187C13.789 10.842 13.3437 10.7512 12.8939 10.7516H9.19196C8.30544 10.7548 7.45613 11.1083 6.82926 11.7352C6.2024 12.362 5.84885 13.2114 5.84572 14.0979V16.6484C5.84611 16.6692 5.85468 16.689 5.86959 16.7035C5.88449 16.7179 5.90443 16.726 5.92521 16.7257ZM26.6963 11.8855C27.4746 12.7672 27.9038 13.9031 27.903 15.0792V16.6484C27.9033 16.6688 27.9115 16.6884 27.926 16.7028C27.9404 16.7172 27.96 16.7255 27.9804 16.7257H36.074C36.0948 16.726 36.1148 16.7179 36.1297 16.7035C36.1446 16.689 36.1532 16.6692 36.1536 16.6484V14.0979C36.1505 13.2114 35.7969 12.3621 35.1701 11.7352C34.5433 11.1084 33.6941 10.7548 32.8076 10.7516H29.1056C28.6557 10.7512 28.2105 10.842 27.7968 11.0187C27.383 11.1953 27.0095 11.4541 26.6987 11.7794C26.6851 11.7935 26.6772 11.8123 26.6768 11.832C26.6764 11.8517 26.6833 11.8708 26.6963 11.8855ZM30.9554 0.659992C31.71 0.659788 32.4478 0.883373 33.0754 1.30247C33.703 1.72157 34.1922 2.31737 34.4812 3.01451C34.7702 3.71165 34.8459 4.47883 34.6989 5.21903C34.5519 5.95923 34.1886 6.63921 33.6552 7.17297C33.1217 7.70674 32.4419 8.07032 31.7018 8.21774C30.9616 8.36515 30.1944 8.28978 29.4971 8.00116C28.7998 7.71254 28.2038 7.22363 27.7844 6.59626C27.3649 5.96889 27.141 5.23123 27.1408 4.47656C27.1406 3.46458 27.5424 2.49396 28.2578 1.77818C28.9732 1.0624 29.9434 0.660402 30.9554 0.659992ZM32.8826 2.54967C32.5016 2.16864 32.0162 1.90914 31.4878 1.80399C30.9593 1.69884 30.4115 1.75276 29.9137 1.95894C29.4159 2.16512 28.9904 2.51429 28.6911 2.96229C28.3917 3.4103 28.2319 3.93701 28.2319 4.47583C28.2319 5.01465 28.3917 5.54137 28.6911 5.98937C28.9904 6.43738 29.4159 6.78655 29.9137 6.99272C30.4115 7.1989 30.9593 7.25282 31.4878 7.14767C32.0162 7.04252 32.5016 6.78302 32.8826 6.40199C33.3932 5.89099 33.68 5.19819 33.68 4.47583C33.68 3.75348 33.3932 3.06067 32.8826 2.54967ZM11.044 0.659992C11.7986 0.660264 12.5361 0.884254 13.1634 1.30364C13.7906 1.72303 14.2795 2.31899 14.5681 3.01618C14.8567 3.71336 14.9321 4.48046 14.7848 5.2205C14.6375 5.96055 14.2741 6.6403 13.7405 7.17382C13.2069 7.70735 12.5271 8.07069 11.7871 8.21791C11.047 8.36513 10.2799 8.28963 9.58278 8.00094C8.88563 7.71224 8.28973 7.22333 7.87041 6.59601C7.45109 5.96869 7.22718 5.23112 7.227 4.47656C7.22683 3.97526 7.32544 3.47884 7.5172 3.01567C7.70897 2.5525 7.99012 2.13166 8.3446 1.77719C8.69907 1.42272 9.11992 1.14158 9.5831 0.949824C10.0463 0.758071 10.5427 0.659812 11.044 0.659992ZM12.969 2.54967C12.588 2.16864 12.1026 1.90914 11.5742 1.80399C11.0457 1.69884 10.4979 1.75276 10.0001 1.95894C9.5023 2.16512 9.07681 2.51429 8.77745 2.96229C8.47809 3.4103 8.31831 3.93701 8.31831 4.47583C8.31831 5.01465 8.47809 5.54137 8.77745 5.98937C9.07681 6.43738 9.5023 6.78655 10.0001 6.99272C10.4979 7.1989 11.0457 7.25282 11.5742 7.14767C12.1026 7.04252 12.588 6.78302 12.969 6.40199C13.4796 5.89099 13.7664 5.19819 13.7664 4.47583C13.7664 3.75348 13.4796 3.06067 12.969 2.54967ZM15.2654 16.7257H26.734C26.7545 16.7255 26.774 16.7172 26.7884 16.7028C26.8029 16.6884 26.8111 16.6688 26.8114 16.6484V15.0792C26.8081 14.0825 26.4107 13.1276 25.706 12.4228C25.0013 11.718 24.0464 11.3206 23.0497 11.3172H18.9498C17.9531 11.3202 16.998 11.7175 16.2932 12.4223C15.5884 13.1271 15.1911 14.0822 15.1881 15.0789V16.6481C15.1883 16.6686 15.1966 16.6881 15.211 16.7025C15.2255 16.717 15.245 16.7255 15.2654 16.7257ZM20.9987 0.222656C21.8555 0.222656 22.693 0.476737 23.4054 0.952767C24.1178 1.4288 24.6731 2.10539 25.0009 2.89699C25.3288 3.68859 25.4145 4.55963 25.2473 5.39997C25.0801 6.2403 24.6675 7.01217 24.0616 7.61798C23.4557 8.22378 22.6837 8.63631 21.8434 8.80338C21.003 8.97045 20.132 8.88456 19.3404 8.55659C18.5489 8.22861 17.8724 7.67326 17.3964 6.96079C16.9205 6.24832 16.6666 5.41071 16.6667 4.55391C16.6674 3.40528 17.124 2.3039 17.9363 1.49176C18.7486 0.679623 19.85 0.223157 20.9987 0.222656ZM23.2906 2.26487C22.8375 1.81176 22.2602 1.50319 21.6318 1.37817C21.0033 1.25315 20.3519 1.31731 19.7598 1.56252C19.1678 1.80773 18.6618 2.22299 18.3058 2.75578C17.9498 3.28857 17.7598 3.91497 17.7598 4.55575C17.7598 5.19654 17.9498 5.82293 18.3058 6.35573C18.6618 6.88852 19.1678 7.30378 19.7598 7.54899C20.3519 7.7942 21.0033 7.85836 21.6318 7.73334C22.2602 7.60832 22.8375 7.29974 23.2906 6.84663C23.5917 6.54595 23.8306 6.18885 23.9936 5.79576C24.1566 5.40266 24.2405 4.9813 24.2405 4.55575C24.2405 4.13021 24.1566 3.70884 23.9936 3.31575C23.8306 2.92266 23.5917 2.56556 23.2906 2.26487ZM1.58443 17.8949V20.5405C1.58442 20.5509 1.58649 20.5611 1.59052 20.5706C1.59455 20.5802 1.60044 20.5888 1.60786 20.596C1.61528 20.6032 1.62408 20.6089 1.63372 20.6126C1.64336 20.6164 1.65366 20.6182 1.664 20.6179H5.92968C6.05879 20.6182 6.18365 20.664 6.28229 20.7474C6.38092 20.8307 6.44702 20.9461 6.46894 21.0733V21.0819C6.81858 22.4097 7.34804 23.6835 8.04263 24.868C8.17961 25.1023 8.17523 25.363 7.97852 25.5597L4.95936 28.5789C4.95203 28.5859 4.94619 28.5943 4.94221 28.6036C4.93822 28.6129 4.93616 28.623 4.93616 28.6331C4.93616 28.6432 4.93822 28.6532 4.94221 28.6625C4.94619 28.6718 4.95203 28.6802 4.95936 28.6872L9.5828 33.3107C9.59 33.318 9.5986 33.3239 9.60809 33.3278C9.61758 33.3318 9.62777 33.3339 9.63806 33.3339C9.64835 33.3339 9.65854 33.3318 9.66803 33.3278C9.67752 33.3239 9.68611 33.318 9.69332 33.3107L12.7102 30.2937C12.9069 30.097 13.1699 30.0904 13.4043 30.2275C14.5881 30.9233 15.862 31.4528 17.1902 31.8011C17.1925 31.8011 17.1947 31.8033 17.1969 31.8033C17.3242 31.8244 17.4398 31.8899 17.5232 31.9883C17.6067 32.0867 17.6524 32.2114 17.6524 32.3404V36.6086C17.6527 36.629 17.6609 36.6486 17.6753 36.663C17.6898 36.6775 17.7093 36.6857 17.7298 36.6859H24.2696C24.29 36.6857 24.3096 36.6775 24.324 36.663C24.3385 36.6486 24.3467 36.629 24.3469 36.6086V32.3407H24.3491C24.3493 32.2201 24.3896 32.103 24.4636 32.0078C24.5377 31.9126 24.6412 31.8446 24.758 31.8147C26.1044 31.4663 27.3957 30.9322 28.5948 30.2277C28.8291 30.0907 29.0899 30.0973 29.2866 30.294L32.3058 33.3109C32.313 33.3183 32.3216 33.3241 32.3311 33.3281C32.3405 33.332 32.3507 33.3341 32.361 33.3341C32.3713 33.3341 32.3815 33.332 32.3909 33.3281C32.4004 33.3241 32.409 33.3183 32.4162 33.3109L37.0397 28.6875C37.0535 28.6729 37.0613 28.6535 37.0613 28.6333C37.0613 28.6132 37.0535 28.5938 37.0397 28.5792L34.021 25.5598C33.8243 25.3631 33.8198 25.1023 33.9548 24.8681C34.6517 23.6837 35.182 22.4089 35.5306 21.0797V21.0731C35.5525 20.9458 35.6186 20.8304 35.7173 20.7471C35.8159 20.6638 35.9407 20.6179 36.0699 20.6176H40.3357C40.3461 20.6179 40.3563 20.6161 40.366 20.6124C40.3756 20.6086 40.3844 20.603 40.3918 20.5958C40.3993 20.5885 40.4052 20.5799 40.4092 20.5704C40.4132 20.5608 40.4153 20.5506 40.4153 20.5403V17.8949C40.4149 17.8741 40.4064 17.8543 40.3914 17.8398C40.3765 17.8254 40.3565 17.8174 40.3357 17.8176H32.1957C32.1761 17.818 32.1573 17.8256 32.143 17.8391C32.1287 17.8526 32.1199 17.8709 32.1184 17.8905C31.9601 20.7322 30.7197 23.4054 28.652 25.3612C26.5843 27.317 23.8462 28.4068 21.0001 28.4068C18.1539 28.4068 15.4158 27.317 13.3481 25.3612C11.2804 23.4054 10.04 20.7322 9.88178 17.8905C9.88026 17.8709 9.8715 17.8525 9.8572 17.8391C9.84289 17.8256 9.82408 17.8179 9.80443 17.8176H1.66383C1.64305 17.8174 1.62303 17.8254 1.60812 17.8399C1.59322 17.8544 1.58481 17.8741 1.58443 17.8949ZM30.9467 17.8176H11.0528C11.0423 17.8176 11.0319 17.8198 11.0223 17.824C11.0126 17.8282 11.0039 17.8343 10.9967 17.8419C10.9895 17.8496 10.9839 17.8586 10.9802 17.8684C10.9766 17.8783 10.975 17.8888 10.9755 17.8993C11.1347 20.4498 12.2601 22.8437 14.1225 24.5935C15.9849 26.3433 18.4443 27.3174 20.9998 27.3174C23.5552 27.3174 26.0146 26.3433 27.877 24.5935C29.7394 22.8437 30.8648 20.4498 31.024 17.8993C31.0246 17.8888 31.0229 17.8783 31.0193 17.8684C31.0157 17.8586 31.01 17.8496 31.0028 17.8419C30.9956 17.8343 30.9869 17.8282 30.9772 17.824C30.9676 17.8198 30.9572 17.8176 30.9467 17.8176Z\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Construction Execution<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                We begin by understanding your current with state goals and the futuer challenges.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e4d55a e-con-full e-flex e-con e-child\" data-id=\"6e4d55a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ffaee7 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"0ffaee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n            <div class=\"services-box-line\"><\/div>\r\n            <div class=\"numbering\">\r\n            <span>04<\/span>\r\n        <\/div>\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 40 42\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M10.2804 37.4735C10.3637 37.5929 10.3963 37.7405 10.3708 37.8839C10.3454 38.0272 10.2641 38.1546 10.1447 38.238C10.0253 38.3214 9.87774 38.3539 9.73438 38.3285C9.59101 38.3031 9.46363 38.2217 9.38024 38.1023L9.34698 38.0548C9.26515 37.9354 9.2338 37.7885 9.25974 37.6461C9.28568 37.5037 9.36681 37.3772 9.48549 37.2943C9.60417 37.2114 9.75078 37.1788 9.89343 37.2034C10.0361 37.2281 10.1632 37.3081 10.2472 37.426L10.2804 37.4735ZM17.1957 31.0585C17.0552 31.0191 16.9361 30.9255 16.8647 30.7982C16.7932 30.671 16.7752 30.5206 16.8146 30.3801C16.854 30.2396 16.9476 30.1205 17.0748 30.0491C17.202 29.9776 17.3524 29.9595 17.4929 29.999L24.5166 31.9891C24.9679 32.1176 25.4516 32.0646 25.8644 31.8415C26.0649 31.7338 26.2421 31.5876 26.3858 31.4112C26.5295 31.2348 26.6369 31.0317 26.7017 30.8136C26.7174 30.7609 26.7304 30.708 26.7409 30.6551C26.7421 30.6478 26.7435 30.6405 26.745 30.6333C26.8221 30.2087 26.7402 29.7706 26.515 29.4026C26.2898 29.0345 25.937 28.7622 25.5239 28.6375C23.522 28.0418 21.5543 27.3344 19.6314 26.5187C16.1449 25.0778 15.9232 24.9873 8.99232 28.6527L13.501 35.1588L13.5879 35.0284L13.5895 35.0295L13.5901 35.0284C13.7665 34.7602 14.0256 34.5569 14.3281 34.4495C14.6306 34.342 14.9599 34.3363 15.2659 34.4332L23.6119 37.0182C25.8737 37.719 31.0783 33.8692 34.6205 31.2492C35.6292 30.5031 36.5085 29.8527 37.1512 29.4312C37.7487 29.0392 37.9579 28.6163 37.8999 28.2408C37.8609 28.0287 37.7658 27.831 37.6245 27.6682C37.4375 27.4493 37.2111 27.2675 36.957 27.1322C36.4282 26.8491 35.8325 26.7146 35.2333 26.7431C34.6341 26.7716 34.0539 26.9621 33.5544 27.2942L27.7686 31.0891C27.7649 31.1022 27.7612 31.1153 27.7573 31.1283C27.651 31.4854 27.4751 31.8179 27.2397 32.1067C27.0044 32.3954 26.7142 32.6348 26.3859 32.8109C25.7224 33.1698 24.9449 33.255 24.2194 33.0484L17.1957 31.0585ZM8.36137 27.7413L8.01031 27.2343C7.78531 26.9105 7.44116 26.689 7.05322 26.6184C6.66529 26.5478 6.26518 26.6338 5.94051 26.8575L1.62533 29.8481C1.30152 30.0731 1.08006 30.4173 1.00945 30.8052C0.93884 31.1932 1.02482 31.5933 1.24858 31.9179L7.59163 41.0713C7.81666 41.3951 8.16084 41.6166 8.5488 41.6872C8.93677 41.7578 9.3369 41.6718 9.6616 41.4481L13.9768 38.4574C14.3006 38.2324 14.5221 37.8883 14.5927 37.5003C14.6633 37.1123 14.5773 36.7122 14.3534 36.3875L14.1766 36.1324L14.5056 35.639L14.504 35.638C14.5497 35.5671 14.6177 35.5135 14.6973 35.4855C14.7768 35.4575 14.8635 35.4567 14.9435 35.4833L23.2894 38.0684C26.0802 38.933 31.5518 34.8858 35.2755 32.1313C36.2531 31.4082 37.1052 30.7779 37.7546 30.3524C38.7717 29.6853 39.1118 28.8617 38.9899 28.0723C38.9198 27.6652 38.7414 27.2844 38.4733 26.9701C38.198 26.6427 37.8634 26.3702 37.487 26.167C36.9023 25.8497 36.2526 25.6703 35.5878 25.6428C37.3848 23.2549 38.4701 20.4076 38.7185 17.4294C38.967 14.4513 38.3685 11.4635 36.992 8.81085C35.6156 6.15819 33.5173 3.94867 30.9392 2.43716C28.3611 0.925658 25.4083 0.173748 22.4212 0.26817C19.4342 0.362591 16.5347 1.2995 14.0573 2.97081C11.5798 4.64212 9.62523 6.97976 8.41907 9.71406C7.21292 12.4484 6.80431 15.4679 7.24036 18.4245C7.67641 21.381 8.93937 24.154 10.8835 26.4237C10.1445 26.801 9.31081 27.2387 8.36137 27.7413ZM11.8986 25.9144C10.0116 23.7915 8.77776 21.1687 8.34542 18.3614C7.91308 15.5541 8.30063 12.6816 9.46149 10.0892C10.6223 7.49686 12.5071 5.29487 14.8893 3.74789C17.2715 2.20091 20.0497 1.37476 22.8902 1.36872C25.7306 1.36269 28.5123 2.17703 30.901 3.71387C33.2898 5.25072 35.1839 7.44468 36.3558 10.0321C37.5276 12.6195 37.9274 15.4903 37.507 18.2994C37.0866 21.1086 35.8639 23.7365 33.9859 25.8675C33.621 25.9907 33.2734 26.1602 32.9517 26.3719L27.8152 29.7406C27.7102 29.2363 27.4711 28.7696 27.1232 28.3897C26.7753 28.0098 26.3313 27.7307 25.8381 27.5819C23.8711 26.9972 21.9383 26.3027 20.049 25.5015C16.8364 24.1739 16.0803 23.8622 11.8986 25.9144ZM13.0854 36.4877L13.0768 36.4773L13.0742 36.4734C13.0595 36.4543 13.046 36.4342 13.034 36.4132L7.10591 27.8589C7.07705 27.8173 7.04024 27.7817 6.99761 27.7543C6.95497 27.7269 6.90735 27.7082 6.85746 27.6993C6.80701 27.69 6.75523 27.6908 6.70509 27.7016C6.65495 27.7125 6.60744 27.7331 6.56527 27.7623L2.25009 30.7529C2.20842 30.7817 2.17286 30.8185 2.14544 30.8612C2.11803 30.9038 2.0993 30.9514 2.09034 31.0013C2.0811 31.0518 2.0819 31.1036 2.09271 31.1537C2.10352 31.2038 2.12412 31.2514 2.15333 31.2935L8.49689 40.4477C8.52577 40.4893 8.56257 40.5248 8.60519 40.5521C8.64781 40.5795 8.6954 40.5982 8.74525 40.6072C8.7957 40.6164 8.84748 40.6156 8.89762 40.6048C8.94776 40.594 8.99527 40.5734 9.03744 40.5442L13.3527 37.5535C13.3944 37.5247 13.4299 37.4879 13.4573 37.4453C13.4847 37.4026 13.5034 37.355 13.5124 37.3051C13.5216 37.2547 13.5208 37.2029 13.51 37.1527C13.4992 37.1026 13.4787 37.0551 13.4495 37.0129L13.0854 36.4877ZM27.7782 9.34516C28.2816 9.34509 28.7695 9.51957 29.1587 9.83889C29.5479 10.1582 29.8143 10.6026 29.9126 11.0964C30.0109 11.5901 29.9349 12.1026 29.6976 12.5466C29.4603 12.9907 29.0764 13.3387 28.6114 13.5313C28.1463 13.724 27.6287 13.7495 27.147 13.6034C26.6652 13.4573 26.249 13.1486 25.9693 12.7301C25.6896 12.3115 25.5637 11.8089 25.613 11.3079C25.6624 10.8069 25.8839 10.3385 26.2399 9.98248C26.4417 9.78015 26.6814 9.61969 26.9454 9.51032C27.2094 9.40095 27.4924 9.34482 27.7782 9.34516ZM28.5373 10.762C28.713 10.9376 28.8224 11.1688 28.8468 11.416C28.8712 11.6632 28.8091 11.9113 28.6712 12.1179C28.5332 12.3245 28.3278 12.4769 28.0901 12.549C27.8524 12.6212 27.597 12.6087 27.3675 12.5137C27.1379 12.4186 26.9484 12.2469 26.8313 12.0278C26.7141 11.8088 26.6766 11.5558 26.725 11.3122C26.7735 11.0685 26.9049 10.8491 27.0969 10.6915C27.289 10.5339 27.5297 10.4478 27.7782 10.4477C27.9192 10.4475 28.0588 10.4752 28.1891 10.5291C28.3193 10.5831 28.4377 10.6622 28.5373 10.762ZM17.5659 9.34516C18.0693 9.34509 18.5572 9.51957 18.9464 9.83889C19.3356 10.1582 19.602 10.6026 19.7003 11.0964C19.7986 11.5901 19.7226 12.1026 19.4853 12.5466C19.248 12.9907 18.8641 13.3387 18.3991 13.5313C17.934 13.724 17.4164 13.7495 16.9347 13.6034C16.4529 13.4573 16.0367 13.1486 15.757 12.7301C15.4773 12.3115 15.3514 11.8089 15.4007 11.3079C15.4501 10.8069 15.6716 10.3385 16.0276 9.98248C16.2294 9.78016 16.4692 9.6197 16.7331 9.51033C16.9971 9.40096 17.2801 9.34483 17.5659 9.34516ZM18.3249 10.762C18.5006 10.9376 18.61 11.1687 18.6344 11.4159C18.6588 11.6632 18.5967 11.9112 18.4587 12.1178C18.3208 12.3244 18.1154 12.4767 17.8777 12.5489C17.64 12.621 17.3846 12.6085 17.1551 12.5135C16.9256 12.4184 16.7361 12.2467 16.619 12.0277C16.5019 11.8086 16.4643 11.5557 16.5128 11.312C16.5612 11.0684 16.6927 10.8491 16.8847 10.6915C17.0767 10.5339 17.3175 10.4477 17.5659 10.4477C17.7069 10.4475 17.8465 10.4752 17.9767 10.5291C18.107 10.5831 18.2253 10.6622 18.3249 10.762ZM30.1032 19.2377C30.1832 19.116 30.3082 19.0311 30.4507 19.0016C30.5933 18.9722 30.7417 19.0005 30.8634 19.0805C30.985 19.1604 31.0699 19.2854 31.0994 19.428C31.1289 19.5705 31.1005 19.719 31.0206 19.8406C30.1397 21.1845 28.9383 22.288 27.5245 23.0517C26.1108 23.8154 24.5293 24.2152 22.9224 24.2152C21.3156 24.2152 19.7341 23.8154 18.3203 23.0517C16.9066 22.288 15.7052 21.1845 14.8243 19.8406C14.7443 19.719 14.716 19.5705 14.7455 19.428C14.775 19.2854 14.8599 19.1604 14.9815 19.0805C15.1032 19.0005 15.2516 18.9722 15.3942 19.0016C15.5367 19.0311 15.6617 19.116 15.7417 19.2377C16.5233 20.4286 17.5888 21.4064 18.8423 22.083C20.0958 22.7597 21.498 23.114 22.9224 23.114C24.3469 23.114 25.749 22.7597 27.0026 22.083C28.2561 21.4064 29.3216 20.4286 30.1032 19.2377Z\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Inspection &amp; Handover<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                We begin by understanding your current with state goals and the futuer challenges.            <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47bf758 e-con-full e-flex e-con e-parent\" data-id=\"47bf758\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-833c5f9 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-gsap-marquee-slide\" data-id=\"833c5f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-gsap-marquee-slide.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"rs-marquee-slider-gsap \">\n        <div class=\"gsap-marquee right speed-10 move-to-600\">\n            <div class=\"marquee-wrapper\">\n                <div class=\"slider-item image\">\n                    \n                                                \n                            <div class=\"marquee-item elementor-repeater-item-640cbeb\">\n                                                                    <p class=\"\">Construction<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-8180446\">\n                                                                    <p class=\"\">Building<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-0a6b5c2\">\n                                                                    <p class=\"\">Renovation<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-ac6d7cc\">\n                                                                    <p class=\"\">Construction<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-d570dd1\">\n                                                                    <p class=\"\">Building<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-09090b0\">\n                                                                    <p class=\"\">Renovation<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-e3255b2\">\n                                                                    <p class=\"\">Construction<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-16ae146\">\n                                                                    <p class=\"\">Building<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-c9d6e67\">\n                                                                    <p class=\"\">Renovation<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-c164e16\">\n                                                                    <p class=\"\">Construction<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-6d862e5\">\n                                                                    <p class=\"\">Building<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-57c7031\">\n                                                                    <p class=\"\">Renovation<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-d8ddcc1\">\n                                                                    <p class=\"\">Construction<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-1449bf4\">\n                                                                    <p class=\"\">Building<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                                    \n                            <div class=\"marquee-item elementor-repeater-item-47b5726\">\n                                                                    <p class=\"\">Renovation<\/p>\n                                                                <div class=\"image-wrapper\">\n                                    <img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png\" class=\"attachment-  size- \" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax.png 120w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/admin-0ajax-100x100.png 100w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/>                                <\/div>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18a3b1cf elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"18a3b1cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41f49c17 e-flex e-con-boxed e-con e-parent\" data-id=\"41f49c17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-104cdb9a e-con-full e-flex e-con e-child\" data-id=\"104cdb9a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7aabd9bd gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"7aabd9bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1 center  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Why choose us<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"1\" data-delay=\"0.06\">Your Trusted Construction Partner<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>We believe that every business is uniquids our approach is never one size fits<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-596ee55e gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-tab-advanced\" data-id=\"596ee55e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-tab-advanced.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <div class=\"rstab-main horizontal tab_596ee55e auto_switch_no full_tab_item  style1\">\n            <nav class=\"tab-menu-wrapper\">\n                <div class=\"nav nav-tabs none\" id=\"nav-tab-596ee55e\" role=\"tablist\">\n                                            <button class=\"nav-link active count_number_no\" id=\"nav-home-1-1540193\" data-bs-toggle=\"tab\" data-bs-target=\"#tab1-1540193\" type=\"button\" role=\"tab\" aria-controls=\"nav-home-1-1540193\" aria-selected=\"true\">\n                                                            <span class=\"nav-btn-icon\">\n                                                                    <\/span>\n                                                        <span class=\"text-part\">\n                                Construction Quality                            <\/span>\n                        <\/button>\n\n                                            <button class=\"nav-link  count_number_no\" id=\"nav-home-2-1540193\" data-bs-toggle=\"tab\" data-bs-target=\"#tab2-1540193\" type=\"button\" role=\"tab\" aria-controls=\"nav-home-2-1540193\" aria-selected=\"true\">\n                                                            <span class=\"nav-btn-icon\">\n                                                                    <\/span>\n                                                        <span class=\"text-part\">\n                                Process Quality                            <\/span>\n                        <\/button>\n\n                                            <button class=\"nav-link  count_number_no\" id=\"nav-home-3-1540193\" data-bs-toggle=\"tab\" data-bs-target=\"#tab3-1540193\" type=\"button\" role=\"tab\" aria-controls=\"nav-home-3-1540193\" aria-selected=\"true\">\n                                                            <span class=\"nav-btn-icon\">\n                                                                    <\/span>\n                                                        <span class=\"text-part\">\n                                Safety &amp; Trust Quality                            <\/span>\n                        <\/button>\n\n                                    <\/div>\n            <\/nav>\n            <div class=\"tab-content\" id=\"nav-tabContent-596ee55e\">\n                                    <div class=\"tab-pane fade show active\" id=\"tab1-1540193\" role=\"tabpanel\" aria-labelledby=\"nav-home-1-1540193\">\n                                                                                                                <div class=\"content--teb-area half-sec\">\n                                    <div class=\"image--right-area\"><img decoding=\"async\" class=\"nor_imgs\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/post_02.jpg\" alt=\"post_02\" \/><\/div>\n                                    <div class=\"content--left-area\">\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                    <div class=\"title\">Expert Quality in Construction<\/div>\n                                        \n                                        <div class=\"desc_btn_wrapper\">\n                                                                                            <p>We provide the best services ensuring your outstanding growth Lorem ipsum dolor sit amet. Nulla ultrices neque sodales best<\/p>                                                                                    <\/div>\n                                        \n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Outstanding Performance<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Strategy Meets Technology<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Global Support Network<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Exceptional Communication<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Rapid Talent Acquisition<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> 24\/7 Availability Across Time<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                            \n                                            <\/div>\n\n                                    <div class=\"tab-pane fade \" id=\"tab2-1540193\" role=\"tabpanel\" aria-labelledby=\"nav-home-2-1540193\">\n                                                                                                                <div class=\"content--teb-area half-sec\">\n                                    <div class=\"image--right-area\"><img decoding=\"async\" class=\"nor_imgs\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/post_01.jpg\" alt=\"post_01\" \/><\/div>\n                                    <div class=\"content--left-area\">\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                    <div class=\"title\">Expert Quality in Process<\/div>\n                                        \n                                        <div class=\"desc_btn_wrapper\">\n                                                                                            <p>We provide the best services ensuring your outstanding growth Lorem ipsum dolor sit amet. Nulla ultrices neque sodales best<\/p>                                                                                    <\/div>\n                                        \n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Outstanding Performance<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Strategy Meets Technology<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Global Support Network<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Exceptional Communication<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Rapid Talent Acquisition<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> 24\/7 Availability Across Time<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                            \n                                            <\/div>\n\n                                    <div class=\"tab-pane fade \" id=\"tab3-1540193\" role=\"tabpanel\" aria-labelledby=\"nav-home-3-1540193\">\n                                                                                                                <div class=\"content--teb-area half-sec\">\n                                    <div class=\"image--right-area\"><img decoding=\"async\" class=\"nor_imgs\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/post_04.jpg\" alt=\"post_04\" \/><\/div>\n                                    <div class=\"content--left-area\">\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                    <div class=\"title\">Expert Quality in Safety &#038; Trust<\/div>\n                                        \n                                        <div class=\"desc_btn_wrapper\">\n                                                                                            <p>We provide the best services ensuring your outstanding growth Lorem ipsum dolor sit amet. Nulla ultrices neque sodales best<\/p>                                                                                    <\/div>\n                                        \n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Outstanding Performance<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Strategy Meets Technology<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Global Support Network<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Exceptional Communication<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> Rapid Talent Acquisition<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"10\" viewBox=\"0 0 12 10\" fill=\"none\"><path d=\"M5.53798 9.63481C5.50614 9.6348 5.47466 9.62821 5.4455 9.61545C5.41633 9.60269 5.39013 9.58404 5.36852 9.56066L0.799591 4.61839C0.769134 4.58544 0.748942 4.54433 0.741488 4.50008C0.734034 4.45584 0.73964 4.41038 0.757622 4.36927C0.775603 4.32816 0.805178 4.29318 0.842729 4.26862C0.880279 4.24406 0.924175 4.23098 0.969045 4.23098H3.16828C3.2013 4.23098 3.23393 4.23807 3.26398 4.25176C3.29403 4.26545 3.32079 4.28542 3.34246 4.31034L4.86941 6.06705C5.03444 5.71429 5.35389 5.12694 5.91448 4.41123C6.74321 3.35315 8.28471 1.79705 10.922 0.392315C10.973 0.36517 11.0323 0.358125 11.0882 0.372571C11.1441 0.387016 11.1926 0.421903 11.2241 0.470342C11.2555 0.51878 11.2676 0.57725 11.2581 0.634205C11.2485 0.69116 11.218 0.742461 11.1724 0.777976C11.1624 0.785846 10.1455 1.58662 8.97521 3.05336C7.89817 4.40313 6.46643 6.61021 5.76191 9.45951C5.74954 9.50957 5.72075 9.55404 5.68015 9.58583C5.63955 9.61762 5.58947 9.6349 5.53791 9.6349L5.53798 9.63481Z\" fill=\"black\"><\/path><\/svg> 24\/7 Availability Across Time<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                            \n                                            <\/div>\n\n                            <\/div>\n        <\/div>\n        \n        <div class=\"accordion tab-menu-wrapper accordion-menu-wrapper rs_horizontal\" id=\"accordionExample-596ee55e\">\n\n                            <div class=\"accordion-item nav-tabs\">\n                    \n                    <div class=\"accordion-headerd\" id=\"heading_1-1540193\">\n                        <button class=\"nav-link accordion-button collapsed show\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_1-1540193\" aria-expanded=\"true\" aria-controls=\"collapse_1-1540193\">\n                            <span class=\"nav-btn-icon\">\n                                                            <\/span>\n\n                            <span class=\"text-part\">\n                                Construction Quality                            <\/span>\n                        <\/button>\n                    <\/div>\n\n                    <div id=\"collapse_1-1540193\" class=\"accordion-collapse collapse show\" aria-labelledby=\"heading_1-1540193\" data-bs-parent=\"#accordionExample-596ee55e\">\n                        <div class=\"tab-pane\">\n                                                                                                                            <div class=\"content--teb-area half-sec\">\n                                    <div class=\"image--right-area\"><img decoding=\"async\" class=\"nor_imgs\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/post_02.jpg\" alt=\"post_02\" \/><\/div>\n                                    <div class=\"content--left-area\">\n\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                    <div class=\"title\">Expert Quality in Construction<\/div>\n                                                                                <div class=\"desc_btn_wrapper\">\n                                                                                            <p>We provide the best services ensuring your outstanding growth Lorem ipsum dolor sit amet. Nulla ultrices neque sodales best<\/p>                                                                                    <\/div>\n\n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Outstanding Performance<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Strategy Meets Technology<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Global Support Network<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Exceptional Communication<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Rapid Talent Acquisition<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> 24\/7 Availability Across Time<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"accordion-item nav-tabs\">\n                    \n                    <div class=\"accordion-headerd\" id=\"heading_2-1540193\">\n                        <button class=\"nav-link accordion-button collapsed \" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_2-1540193\" aria-expanded=\"true\" aria-controls=\"collapse_2-1540193\">\n                            <span class=\"nav-btn-icon\">\n                                                            <\/span>\n\n                            <span class=\"text-part\">\n                                Process Quality                            <\/span>\n                        <\/button>\n                    <\/div>\n\n                    <div id=\"collapse_2-1540193\" class=\"accordion-collapse collapse \" aria-labelledby=\"heading_2-1540193\" data-bs-parent=\"#accordionExample-596ee55e\">\n                        <div class=\"tab-pane\">\n                                                                                                                            <div class=\"content--teb-area half-sec\">\n                                    <div class=\"image--right-area\"><img decoding=\"async\" class=\"nor_imgs\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/post_01.jpg\" alt=\"post_01\" \/><\/div>\n                                    <div class=\"content--left-area\">\n\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                    <div class=\"title\">Expert Quality in Process<\/div>\n                                                                                <div class=\"desc_btn_wrapper\">\n                                                                                            <p>We provide the best services ensuring your outstanding growth Lorem ipsum dolor sit amet. Nulla ultrices neque sodales best<\/p>                                                                                    <\/div>\n\n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Outstanding Performance<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Strategy Meets Technology<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Global Support Network<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Exceptional Communication<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Rapid Talent Acquisition<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> 24\/7 Availability Across Time<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"accordion-item nav-tabs\">\n                    \n                    <div class=\"accordion-headerd\" id=\"heading_3-1540193\">\n                        <button class=\"nav-link accordion-button collapsed \" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_3-1540193\" aria-expanded=\"true\" aria-controls=\"collapse_3-1540193\">\n                            <span class=\"nav-btn-icon\">\n                                                            <\/span>\n\n                            <span class=\"text-part\">\n                                Safety &amp; Trust Quality                            <\/span>\n                        <\/button>\n                    <\/div>\n\n                    <div id=\"collapse_3-1540193\" class=\"accordion-collapse collapse \" aria-labelledby=\"heading_3-1540193\" data-bs-parent=\"#accordionExample-596ee55e\">\n                        <div class=\"tab-pane\">\n                                                                                                                            <div class=\"content--teb-area half-sec\">\n                                    <div class=\"image--right-area\"><img decoding=\"async\" class=\"nor_imgs\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/post_04.jpg\" alt=\"post_04\" \/><\/div>\n                                    <div class=\"content--left-area\">\n\n                                                                                    <div class=\"content_part_image\">\n                                                                                            <\/div>\n                                        \n                                                                                    <div class=\"title\">Expert Quality in Safety &#038; Trust<\/div>\n                                                                                <div class=\"desc_btn_wrapper\">\n                                                                                            <p>We provide the best services ensuring your outstanding growth Lorem ipsum dolor sit amet. Nulla ultrices neque sodales best<\/p>                                                                                    <\/div>\n\n                                                                                    <ul class=\"rs-features-list\">\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Outstanding Performance<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Strategy Meets Technology<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Global Support Network<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Exceptional Communication<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> Rapid Talent Acquisition<\/li>\n                                                                                                    <li><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  viewBox=\"0 0 24 24\" width=\"48px\" height=\"48px\"><path d=\"M19.8,10.4c0.1,0.5,0.2,1.1,0.2,1.6c0,4.4-3.6,8-8,8s-8-3.6-8-8s3.6-8,8-8c1.6,0,3.2,0.5,4.4,1.3l1.4-1.4 C16.2,2.7,14.2,2,12,2C6.5,2,2,6.5,2,12s4.5,10,10,10s10-4.5,10-10c0-1.1-0.2-2.2-0.5-3.2L19.8,10.4z\"\/><path d=\"M11 16.4L6.3 11.7 7.7 10.3 11 13.6 21.3 3.3 22.7 4.7z\"\/><\/svg> 24\/7 Availability Across Time<\/li>\n                                                                                            <\/ul>\n                                        \n                                                                            <\/div>\n                                <\/div>\n                                                                                    <\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d2279d e-flex e-con-boxed e-con e-parent\" data-id=\"7d2279d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-66877b53 e-con-full e-flex e-con e-child\" data-id=\"66877b53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62d409f1 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-counter\" data-id=\"62d409f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"counter-top-area\">\r\n\t\t\t\t<div class=\"rs-counter-list\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"id-62d409f1 rs-counter odometer\">62.5<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"prefix\">\r\n\t\t\t\t\t\t\t\t\tK\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"title\">Customer Satisfaction <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-text\">01<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\tvar delay = 0;\r\n\t\t\t\tsetTimeout(function() {\r\n\t\t\t\t\t$(\".odometer.id-62d409f1\").each(function () {\r\n\t\t\t\t\t\tvar countNumber = 62.5;\r\n\t\t\t\t\t\tcountNumber = countNumber.toString();\r\n\t\t\t\t\t\tvar digits = countNumber.length;\r\n\t\t\t\t\t\tvar zeros = \"0\".repeat(digits);\r\n\t\t\t\t\t\t$(this).html(zeros);\r\n\t\t\t\t\t});\r\n\t\t\t\t\r\n\t\t\t\t\t$('.odometer.id-62d409f1').appear(function () {\r\n\t\t\t\t\t\t$(this).each(function () {\r\n\t\t\t\t\t\t\tvar countNumber = 62.5;\r\n\t\t\t\t\t\t\t$(this).html(countNumber);\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t});\r\n\t\t\t\t}, delay);\r\n\t\t\t});\r\n\r\n\t\t<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e915f5 e-con-full e-flex e-con e-child\" data-id=\"e915f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6035cd29 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-counter\" data-id=\"6035cd29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"counter-top-area\">\r\n\t\t\t\t<div class=\"rs-counter-list\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"id-6035cd29 rs-counter odometer\">7.8<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"prefix\">\r\n\t\t\t\t\t\t\t\t\tK\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"title\">Projects Completed<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-text\">02<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\tvar delay = 0;\r\n\t\t\t\tsetTimeout(function() {\r\n\t\t\t\t\t$(\".odometer.id-6035cd29\").each(function () {\r\n\t\t\t\t\t\tvar countNumber = 7.8;\r\n\t\t\t\t\t\tcountNumber = countNumber.toString();\r\n\t\t\t\t\t\tvar digits = countNumber.length;\r\n\t\t\t\t\t\tvar zeros = \"0\".repeat(digits);\r\n\t\t\t\t\t\t$(this).html(zeros);\r\n\t\t\t\t\t});\r\n\t\t\t\t\r\n\t\t\t\t\t$('.odometer.id-6035cd29').appear(function () {\r\n\t\t\t\t\t\t$(this).each(function () {\r\n\t\t\t\t\t\t\tvar countNumber = 7.8;\r\n\t\t\t\t\t\t\t$(this).html(countNumber);\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t});\r\n\t\t\t\t}, delay);\r\n\t\t\t});\r\n\r\n\t\t<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c938c3d e-con-full e-flex e-con e-child\" data-id=\"c938c3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e2b90fd gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-counter\" data-id=\"4e2b90fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"counter-top-area\">\r\n\t\t\t\t<div class=\"rs-counter-list\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"id-4e2b90fd rs-counter odometer\">125<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"prefix\">\r\n\t\t\t\t\t\t\t\t\t+\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"title\">Construction Award<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-text\">03<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\tvar delay = 0;\r\n\t\t\t\tsetTimeout(function() {\r\n\t\t\t\t\t$(\".odometer.id-4e2b90fd\").each(function () {\r\n\t\t\t\t\t\tvar countNumber = 125;\r\n\t\t\t\t\t\tcountNumber = countNumber.toString();\r\n\t\t\t\t\t\tvar digits = countNumber.length;\r\n\t\t\t\t\t\tvar zeros = \"0\".repeat(digits);\r\n\t\t\t\t\t\t$(this).html(zeros);\r\n\t\t\t\t\t});\r\n\t\t\t\t\r\n\t\t\t\t\t$('.odometer.id-4e2b90fd').appear(function () {\r\n\t\t\t\t\t\t$(this).each(function () {\r\n\t\t\t\t\t\t\tvar countNumber = 125;\r\n\t\t\t\t\t\t\t$(this).html(countNumber);\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t});\r\n\t\t\t\t}, delay);\r\n\t\t\t});\r\n\r\n\t\t<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69115323 e-con-full e-flex e-con e-child\" data-id=\"69115323\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7efaa gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-counter\" data-id=\"fb7efaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"counter-top-area\">\r\n\t\t\t\t<div class=\"rs-counter-list\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"id-fb7efaa rs-counter odometer\">60.5<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"prefix\">\r\n\t\t\t\t\t\t\t\t\tK\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"title\">Completed Projects <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"number-text\">04<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\tvar delay = 0;\r\n\t\t\t\tsetTimeout(function() {\r\n\t\t\t\t\t$(\".odometer.id-fb7efaa\").each(function () {\r\n\t\t\t\t\t\tvar countNumber = 60.5;\r\n\t\t\t\t\t\tcountNumber = countNumber.toString();\r\n\t\t\t\t\t\tvar digits = countNumber.length;\r\n\t\t\t\t\t\tvar zeros = \"0\".repeat(digits);\r\n\t\t\t\t\t\t$(this).html(zeros);\r\n\t\t\t\t\t});\r\n\t\t\t\t\r\n\t\t\t\t\t$('.odometer.id-fb7efaa').appear(function () {\r\n\t\t\t\t\t\t$(this).each(function () {\r\n\t\t\t\t\t\t\tvar countNumber = 60.5;\r\n\t\t\t\t\t\t\t$(this).html(countNumber);\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t});\r\n\t\t\t\t}, delay);\r\n\t\t\t});\r\n\r\n\t\t<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6056afc e-con-full e-flex e-con e-parent\" data-id=\"6056afc\" data-element_type=\"container\" data-e-type=\"container\" id=\"projects\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53a6d813 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"53a6d813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1 center  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Our Featured Projects<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"1\" data-delay=\"0.06\">Our Project Excellence<\/h2>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3be32f90 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-ajax-post-load\" data-id=\"3be32f90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ajax-post-load.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div id=\"rs-unique-slider-id_3be32f90\" class=\"rsaddon-unique-slider rs-ajax-post-load-parent \">\n\n                                <div class=\"rs-ajax-filter\" data-post-type=\"portfolios\" >\n                                            <button data-category=\"commercial, construction, industrial, residential\" class=\"active\">All Projects<\/button>\n                        <button data-category=\"commercial\">Commercial (04)<\/button><button data-category=\"construction\">Construction (04)<\/button><button data-category=\"industrial\">Industrial (04)<\/button><button data-category=\"residential\">Residential (04)<\/button>                <\/div>\n            \n                <div class=\"swiper addon-slider-id_3be32f90 style-1 rs-addon-slider rs-ajax-post-load\" dir=\"ltr\">\n        \n            <div class=\"layout-cls swiper-wrapper\" data-settings=\"{&quot;style&quot;:&quot;style-1&quot;,&quot;layout&quot;:&quot;slider&quot;,&quot;post_type&quot;:&quot;portfolios&quot;,&quot;show_category&quot;:&quot;&quot;,&quot;category&quot;:&quot;commercial, construction, industrial, residential&quot;,&quot;order&quot;:&quot;ASC&quot;,&quot;per_page&quot;:&quot;&quot;,&quot;initial_load_count&quot;:10,&quot;paged&quot;:1,&quot;unique_id&quot;:&quot;id_3be32f90&quot;,&quot;post_title_tag&quot;:&quot;h4&quot;,&quot;show_excerpt&quot;:&quot;yes&quot;,&quot;excerpt_expand&quot;:&quot;yes&quot;,&quot;excerpt_word&quot;:10,&quot;grid_cols&quot;:&quot;swiper-slide&quot;,&quot;show_read_more&quot;:&quot;yes&quot;,&quot;read_more_text&quot;:&quot;More Details&quot;,&quot;read_more_icon&quot;:{&quot;value&quot;:{&quot;id&quot;:&quot;23&quot;,&quot;url&quot;:&quot;https:\\\/\\\/demo.rstheme.com\\\/wordpress\\\/brickz\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/button-arrow-all.svg&quot;},&quot;library&quot;:&quot;svg&quot;}}\">\n                <div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_1.jpg\" class=\"attachment-full size-full\" alt=\"project_1\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_1.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_1-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_1-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/sustainable-pathway\/\">Sustainable Pathway<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/sustainable-pathway\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_2.jpg\" class=\"attachment-full size-full\" alt=\"project_2\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_2.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_2-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_2-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/green-view-housing\/\">Green View Housing<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/green-view-housing\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_3.jpg\" class=\"attachment-full size-full\" alt=\"project_3\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_3.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_3-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_3-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/sunrise-residency\/\">Sunrise Residency<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/sunrise-residency\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_4.jpg\" class=\"attachment-full size-full\" alt=\"project_4\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_4.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_4-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_4-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/harmony-homes\/\">Harmony Homes<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/harmony-homes\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_5.jpg\" class=\"attachment-full size-full\" alt=\"project_5\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_5.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_5-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_5-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/oceanview-residences-2-2-2-2\/\">Oceanview Residences<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/oceanview-residences-2-2-2-2\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_6.jpg\" class=\"attachment-full size-full\" alt=\"project_6\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_6.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_6-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_6-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/progress-corridor\/\">Progress Corridor<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/progress-corridor\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_7.jpg\" class=\"attachment-full size-full\" alt=\"project_7\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_7.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_7-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_7-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/shapla-housing\/\">Shapla Housing<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/shapla-housing\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_9.jpg\" class=\"attachment-full size-full\" alt=\"project_9\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_9.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_9-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_9-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/eco-build-initiative\/\">Eco Build Initiative<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/eco-build-initiative\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_8.jpg\" class=\"attachment-full size-full\" alt=\"project_8\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_8.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_8-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_8-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/solid-foundation\/\">Solid Foundation<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/solid-foundation\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"grid-item swiper-slide \" >\r\n    <div class=\"post-wrapper\">\r\n                    <div class=\"post-img\">\r\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"889\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_10.jpg\" class=\"attachment-full size-full\" alt=\"project_10\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_10.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_10-259x300.jpg 259w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/project_10-600x695.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>            <\/div>\r\n            <div class=\"post-content\">\r\n                                <h4 class=\"post-title\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/integrity-build\/\">Integrity Build<\/a><\/h4>\r\n                <div class=\"post-excerpt expand-effect\">This proje...<\/div>                    <div class=\"btn-part\">\r\n                        <a class=\"anim-dir-angle\" href=\"https:\/\/warehousetentpro.com\/index.php\/portfolios\/integrity-build\/\">\r\n                            More Details \r\n                                <em>\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>                                <\/em>\r\n                                                    <\/a>\r\n                    <\/div>\r\n                \t\t\t\t            <\/div>\r\n            <\/div>\r\n<\/div>            <\/div><!-- .row\/.swiper-wrapper -->\n\n            <div class=\"button-wrapper d-none\">\n                <button\n                    class=\"rs-loadmore-btn\"\n                    data-category=\"commercial, construction, industrial, residential\">\n                                    <\/button>\n            <\/div>\n        <\/div><!-- .rs-ajax-post-load -->\n\n                            <div class=\"rsaddon-slider-conf d-none\" data-conf=\"{&quot;slidesToShow&quot;:&quot;3&quot;,&quot;spaceBetween&quot;:0,&quot;spaceBetweenLg&quot;:0,&quot;spaceBetweenMd&quot;:0,&quot;spaceBetweenSm&quot;:0,&quot;spaceBetweenXs&quot;:0,&quot;sliderSpeed&quot;:500,&quot;interval&quot;:3000,&quot;slidesToScroll&quot;:2,&quot;slider_autoplay&quot;:&quot;true&quot;,&quot;pauseOnHover&quot;:&quot;false&quot;,&quot;sliderNav&quot;:&quot;false&quot;,&quot;infinite&quot;:&quot;true&quot;,&quot;centerMode&quot;:&quot;false&quot;,&quot;col_desktop&quot;:&quot;4&quot;,&quot;col_lg&quot;:&quot;3&quot;,&quot;col_md&quot;:3,&quot;col_sm&quot;:2,&quot;col_xs&quot;:1,&quot;freeMode&quot;:&quot;false&quot;,&quot;grabCursor&quot;:&quot;false&quot;,&quot;mousewheel&quot;:&quot;false&quot;,&quot;autoHeight&quot;:&quot;false&quot;,&quot;verticalMode&quot;:&quot;horizontal&quot;,&quot;verticalModeLg&quot;:&quot;horizontal&quot;,&quot;verticalModeMd&quot;:&quot;horizontal&quot;,&quot;verticalModeSm&quot;:&quot;horizontal&quot;,&quot;verticalModeXs&quot;:&quot;horizontal&quot;,&quot;keyboardControl&quot;:&quot;false&quot;,&quot;slideEffect&quot;:&quot;&quot;,&quot;initialSlide&quot;:0}\"><\/div>\n            \n        <\/div><!-- .rsaddon-unique-slider -->\n\n                    <script>\n                jQuery(document).ready(function($) {\n                    $('#rs-unique-slider-id_3be32f90').each(function() {\n\n                        var $slider = $(this);\n                        var dataConf = $slider.find('.rsaddon-slider-conf').attr('data-conf');\n                        var slider_conf = JSON.parse(dataConf);\n                        if (slider_conf) {\n                            const progressCircle = $slider.find(\".autoplay-progress svg\")[0];\n                            const progressContent = $slider.find(\".autoplay-progress span\")[0];\n                            var swiper_id_3be32f90 = new Swiper(\".addon-slider-id_3be32f90\", {\n                                slidesPerView: slider_conf.col_desktop,\n                                speed: parseInt(slider_conf.sliderSpeed),\n                                slidesPerGroup: parseInt(slider_conf.slidesToScroll),\n                                spaceBetween: parseInt(slider_conf.spaceBetween),\n                                initialSlide: parseInt(slider_conf.initialSlide),\n                                loop: slider_conf.infinite === 'true' ? true : false,\n                                freeMode: slider_conf.freeMode === 'true' ? true : false,\n                                direction: slider_conf.verticalMode,\n                                grabCursor: slider_conf.grabCursor === 'true' ? true : false,\n                                mousewheel: slider_conf.mousewheel === 'true' ? true : false,\n                                autoHeight: slider_conf.autoHeight === 'true' ? true : false,\n                                centeredSlides: slider_conf.centerMode === 'true' ? true : false,\n                                rtl: false,\n                                effect: slider_conf.slideEffect, \/\/ 'fade', cube', 'coverflow', 'flip', 'cards', 'creative'\n                                keyboard: {\n                                    enabled: slider_conf.keyboardControl === 'true' ? true : false,\n                                },\n                                navigation: {\n                                    nextEl: $slider.find(\".swiper-button-next\")[0],\n                                    prevEl: $slider.find(\".swiper-button-prev\")[0],\n                                },\n                                scrollbar: {\n                                    el: $slider.find(\".swiper-scrollbar\")[0],\n                                    hide: false,\n                                    draggable: true,\n                                },\n                                                                    autoplay: {\n                                        delay: parseInt(slider_conf.interval),\n                                        disableOnInteraction: false,\n                                    },\n                                    \n                                \n                                breakpoints: {\n                                    100: {\n                                        slidesPerView: slider_conf.col_xs,\n                                        spaceBetween: parseInt(slider_conf.spaceBetweenXs),\n                                        direction: slider_conf.verticalModeXs,\n                                    },\n                                    576: {\n                                        slidesPerView: slider_conf.col_sm,\n                                        spaceBetween: parseInt(slider_conf.spaceBetweenSm),\n                                        direction: slider_conf.verticalModeSm,\n                                    },\n                                    768: {\n                                        slidesPerView: slider_conf.col_md,\n                                        spaceBetween: parseInt(slider_conf.spaceBetweenMd),\n                                        direction: slider_conf.verticalModeMd,\n                                    },\n                                    992: {\n                                        slidesPerView: slider_conf.col_lg,\n                                        spaceBetween: parseInt(slider_conf.spaceBetweenLg),\n                                        direction: slider_conf.verticalModeLg,\n                                    },\n                                    1200: {\n                                        slidesPerView: slider_conf.col_desktop,\n                                        spaceBetween: parseInt(slider_conf.spaceBetween),\n                                        direction: slider_conf.verticalMode,\n                                    },\n                                },\n                            });\n                            \n                            $(document).on('rsAjaxPostLoadFilter_id_3be32f90', function () {\n                                if (swiper_id_3be32f90) {\n                                    swiper_id_3be32f90.slideTo(0, 0);\n                                    swiper_id_3be32f90.updateSlides();\n                                    swiper_id_3be32f90.update();\n                                }\n                            });\n                        }\n                    });\n                                    });\n            <\/script>\n                    <script>\n                jQuery(document).ready(function($) {\n                    const $container = $('#rs-unique-slider-id_3be32f90 .rs-ajax-post-load');\n\n                    function hoverHandel() {\n                        let item = $container.find('.grid-item').not('[data-init]');\n                        item.each(function () {\n                            let desc = $(this).find('.post-excerpt.expand-effect');\n                            let descHeight = desc.innerHeight();\n                            desc.css({\n                                '--desc-height': descHeight + 'px',\n                                'height': 0\n                            });\n\n                            if ($(this).parent('.layout-cls.row').length) {\n                                $(this).on('mouseenter.rsHover', function () {\n                                    $(this)\n                                        .addClass('active')\n                                        .siblings('.grid-item')\n                                        .removeClass('active');\n                                });\n                            }\n                            if ($(this).parent('.layout-cls.swiper-wrapper').length) {\n                                $(this).on('mouseenter.rsHover', function () {\n                                    $(this)\n                                        .addClass('swiper-slide-active')\n                                        .siblings('.grid-item')\n                                        .removeClass('swiper-slide-active');\n                                });\n                            }\n                            $(this).attr('data-init', '1');\n                        });\n                    }\n                    hoverHandel();\n\n                    $(document).on('rsAjaxPostLoadFilter_id_3be32f90', function () {\n                        hoverHandel();\n                    });\n                    $(document).on('rsAjaxPostLoadMoreBtn_id_3be32f90', function () {\n                        hoverHandel();\n                    });\n                });\n            <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49f234f e-flex e-con-boxed e-con e-child\" data-id=\"49f234f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13adf25 elementor-widget__width-auto gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"13adf25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle2\">\r\n\r\n\t\t\t\t\t\t\t            <div class=\"address-icon icon_1 elementor-repeater-item-a863b1d\">\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"6\" height=\"11\" viewBox=\"0 0 6 11\" fill=\"none\"><path d=\"M0.50204 0.439454C0.811629 0.16438 1.28548 0.192407 1.56063 0.501954L5.56063 5.00195C5.81308 5.28608 5.81308 5.71392 5.56063 5.99805L1.56063 10.498C1.28548 10.8076 0.811629 10.8356 0.50204 10.5605C0.192493 10.2854 0.164466 9.81154 0.43954 9.50195L3.99618 5.5L0.43954 1.49805C0.164466 1.18846 0.192493 0.714606 0.50204 0.439454Z\" fill=\"#AB052D\"><\/path><\/svg>\t\t            <\/div>\r\n\t\t            \r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"des\">\r\n\t\t\t\t\t\t\t\t\t\t\tFacing Obstacles in Construction Project?\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c643f8 elementor-widget__width-auto gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"9c643f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle2\">\r\n\r\n\t\t\t\t\t\r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\t\t\t\t\t\t\t<div class=\"text\">\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/projects\/\" >\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"des\">\r\n\t\t\t\t\t\t\t\t\t\t\t\tView All Projects\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4cd2ec6e e-flex e-con-boxed e-con e-parent\" data-id=\"4cd2ec6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74e1699b gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"74e1699b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1 center  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Our flexible pricing plan<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"1\" data-delay=\"0.06\">Affordable  Solutions For Every Project<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Read and update the latest news from us. donec eu magna quis felis.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7465e338 elementor-widget__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-pricing-switcher\" data-id=\"7465e338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-pricing-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"rs-pricing-switcher style-3  btn-1     uni-528532\">\n                <div class=\"row\">\n                                            <div class=\"col-lg-4 col-sm-6 elementor-repeater-item-0054641\">\r\n    <div class=\"pricing-item monthly \">\r\n              \r\n        <div class=\"title-wrapper\">\r\n            <h3 class=\"title\">Basic Plan<\/h3>\r\n                    <\/div>\r\n        <div class=\"price-wrapper\">\r\n            <div class=\"price\">\r\n                $49            <\/div>\r\n                            <div class=\"plan-duration\">\r\n                    \/Monthly                <\/div>\r\n                    <\/div>\r\n                    <div class=\"price-description\">Provide the best services, ensurin undibo outstanding growth ipsum topmin.<\/div>\r\n                    <div class=\"pricing-btn  btn-row\">\r\n                                    <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/appointment\/\" class=\"anim-dir-angle\" >\r\n                        Choose your plan<em><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><\/em>                    <\/a>\r\n                            <\/div>\r\n                    <div class=\"pricing-feature\">\r\n                                <ul><li>Business Plan Creation<\/li><li>Cost Efficiency Audits<\/li><li>24\/7 Support at Andy Time<\/li><li>Power and Predictive Dialing<\/li><li class=\"close\" style=\"opacity: 0.6\">Profitability Optimization<\/li><li class=\"close\" style=\"opacity: 0.6\">Customizable Platform<\/li><\/ul>            <\/div>\r\n            <\/div>\r\n    <div class=\"pricing-item yearly \">\r\n                <div class=\"title-wrapper\">\r\n            <h3 class=\"title\">Basic Plan<\/h3>\r\n                    <\/div>\r\n        <div class=\"price-wrapper\">\r\n            <div class=\"price\">\r\n                $249            <\/div>\r\n                            <div class=\"plan-duration\">\r\n                    \/Yearly                <\/div>\r\n                    <\/div>\r\n                    <div class=\"price-description\">It could relate to a subscription service insurance, mobile plan.<\/div>\r\n                    <div class=\"pricing-btn  btn-row\">\r\n                                    <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/contact\/\" class=\"anim-dir-angle\" >\r\n                        Choose your plan<em><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><\/em>                    <\/a>\r\n                            <\/div>\r\n                    <div class=\"pricing-feature\">\r\n                                <ul><li>All analytics features<\/li><li>Upgrade Anytime Protection<\/li><li class=\"close\">40 Days Product Testing<\/li><li class=\"close\">500 Malware Removal<\/li><li>24\/7 Live Assistance<\/li><\/ul>            <\/div>\r\n                \r\n            <\/div>\r\n<\/div>                                            <div class=\"col-lg-4 col-sm-6 elementor-repeater-item-0f11314\">\r\n    <div class=\"pricing-item monthly item-active\">\r\n              \r\n        <div class=\"title-wrapper\">\r\n            <h3 class=\"title\">Business Plan<\/h3>\r\n                    <\/div>\r\n        <div class=\"price-wrapper\">\r\n            <div class=\"price\">\r\n                $69            <\/div>\r\n                            <div class=\"plan-duration\">\r\n                    \/Monthly                <\/div>\r\n                    <\/div>\r\n                    <div class=\"price-description\">Provide the best services, ensurin undibo outstanding growth ipsum topmin.<\/div>\r\n                    <div class=\"pricing-btn  btn-row\">\r\n                                    <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/contact\/\" class=\"anim-dir-angle\" >\r\n                        Choose your plan<em><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><\/em>                    <\/a>\r\n                            <\/div>\r\n                    <div class=\"pricing-feature\">\r\n                                <ul><li>Business Plan Creation<\/li><li>Cost Efficiency Audits<\/li><li>24\/7 Support at Andy Time<\/li><li>Power and Predictive Dialing<\/li><li class=\"close\" style=\"opacity: 0.6\">Profitability Optimization<\/li><li class=\"close\" style=\"opacity: 0.6\">Customizable Platform<\/li><\/ul>            <\/div>\r\n            <\/div>\r\n    <div class=\"pricing-item yearly item-active\">\r\n                <div class=\"title-wrapper\">\r\n            <h3 class=\"title\">Business Plan<\/h3>\r\n                    <\/div>\r\n        <div class=\"price-wrapper\">\r\n            <div class=\"price\">\r\n                $469            <\/div>\r\n                            <div class=\"plan-duration\">\r\n                    \/Yearly                <\/div>\r\n                    <\/div>\r\n                    <div class=\"price-description\">It could relate to a subscription service insurance, mobile plan.<\/div>\r\n                    <div class=\"pricing-btn  btn-row\">\r\n                                    <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/appointment\/\" class=\"anim-dir-angle\" >\r\n                        Choose your plan<em><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><\/em>                    <\/a>\r\n                            <\/div>\r\n                    <div class=\"pricing-feature\">\r\n                                <ul><li>All analytics features<\/li><li>Upgrade Anytime Protection<\/li><li class=\"close\">40 Days Product Testing<\/li><li class=\"close\">500 Malware Removal<\/li><li>24\/7 Live Assistance<\/li><\/ul>            <\/div>\r\n                \r\n            <\/div>\r\n<\/div>                                            <div class=\"col-lg-4 col-sm-6 elementor-repeater-item-aa42e15\">\r\n    <div class=\"pricing-item monthly \">\r\n              \r\n        <div class=\"title-wrapper\">\r\n            <h3 class=\"title\">Premium Plan<\/h3>\r\n                    <\/div>\r\n        <div class=\"price-wrapper\">\r\n            <div class=\"price\">\r\n                $99            <\/div>\r\n                            <div class=\"plan-duration\">\r\n                    \/Monthly                <\/div>\r\n                    <\/div>\r\n                    <div class=\"price-description\">Provide the best services, ensurin undibo outstanding growth ipsum topmin.<\/div>\r\n                    <div class=\"pricing-btn  btn-row\">\r\n                                    <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/contact\/\" class=\"anim-dir-angle\" >\r\n                        Choose your plan<em><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><\/em>                    <\/a>\r\n                            <\/div>\r\n                    <div class=\"pricing-feature\">\r\n                                <ul><li>Business Plan Creation<\/li><li>Cost Efficiency Audits<\/li><li>24\/7 Support at Andy Time<\/li><li>Power and Predictive Dialing<\/li><li class=\"close\" style=\"opacity: 0.6\">Profitability Optimization<\/li><li class=\"close\" style=\"opacity: 0.6\">Customizable Platform<\/li><\/ul>            <\/div>\r\n            <\/div>\r\n    <div class=\"pricing-item yearly \">\r\n                <div class=\"title-wrapper\">\r\n            <h3 class=\"title\">Premium Plan<\/h3>\r\n                    <\/div>\r\n        <div class=\"price-wrapper\">\r\n            <div class=\"price\">\r\n                $999            <\/div>\r\n                            <div class=\"plan-duration\">\r\n                    \/Yearly                <\/div>\r\n                    <\/div>\r\n                    <div class=\"price-description\">It could relate to a subscription service insurance, mobile plan.<\/div>\r\n                    <div class=\"pricing-btn  btn-row\">\r\n                                    <a href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/appointment\/\" class=\"anim-dir-angle\" >\r\n                        Choose your plan<em><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg><\/em>                    <\/a>\r\n                            <\/div>\r\n                    <div class=\"pricing-feature\">\r\n                                <ul><li>All analytics features<\/li><li>Upgrade Anytime Protection<\/li><li class=\"close\">40 Days Product Testing<\/li><li class=\"close\">500 Malware Removal<\/li><li>24\/7 Live Assistance<\/li><\/ul>            <\/div>\r\n                \r\n            <\/div>\r\n<\/div>                    <\/div>\n    <\/div>\n    <script>\n        jQuery(function($) {\n            var timeoutValue = 50;\n            $('.pricing-switcher-wrapper.uni-528532 span').click(function() {\n                $('.rs-pricing-switcher.uni-528532').toggleClass('switched');\n\n                            });\n\n                    });\n    <\/script>\n        \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-184017a0 e-flex e-con-boxed e-con e-parent\" data-id=\"184017a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5aedbc05 e-con-full e-flex e-con e-child\" data-id=\"5aedbc05\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-39df7418 e-con-full e-flex e-con e-child\" data-id=\"39df7418\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d56b8ae gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"7d56b8ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1 left  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Our Clients Testimonials<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-left \" data-split-type=\"words\" data-duration=\"0.8\" data-delay=\"0.06\">What Our Customers Say?<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Find answers to our question about our consulting coverage options.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-363dda3b e-con-full e-flex e-con e-child\" data-id=\"363dda3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50ed8daa gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-counter\" data-id=\"50ed8daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"counter-top-area\">\r\n\t\t\t\t<div class=\"rs-counter-list\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"count-text\">\r\n\t\t\t\t\t\t<div class=\"count-number\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"id-50ed8daa rs-counter odometer\">98<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"prefix\">\r\n\t\t\t\t\t\t\t\t\t%\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"title\">Customers Satisfaction<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\tvar delay = 0;\r\n\t\t\t\tsetTimeout(function() {\r\n\t\t\t\t\t$(\".odometer.id-50ed8daa\").each(function () {\r\n\t\t\t\t\t\tvar countNumber = 98;\r\n\t\t\t\t\t\tcountNumber = countNumber.toString();\r\n\t\t\t\t\t\tvar digits = countNumber.length;\r\n\t\t\t\t\t\tvar zeros = \"0\".repeat(digits);\r\n\t\t\t\t\t\t$(this).html(zeros);\r\n\t\t\t\t\t});\r\n\t\t\t\t\r\n\t\t\t\t\t$('.odometer.id-50ed8daa').appear(function () {\r\n\t\t\t\t\t\t$(this).each(function () {\r\n\t\t\t\t\t\t\tvar countNumber = 98;\r\n\t\t\t\t\t\t\t$(this).html(countNumber);\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t});\r\n\t\t\t\t}, delay);\r\n\t\t\t});\r\n\r\n\t\t<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fc8058a e-con-full e-flex e-con e-child\" data-id=\"1fc8058a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-51c732f9 e-con-full e-flex e-con e-child\" data-id=\"51c732f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29e23023 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-image\" data-id=\"29e23023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n\n\n        <div class=\"rs-image      \" >\n\n\n                                                        <img decoding=\"async\" class=\"rs-multi-image  reverse- blend_unset\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/image0022.jpg\" alt=\"image0022\"\/>\n                                <\/div>   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78798857 e-con-full e-flex e-con e-child\" data-id=\"78798857\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43c1323a gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-testimonial-slider\" data-id=\"43c1323a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-testimonial-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div id=\"rs-unique-slider-31751\" class=\"rsaddon-unique-slider   slick-dots- \">\r\n            <div class=\"swiper addon-slider-31751 rs-addon-slider rs-testimonial-slider style1   \" dir=\"ltr\">\r\n                    <div class=\"swiper-wrapper\">\r\n                <div class=\"grid-item swiper-slide\">\r\n    <div class=\"testimonial-inner\">\r\n        <div class=\"quote_icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"44\" viewBox=\"0 0 60 44\" fill=\"none\"><path d=\"M12.7244 28.0195C11.6004 34.2343 9.70513 38.7081 8.20652 41.485C7.61148 42.5648 8.82362 43.777 9.88146 43.1599C22.4434 35.8431 27.953 25.1765 28.6362 16.6036C29.2312 9.22068 24.1844 1.61742 16.5591 0.229C8.9338 -1.15942 1.61704 3.90943 0.228614 11.5347C-1.22592 19.5347 4.41591 27.2261 12.7244 28.0195Z\" fill=\"#3D4C57\"><\/path><path d=\"M44.0406 28.0195C42.9166 34.2343 41.0213 38.7081 39.5227 41.485C38.9277 42.5648 40.1398 43.777 41.1976 43.1599C53.7595 35.8431 59.2692 25.1765 59.9524 16.6036C60.5474 9.22068 55.5006 1.61742 47.8753 0.229C40.25 -1.15942 32.9332 3.90943 31.5448 11.5347C30.0902 19.5347 35.7321 27.2261 44.0406 28.0195Z\" fill=\"#3D4C57\"><\/path><\/svg>        <\/div>\r\n                            <div class=\"ratings\">\r\n                <span class=\"rating-count\">5<\/span>\r\n                <i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i>            <\/div>\r\n                 \r\n            <h4 class=\"title\">Business Strategy<\/h4>\r\n                <div class=\"descripti\">\r\n            \u201cThe standard chunk of Lorem Ipsum used since the 1500s is reproduced below for those interested, Bonorum Malorum Cicero are also their exact original form, accompanied by English versions.\u201d        <\/div>\r\n        <div class=\"testi-card-bottom \">\r\n                        <div class=\"content-part\">\r\n                <h5 class=\"name\">Abdur Rashid<\/h5>\r\n                <div class=\"testi-designation\">Founder &amp; CEO<\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"grid-item swiper-slide\">\r\n    <div class=\"testimonial-inner\">\r\n        <div class=\"quote_icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"44\" viewBox=\"0 0 60 44\" fill=\"none\"><path d=\"M12.7244 28.0195C11.6004 34.2343 9.70513 38.7081 8.20652 41.485C7.61148 42.5648 8.82362 43.777 9.88146 43.1599C22.4434 35.8431 27.953 25.1765 28.6362 16.6036C29.2312 9.22068 24.1844 1.61742 16.5591 0.229C8.9338 -1.15942 1.61704 3.90943 0.228614 11.5347C-1.22592 19.5347 4.41591 27.2261 12.7244 28.0195Z\" fill=\"#3D4C57\"><\/path><path d=\"M44.0406 28.0195C42.9166 34.2343 41.0213 38.7081 39.5227 41.485C38.9277 42.5648 40.1398 43.777 41.1976 43.1599C53.7595 35.8431 59.2692 25.1765 59.9524 16.6036C60.5474 9.22068 55.5006 1.61742 47.8753 0.229C40.25 -1.15942 32.9332 3.90943 31.5448 11.5347C30.0902 19.5347 35.7321 27.2261 44.0406 28.0195Z\" fill=\"#3D4C57\"><\/path><\/svg>        <\/div>\r\n                            <div class=\"ratings\">\r\n                <span class=\"rating-count\">5<\/span>\r\n                <i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i>            <\/div>\r\n                 \r\n            <h4 class=\"title\">Business Strategy<\/h4>\r\n                <div class=\"descripti\">\r\n            \u201cThe standard chunk of Lorem Ipsum used since the 1500s is reproduced below for those interested, Bonorum Malorum Cicero are also their exact original form, accompanied by English versions.\u201d        <\/div>\r\n        <div class=\"testi-card-bottom \">\r\n                        <div class=\"content-part\">\r\n                <h5 class=\"name\">Ronald Richards<\/h5>\r\n                <div class=\"testi-designation\">Project Manager<\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"grid-item swiper-slide\">\r\n    <div class=\"testimonial-inner\">\r\n        <div class=\"quote_icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"44\" viewBox=\"0 0 60 44\" fill=\"none\"><path d=\"M12.7244 28.0195C11.6004 34.2343 9.70513 38.7081 8.20652 41.485C7.61148 42.5648 8.82362 43.777 9.88146 43.1599C22.4434 35.8431 27.953 25.1765 28.6362 16.6036C29.2312 9.22068 24.1844 1.61742 16.5591 0.229C8.9338 -1.15942 1.61704 3.90943 0.228614 11.5347C-1.22592 19.5347 4.41591 27.2261 12.7244 28.0195Z\" fill=\"#3D4C57\"><\/path><path d=\"M44.0406 28.0195C42.9166 34.2343 41.0213 38.7081 39.5227 41.485C38.9277 42.5648 40.1398 43.777 41.1976 43.1599C53.7595 35.8431 59.2692 25.1765 59.9524 16.6036C60.5474 9.22068 55.5006 1.61742 47.8753 0.229C40.25 -1.15942 32.9332 3.90943 31.5448 11.5347C30.0902 19.5347 35.7321 27.2261 44.0406 28.0195Z\" fill=\"#3D4C57\"><\/path><\/svg>        <\/div>\r\n                            <div class=\"ratings\">\r\n                <span class=\"rating-count\">5<\/span>\r\n                <i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i>            <\/div>\r\n                 \r\n            <h4 class=\"title\">Business Strategy<\/h4>\r\n                <div class=\"descripti\">\r\n            \u201cThe standard chunk of Lorem Ipsum used since the 1500s is reproduced below for those interested, Bonorum Malorum Cicero are also their exact original form, accompanied by English versions.\u201d        <\/div>\r\n        <div class=\"testi-card-bottom \">\r\n                        <div class=\"content-part\">\r\n                <h5 class=\"name\">Leslie Alexander<\/h5>\r\n                <div class=\"testi-designation\">President of Sales<\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"grid-item swiper-slide\">\r\n    <div class=\"testimonial-inner\">\r\n        <div class=\"quote_icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"44\" viewBox=\"0 0 60 44\" fill=\"none\"><path d=\"M12.7244 28.0195C11.6004 34.2343 9.70513 38.7081 8.20652 41.485C7.61148 42.5648 8.82362 43.777 9.88146 43.1599C22.4434 35.8431 27.953 25.1765 28.6362 16.6036C29.2312 9.22068 24.1844 1.61742 16.5591 0.229C8.9338 -1.15942 1.61704 3.90943 0.228614 11.5347C-1.22592 19.5347 4.41591 27.2261 12.7244 28.0195Z\" fill=\"#3D4C57\"><\/path><path d=\"M44.0406 28.0195C42.9166 34.2343 41.0213 38.7081 39.5227 41.485C38.9277 42.5648 40.1398 43.777 41.1976 43.1599C53.7595 35.8431 59.2692 25.1765 59.9524 16.6036C60.5474 9.22068 55.5006 1.61742 47.8753 0.229C40.25 -1.15942 32.9332 3.90943 31.5448 11.5347C30.0902 19.5347 35.7321 27.2261 44.0406 28.0195Z\" fill=\"#3D4C57\"><\/path><\/svg>        <\/div>\r\n                            <div class=\"ratings\">\r\n                <span class=\"rating-count\">5<\/span>\r\n                <i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i>            <\/div>\r\n                 \r\n            <h4 class=\"title\">Business Strategy<\/h4>\r\n                <div class=\"descripti\">\r\n            \u201cThe standard chunk of Lorem Ipsum used since the 1500s is reproduced below for those interested, Bonorum Malorum Cicero are also their exact original form, accompanied by English versions.\u201d        <\/div>\r\n        <div class=\"testi-card-bottom \">\r\n                        <div class=\"content-part\">\r\n                <h5 class=\"name\">Savannah Nguyen<\/h5>\r\n                <div class=\"testi-designation\">Software Tester<\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"grid-item swiper-slide\">\r\n    <div class=\"testimonial-inner\">\r\n        <div class=\"quote_icon\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"44\" viewBox=\"0 0 60 44\" fill=\"none\"><path d=\"M12.7244 28.0195C11.6004 34.2343 9.70513 38.7081 8.20652 41.485C7.61148 42.5648 8.82362 43.777 9.88146 43.1599C22.4434 35.8431 27.953 25.1765 28.6362 16.6036C29.2312 9.22068 24.1844 1.61742 16.5591 0.229C8.9338 -1.15942 1.61704 3.90943 0.228614 11.5347C-1.22592 19.5347 4.41591 27.2261 12.7244 28.0195Z\" fill=\"#3D4C57\"><\/path><path d=\"M44.0406 28.0195C42.9166 34.2343 41.0213 38.7081 39.5227 41.485C38.9277 42.5648 40.1398 43.777 41.1976 43.1599C53.7595 35.8431 59.2692 25.1765 59.9524 16.6036C60.5474 9.22068 55.5006 1.61742 47.8753 0.229C40.25 -1.15942 32.9332 3.90943 31.5448 11.5347C30.0902 19.5347 35.7321 27.2261 44.0406 28.0195Z\" fill=\"#3D4C57\"><\/path><\/svg>        <\/div>\r\n                            <div class=\"ratings\">\r\n                <span class=\"rating-count\">5<\/span>\r\n                <i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i><i class=\"ri-star-fill\"><\/i>            <\/div>\r\n                 \r\n            <h4 class=\"title\">Business Strategy<\/h4>\r\n                <div class=\"descripti\">\r\n            \u201cThe standard chunk of Lorem Ipsum used since the 1500s is reproduced below for those interested, Bonorum Malorum Cicero are also their exact original form, accompanied by English versions.\u201d        <\/div>\r\n        <div class=\"testi-card-bottom \">\r\n                        <div class=\"content-part\">\r\n                <h5 class=\"name\">Marry Holder<\/h5>\r\n                <div class=\"testi-designation\">HR Manager<\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>            <\/div>\r\n        <\/div>\r\n                                    <div class=\"swiper-button-prev\"><\/div>\r\n                <div class=\"swiper-button-next\"><\/div>\r\n                    <div class=\"rsaddon-slider-conf d-none\" data-conf=\"{&quot;slidesToShow&quot;:&quot;1&quot;,&quot;spaceBetween&quot;:30,&quot;spaceBetweenLg&quot;:30,&quot;spaceBetweenMd&quot;:30,&quot;spaceBetweenSm&quot;:30,&quot;spaceBetweenXs&quot;:10,&quot;sliderSpeed&quot;:500,&quot;interval&quot;:&quot;3500&quot;,&quot;slidesToScroll&quot;:&quot;1&quot;,&quot;slider_autoplay&quot;:&quot;true&quot;,&quot;pauseOnHover&quot;:&quot;false&quot;,&quot;sliderDots&quot;:&quot;false&quot;,&quot;sliderNav&quot;:&quot;true&quot;,&quot;infinite&quot;:&quot;true&quot;,&quot;centerMode&quot;:&quot;false&quot;,&quot;col_desktop&quot;:&quot;1&quot;,&quot;col_lg&quot;:&quot;1&quot;,&quot;col_md&quot;:&quot;1&quot;,&quot;col_sm&quot;:&quot;1&quot;,&quot;col_xs&quot;:1,&quot;freeMode&quot;:&quot;false&quot;,&quot;grabCursor&quot;:&quot;false&quot;,&quot;mousewheel&quot;:&quot;false&quot;,&quot;autoHeight&quot;:&quot;false&quot;,&quot;verticalMode&quot;:&quot;horizontal&quot;,&quot;verticalModeLg&quot;:&quot;horizontal&quot;,&quot;verticalModeMd&quot;:&quot;horizontal&quot;,&quot;verticalModeSm&quot;:&quot;horizontal&quot;,&quot;verticalModeXs&quot;:&quot;horizontal&quot;,&quot;keyboardControl&quot;:&quot;false&quot;,&quot;dynamicBullets&quot;:&quot;false&quot;,&quot;bulletType&quot;:&quot;&quot;,&quot;slideEffect&quot;:&quot;&quot;,&quot;initialSlide&quot;:0}\"><\/div>\r\n        <\/div>\r\n        <script>\r\n            jQuery(document).ready(function($) {\r\n                $('#rs-unique-slider-31751').each(function() {\r\n                    \r\n                    var $slider = $(this);\r\n                    var dataConf = $slider.find('.rsaddon-slider-conf').attr('data-conf');\r\n                    var slider_conf = JSON.parse(dataConf);\r\n                    if (slider_conf) {\r\n                        const progressCircle = $slider.find(\".autoplay-progress svg\")[0];\r\n                        const progressContent = $slider.find(\".autoplay-progress span\")[0];\r\n                        var swiper = new Swiper(\".addon-slider-31751\", {\r\n                            slidesPerView: slider_conf.col_desktop,\r\n                            speed: parseInt(slider_conf.sliderSpeed),\r\n                            slidesPerGroup: parseInt(slider_conf.slidesToScroll),\r\n                            spaceBetween: parseInt(slider_conf.spaceBetween),\r\n                            initialSlide: parseInt(slider_conf.initialSlide),\r\n                            loop: slider_conf.infinite === 'true' ? true : false,\r\n                            freeMode: slider_conf.freeMode === 'true' ? true : false,\r\n                            direction: slider_conf.verticalMode,\r\n                            grabCursor: slider_conf.grabCursor === 'true' ? true : false,\r\n                            mousewheel: slider_conf.mousewheel === 'true' ? true : false,\r\n                            autoHeight: slider_conf.autoHeight === 'true' ? true : false,\r\n                            centeredSlides: slider_conf.centerMode === 'true' ? true : false,\r\n                            rtl: false,\r\n                            effect: slider_conf.slideEffect, \/\/ 'fade', cube', 'coverflow', 'flip', 'cards', 'creative'\r\n                            keyboard: {\r\n                                enabled: slider_conf.keyboardControl === 'true' ? true : false,\r\n                            },\r\n                            navigation: {\r\n                                nextEl: $slider.find(\".swiper-button-next\")[0],\r\n                                prevEl: $slider.find(\".swiper-button-prev\")[0],\r\n                            },\r\n                            pagination: {\r\n                                el: $slider.find(\".swiper-pagination\")[0],\r\n                                clickable: true,\r\n                                dynamicBullets: slider_conf.dynamicBullets === 'true' ? true : false,\r\n                                                            },\r\n                            scrollbar: {\r\n                                el: $slider.find(\".swiper-scrollbar\")[0],\r\n                                hide: false,\r\n                                draggable: true,\r\n                            },\r\n                                                            autoplay: {\r\n                                    delay: parseInt(slider_conf.interval),\r\n                                    disableOnInteraction: false,\r\n                                                                            reverseDirection: true,\r\n                                                                    },\r\n                                \r\n                                                        \r\n                            breakpoints: {\r\n                                100: {\r\n                                    slidesPerView: slider_conf.col_xs,\r\n                                    spaceBetween: parseInt(slider_conf.spaceBetweenXs),\r\n                                    direction: slider_conf.verticalModeXs,\r\n                                },\r\n                                576: {\r\n                                    slidesPerView: slider_conf.col_sm,\r\n                                    spaceBetween: parseInt(slider_conf.spaceBetweenSm),\r\n                                    direction: slider_conf.verticalModeSm,\r\n                                },\r\n                                768: {\r\n                                    slidesPerView: slider_conf.col_md,\r\n                                    spaceBetween: parseInt(slider_conf.spaceBetweenMd),\r\n                                    direction: slider_conf.verticalModeMd,\r\n                                },\r\n                                992: {\r\n                                    slidesPerView: slider_conf.col_lg,\r\n                                    spaceBetween: parseInt(slider_conf.spaceBetweenLg),\r\n                                    direction: slider_conf.verticalModeLg,\r\n                                },\r\n                                1200: {\r\n                                    slidesPerView: slider_conf.col_desktop,\r\n                                    spaceBetween: parseInt(slider_conf.spaceBetween),\r\n                                    direction: slider_conf.verticalMode,\r\n                                },\r\n                            },\r\n                        });\r\n                                            }\r\n                });\r\n            });\r\n        <\/script>\r\n    \r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ead70ae e-con-full e-flex e-con e-parent\" data-id=\"2ead70ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-55e62fa9 e-con-full e-flex e-con e-child\" data-id=\"55e62fa9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1f6e9a17 e-con-full e-flex e-con e-child\" data-id=\"1f6e9a17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4193eeca gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-logo\" data-id=\"4193eeca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div id=\"rs-unique-slider-235976\" class=\"rsaddon-unique-slider  slick-dots-\">\n            <div class=\"swiper rs-addon-slider rs-logo-slider addon-slider-235976 style1\" dir=\"ltr\">\n                        <div class=\"swiper-wrapper\">\n                    <div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons1.png\" alt=\"ptnr-b-icons1.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons2.png\" alt=\"ptnr-b-icons2.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons3.png\" alt=\"ptnr-b-icons3.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons4.png\" alt=\"ptnr-b-icons4.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons5.png\" alt=\"ptnr-b-icons5.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons6.png\" alt=\"ptnr-b-icons6.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons7.png\" alt=\"ptnr-b-icons7.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons8.png\" alt=\"ptnr-b-icons8.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons9.png\" alt=\"ptnr-b-icons9.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons10.png\" alt=\"ptnr-b-icons10.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons11.png\" alt=\"ptnr-b-icons11.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div><div class=\"logo-item swiper-slide\">\r\n    <a href=\"#\" class=\"logo-item-wrapper\" >\r\n        <div class=\"image-wrapper\">\r\n            <img decoding=\"async\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/ptnr-b-icons12.png\" alt=\"ptnr-b-icons12.png\">\r\n        <\/div>\r\n            <\/a>\r\n<\/div>                <\/div>\n            <\/div> <!-- .rs-logo-slider -->\n                            <style>\n                    .rs-logo-slider.addon-slider-235976 .logo-item-wrapper:hover .image-wrapper img {\n                        animation: slideInUp 500ms ;\n                    }\n                <\/style>\n                            <!-- Sl Controls -->\n                                <div class=\"rsaddon-slider-conf d-none\" data-conf=\"{&quot;slidesToShow&quot;:4,&quot;spaceBetween&quot;:0,&quot;spaceBetweenLg&quot;:0,&quot;spaceBetweenMd&quot;:0,&quot;spaceBetweenSm&quot;:0,&quot;spaceBetweenXs&quot;:10,&quot;sliderSpeed&quot;:500,&quot;interval&quot;:null,&quot;slidesToScroll&quot;:2,&quot;slider_autoplay&quot;:&quot;false&quot;,&quot;pauseOnHover&quot;:&quot;false&quot;,&quot;sliderDots&quot;:&quot;false&quot;,&quot;sliderNav&quot;:&quot;false&quot;,&quot;infinite&quot;:&quot;true&quot;,&quot;centerMode&quot;:&quot;false&quot;,&quot;col_desktop&quot;:&quot;6&quot;,&quot;col_lg&quot;:4,&quot;col_md&quot;:4,&quot;col_sm&quot;:3,&quot;col_xs&quot;:2,&quot;freeMode&quot;:&quot;false&quot;,&quot;grabCursor&quot;:&quot;false&quot;,&quot;mousewheel&quot;:&quot;false&quot;,&quot;autoHeight&quot;:&quot;false&quot;,&quot;verticalMode&quot;:&quot;horizontal&quot;,&quot;verticalModeLg&quot;:&quot;horizontal&quot;,&quot;verticalModeMd&quot;:&quot;horizontal&quot;,&quot;verticalModeSm&quot;:&quot;horizontal&quot;,&quot;verticalModeXs&quot;:&quot;horizontal&quot;,&quot;keyboardControl&quot;:&quot;false&quot;,&quot;dynamicBullets&quot;:&quot;false&quot;,&quot;bulletType&quot;:&quot;&quot;,&quot;slideEffect&quot;:&quot;&quot;,&quot;initialSlide&quot;:0}\"><\/div>\n                            <script>\n                    jQuery(document).ready(function($) {\n                        $('#rs-unique-slider-235976').each(function() {\n                            var $slider = $(this);\n                            var dataConf = $slider.find('.rsaddon-slider-conf').attr('data-conf');\n                            var slider_conf = JSON.parse(dataConf);\n                            if (slider_conf) {\n                                const progressCircle = $slider.find(\".autoplay-progress svg\")[0];\n                                const progressContent = $slider.find(\".autoplay-progress span\")[0];\n                                var swiper = new Swiper(\".addon-slider-235976\", {\n                                    slidesPerView: slider_conf.col_desktop,\n                                    speed: parseInt(slider_conf.sliderSpeed),\n                                    slidesPerGroup: parseInt(slider_conf.slidesToScroll),\n                                    spaceBetween: parseInt(slider_conf.spaceBetween),\n                                    initialSlide: parseInt(slider_conf.initialSlide),\n                                    loop: slider_conf.infinite === 'true' ? true : false,\n                                    freeMode: slider_conf.freeMode === 'true' ? true : false,\n                                    direction: slider_conf.verticalMode,\n                                    grabCursor: slider_conf.grabCursor === 'true' ? true : false,\n                                    mousewheel: slider_conf.mousewheel === 'true' ? true : false,\n                                    autoHeight: slider_conf.autoHeight === 'true' ? true : false,\n                                    centeredSlides: slider_conf.centerMode === 'true' ? true : false,\n                                    rtl: false,\n                                    effect: slider_conf.slideEffect, \/\/ 'fade', cube', 'coverflow', 'flip', 'cards', 'creative'\n                                    keyboard: {\n                                        enabled: slider_conf.keyboardControl === 'true' ? true : false,\n                                    },\n                                    navigation: {\n                                        nextEl: $slider.find(\".swiper-button-next\")[0],\n                                        prevEl: $slider.find(\".swiper-button-prev\")[0],\n                                    },\n                                    pagination: {\n                                        el: $slider.find(\".swiper-pagination\")[0],\n                                        clickable: true,\n                                        dynamicBullets: slider_conf.dynamicBullets === 'true' ? true : false,\n                                                                            },\n                                    scrollbar: {\n                                        el: $slider.find(\".swiper-scrollbar\")[0],\n                                        hide: false,\n                                        draggable: true,\n                                    },\n                                    \n                                                                        \n                                    breakpoints: {\n                                        100: {\n                                            slidesPerView: slider_conf.col_xs,\n                                            spaceBetween: parseInt(slider_conf.spaceBetweenXs),\n                                            direction: slider_conf.verticalModeXs,\n                                        },\n                                        576: {\n                                            slidesPerView: slider_conf.col_sm,\n                                            spaceBetween: parseInt(slider_conf.spaceBetweenSm),\n                                            direction: slider_conf.verticalModeSm,\n                                        },\n                                        768: {\n                                            slidesPerView: slider_conf.col_md,\n                                            spaceBetween: parseInt(slider_conf.spaceBetweenMd),\n                                            direction: slider_conf.verticalModeMd,\n                                        },\n                                        992: {\n                                            slidesPerView: slider_conf.col_lg,\n                                            spaceBetween: parseInt(slider_conf.spaceBetweenLg),\n                                            direction: slider_conf.verticalModeLg,\n                                        },\n                                        1200: {\n                                            slidesPerView: slider_conf.col_desktop,\n                                            spaceBetween: parseInt(slider_conf.spaceBetween),\n                                            direction: slider_conf.verticalMode,\n                                        },\n                                    },\n                                });\n                                                            }\n                        });\n                    });\n                <\/script>\n                    <\/div> <!-- .rsaddon-unique-slider -->\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6856c27 e-flex e-con-boxed e-con e-parent\" data-id=\"6856c27\" data-element_type=\"container\" data-e-type=\"container\" id=\"blog\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5226c3e e-con-full e-flex e-con e-child\" data-id=\"5226c3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95fec15 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"95fec15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1 center  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Read Our Blog & News\n<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-left \" data-split-type=\"words\" data-duration=\"0.8\" data-delay=\"0.06\">Featured News &amp; Insights<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Read and update the latest news from us. donec eu magna quis felis.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f799d06 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-blog-posts\" data-id=\"f799d06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-blog-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div id=\"rs-unique-slider-f799d06\" class=\"rsaddon-unique-slider  \">\r\n\t\t\t<div class=\"rs-blog-posts style-overly swiper\" dir=\"ltr\">\r\n\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t<div class=\"swiper-slide\">\t\t\t<div class=\"blog-post-item\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-thumbnail\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"650\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_06.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_06.jpg 1280w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_06-300x152.jpg 300w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_06-1024x520.jpg 1024w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_06-768x390.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_06-600x305.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>        <div class=\"post-meta on-thumbnail\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/how-sustainable-design-reduces-construction-costs\/\" class=\"meta-date\">\r\n\t\t\t\t\t\t\t\t2025\u5e7412\u670817\u65e5            <\/a>\r\n\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"post-content\">\r\n\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/construction\/\"><i class=\"ri-price-tag-3-line\"><\/i>Construction<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/how-sustainable-design-reduces-construction-costs\/\">How Sustai..<\/a><\/h4>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-content-hover\">\r\n\t\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/construction\/\"><i class=\"ri-price-tag-3-line\"><\/i>Construction<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/how-sustainable-design-reduces-construction-costs\/\">How Sustai..<\/a><\/h4><p class=\"post-excerpt\">Construction...<\/p>        <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/how-sustainable-design-reduces-construction-costs\/\" class=\"post-read-more\">\r\n\t\t\tRead More\t\t\t        <\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div><div class=\"swiper-slide\">\t\t\t<div class=\"blog-post-item\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-thumbnail\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"650\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_05.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_05.jpg 1280w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_05-300x152.jpg 300w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_05-1024x520.jpg 1024w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_05-768x390.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_05-600x305.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>        <div class=\"post-meta on-thumbnail\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/green-construction-building-a-sustainable-future\/\" class=\"meta-date\">\r\n\t\t\t\t\t\t\t\t2025\u5e7412\u670817\u65e5            <\/a>\r\n\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"post-content\">\r\n\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/building\/\"><i class=\"ri-price-tag-3-line\"><\/i>Building<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/green-construction-building-a-sustainable-future\/\">Green Cons..<\/a><\/h4>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-content-hover\">\r\n\t\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/building\/\"><i class=\"ri-price-tag-3-line\"><\/i>Building<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/green-construction-building-a-sustainable-future\/\">Green Cons..<\/a><\/h4><p class=\"post-excerpt\">Digital tool...<\/p>        <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/green-construction-building-a-sustainable-future\/\" class=\"post-read-more\">\r\n\t\t\tRead More\t\t\t        <\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div><div class=\"swiper-slide\">\t\t\t<div class=\"blog-post-item\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-thumbnail\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"650\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_04.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_04.jpg 1280w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_04-300x152.jpg 300w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_04-1024x520.jpg 1024w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_04-768x390.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_04-600x305.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>        <div class=\"post-meta on-thumbnail\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/commercial-construction-trends-to-watch-this-year\/\" class=\"meta-date\">\r\n\t\t\t\t\t\t\t\t2025\u5e7412\u670817\u65e5            <\/a>\r\n\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"post-content\">\r\n\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/commercial\/\"><i class=\"ri-price-tag-3-line\"><\/i>Commercial<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/commercial-construction-trends-to-watch-this-year\/\">Commercial..<\/a><\/h4>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-content-hover\">\r\n\t\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/commercial\/\"><i class=\"ri-price-tag-3-line\"><\/i>Commercial<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/commercial-construction-trends-to-watch-this-year\/\">Commercial..<\/a><\/h4><p class=\"post-excerpt\">One of the b...<\/p>        <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/commercial-construction-trends-to-watch-this-year\/\" class=\"post-read-more\">\r\n\t\t\tRead More\t\t\t        <\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div><div class=\"swiper-slide\">\t\t\t<div class=\"blog-post-item\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-thumbnail\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"650\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_03.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_03.jpg 1280w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_03-300x152.jpg 300w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_03-1024x520.jpg 1024w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_03-768x390.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_03-600x305.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>        <div class=\"post-meta on-thumbnail\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/road-highway-construction-challenges-and-solutions\/\" class=\"meta-date\">\r\n\t\t\t\t\t\t\t\t2025\u5e7412\u670817\u65e5            <\/a>\r\n\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"post-content\">\r\n\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/renovation\/\"><i class=\"ri-price-tag-3-line\"><\/i>Renovation<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/road-highway-construction-challenges-and-solutions\/\">Road &#038..<\/a><\/h4>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-content-hover\">\r\n\t\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/renovation\/\"><i class=\"ri-price-tag-3-line\"><\/i>Renovation<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/road-highway-construction-challenges-and-solutions\/\">Road &#038..<\/a><\/h4><p class=\"post-excerpt\">The construc...<\/p>        <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/road-highway-construction-challenges-and-solutions\/\" class=\"post-read-more\">\r\n\t\t\tRead More\t\t\t        <\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div><div class=\"swiper-slide\">\t\t\t<div class=\"blog-post-item\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-thumbnail\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"650\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_01.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_01.jpg 1280w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_01-300x152.jpg 300w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_01-1024x520.jpg 1024w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_01-768x390.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_01-600x305.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>        <div class=\"post-meta on-thumbnail\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/the-importance-of-civil-works-in-modern-infrastructure\/\" class=\"meta-date\">\r\n\t\t\t\t\t\t\t\t2025\u5e7412\u670817\u65e5            <\/a>\r\n\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"post-content\">\r\n\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/residential\/\"><i class=\"ri-price-tag-3-line\"><\/i>Residential<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/the-importance-of-civil-works-in-modern-infrastructure\/\">The Import..<\/a><\/h4>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-content-hover\">\r\n\t\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/residential\/\"><i class=\"ri-price-tag-3-line\"><\/i>Residential<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/the-importance-of-civil-works-in-modern-infrastructure\/\">The Import..<\/a><\/h4><p class=\"post-excerpt\">Despite prog...<\/p>        <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/17\/the-importance-of-civil-works-in-modern-infrastructure\/\" class=\"post-read-more\">\r\n\t\t\tRead More\t\t\t        <\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div><div class=\"swiper-slide\">\t\t\t<div class=\"blog-post-item\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-thumbnail\">\r\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"650\" src=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_02.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_02.jpg 1280w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_02-300x152.jpg 300w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_02-1024x520.jpg 1024w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_02-768x390.jpg 768w, https:\/\/warehousetentpro.com\/wp-content\/uploads\/2025\/12\/post_02-600x305.jpg 600w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>        <div class=\"post-meta on-thumbnail\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/08\/how-quality-construction-impacts-long-term-durability\/\" class=\"meta-date\">\r\n\t\t\t\t\t\t\t\t2025\u5e7412\u67088\u65e5            <\/a>\r\n\t\t\t\t\t        <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"post-content\">\r\n\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/industrial\/\"><i class=\"ri-price-tag-3-line\"><\/i>Industrial<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/08\/how-quality-construction-impacts-long-term-durability\/\">How Qualit..<\/a><\/h4>\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"post-content-hover\">\r\n\t\t\t\t\t\t        <div class=\"post-meta before-title\">\r\n\t\t\t            <a href=\"https:\/\/warehousetentpro.com\/index.php\/author\/shoulder\/\" class=\"meta-author\">\r\n\t\t\t\t<i class=\"ri-user-line\"><\/i>\t\t\t\tshoulder            <\/a>\r\n\t\t\t\t\t<a class=\"meta-category\" href=\"https:\/\/warehousetentpro.com\/index.php\/category\/industrial\/\"><i class=\"ri-price-tag-3-line\"><\/i>Industrial<\/a>\t\t        <\/div>\r\n\t\t<h4 class=\"post-title title-animated-border\"><a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/08\/how-quality-construction-impacts-long-term-durability\/\">How Qualit..<\/a><\/h4><p class=\"post-excerpt\">Consulting e...<\/p>        <a href=\"https:\/\/warehousetentpro.com\/index.php\/2025\/12\/08\/how-quality-construction-impacts-long-term-durability\/\" class=\"post-read-more\">\r\n\t\t\tRead More\t\t\t        <\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\t\t<script>\r\n\t\t\t(function ($) {\r\n    \t\t\t\"use strict\";\r\n\r\n\t\t\t\t$(function () {\r\n\t\t\t\t\t$('#rs-unique-slider-f799d06').each(function() {\r\n\t\t\t\t\t\tconst $this = $(this);\r\n\t\t\t\t\t\tconst $slider = $this.find('.rs-blog-posts.swiper');\r\n\t\t\t\t\t\tconst progressCircle = $this.find(\".autoplay-progress svg\")[0];\r\n\t\t\t\t\t\tconst progressContent = $this.find(\".autoplay-progress span\")[0];\r\n\r\n\t\t\t\t\t\t\/\/ Breakpoints\r\n\t\t\t\t\t\tvar el_breakpoints = elementorFrontend.config.responsive.activeBreakpoints || '';\r\n\t\t\t\t\t\tvar breakpoints = {};\r\n\t\t\t\t\t\tfor (var key in el_breakpoints) {\r\n\t\t\t\t\t\t\tif (!el_breakpoints.hasOwnProperty(key)) continue;\r\n\r\n\t\t\t\t\t\t\tvar bp = el_breakpoints[key];\r\n\r\n\t\t\t\t\t\t\tif (bp.direction === 'max') {\r\n\t\t\t\t\t\t\t\tbreakpoints[key] = bp.value;\r\n\t\t\t\t\t\t\t} else if (bp.direction === 'min') {\r\n\t\t\t\t\t\t\t\tbreakpoints[key] = null;\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t}\r\n\t\t\t\t\t\tvar xl = breakpoints['laptop'] || 1366;\r\n\t\t\t\t\t\tvar lg = breakpoints['tablet_extra'] || 1200;\r\n\t\t\t\t\t\tvar md = breakpoints['tablet'] || 1024;\r\n\t\t\t\t\t\tvar sm = breakpoints['mobile_extra'] || 880;\r\n\t\t\t\t\t\tvar xs = breakpoints['mobile'] || 767;\r\n\t\t\t\t\t\tvar xxs = 0;\r\n\r\n\t\t\t\t\t\tvar swiper = new Swiper($slider[0], {\r\n\t\t\t\t\t\t\tslidesPerView: 3,\r\n\t\t\t\t\t\t\tslidesPerGroup: 1,\r\n\t\t\t\t\t\t\tspaceBetween: 30,\r\n\t\t\t\t\t\t\tdirection: \"horizontal\",\r\n\t\t\t\t\t\t\tspeed: 500,\r\n\t\t\t\t\t\t\tinitialSlide: 0,\r\n\t\t\t\t\t\t\tloop: true,\r\n\t\t\t\t\t\t\tfreeMode: false,\r\n\t\t\t\t\t\t\tgrabCursor: false,\r\n\t\t\t\t\t\t\tmousewheel: false,\r\n\t\t\t\t\t\t\tautoHeight: false,\r\n\t\t\t\t\t\t\tcenteredSlides: false,\r\n\t\t\t\t\t\t\trtl: false,\r\n\t\t\t\t\t\t\teffect: \"\", \/\/ 'fade', cube', 'coverflow', 'flip', 'cards', 'creative'\r\n\t\t\t\t\t\t\tkeyboard: {\r\n                                enabled: false,\r\n                            },\r\n\t\t\t\t\t\t\tnavigation: {\r\n                                nextEl: $this.find(\".swiper-button-next\")[0],\r\n                                prevEl: $this.find(\".swiper-button-prev\")[0],\r\n                            },\r\n\t\t\t\t\t\t\tpagination: {\r\n                                el: $this.find(\".swiper-pagination\")[0],\r\n                                clickable: true,\r\n                                dynamicBullets: false,\r\n                                                            },\r\n\t\t\t\t\t\t\tscrollbar: {\r\n                                el: $this.find(\".swiper-scrollbar\")[0],\r\n                                hide: false,\r\n                                draggable: true,\r\n                            },\r\n\t\t\t\t\t\t\t                                autoplay: {\r\n                                    delay: 3000,\r\n                                    disableOnInteraction: false,\r\n                                },\r\n                                \t\t\t\t\t\t\tbreakpoints: {\r\n\t\t\t\t\t\t\t\t[xxs]: {\r\n\t\t\t\t\t\t\t\t\tslidesPerView: 1,\r\n\t\t\t\t\t\t\t\t\tspaceBetween: 30,\r\n                                    direction: \"horizontal\",\r\n\t\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t\t[xs]: {\r\n\t\t\t\t\t\t\t\t\tslidesPerView: 2,\r\n\t\t\t\t\t\t\t\t\tspaceBetween: 30,\r\n                                    direction: \"horizontal\",\r\n\t\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t\t[sm]: {\r\n\t\t\t\t\t\t\t\t\tslidesPerView: 2,\r\n\t\t\t\t\t\t\t\t\tspaceBetween: 30,\r\n                                    direction: \"horizontal\",\r\n\t\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t\t[md]: {\r\n\t\t\t\t\t\t\t\t\tslidesPerView: 3,\r\n\t\t\t\t\t\t\t\t\tspaceBetween: 30,\r\n                                    direction: \"horizontal\",\r\n\t\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t\t[lg]: {\r\n\t\t\t\t\t\t\t\t\tslidesPerView: 3,\r\n\t\t\t\t\t\t\t\t\tspaceBetween: 30,\r\n                                    direction: \"horizontal\",\r\n\t\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t\t[xl]: {\r\n\t\t\t\t\t\t\t\t\tslidesPerView: 3,\r\n\t\t\t\t\t\t\t\t\tspaceBetween: 30,\r\n                                    direction: \"horizontal\",\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t\t\t\t\t\t\t});\r\n\t\t\t\t});\r\n\r\n\t\t\t})(jQuery);\r\n\t\t<\/script>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3038232 e-flex e-con-boxed e-con e-parent\" data-id=\"3038232\" data-element_type=\"container\" data-e-type=\"container\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb1e390 elementor-widget__width-initial elementor-absolute gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-image\" data-id=\"cb1e390\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"rs-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n\n\n        <div class=\"rs-image  css-anim    \" >\n\n\n                                                        <img decoding=\"async\" class=\"rs-multi-image horizontal2 reverse- blend_unset\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/van.png\" alt=\"van.png\"\/>\n                                <\/div>   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26d041b e-con-full e-flex e-con e-child\" data-id=\"26d041b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-548b697 e-con-full e-flex e-con e-child\" data-id=\"548b697\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab17c1b gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"ab17c1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t<h3 class=\"title  \">Have Any Questions?<\/h3>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>The point of using Lorem Ipsum is that it has more<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5535515 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-cf7\" data-id=\"5535515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"wpcf7-contact-form-not-found\"><strong>\u62a5\u9519\uff1a<\/strong> \u672a\u627e\u5230\u8fd9\u4e2a\u8868\u5355<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7dd36b0 e-con-full e-flex e-con e-child\" data-id=\"7dd36b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17774e7 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"17774e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading style1   animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>Let\u2019s Work<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title rs-split-text-enable split-in-fade \" data-split-type=\"words\" data-duration=\"0.8\" data-delay=\"0.12\">Your Trusted Partner in Construction.<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Crafting compelling digital experiences that captivate and drive meaningful connections. our digital agency combines innovation online success.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2aac968 e-flex e-con-boxed e-con e-child\" data-id=\"2aac968\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-21e1b43 e-flex e-con-boxed e-con e-child\" data-id=\"21e1b43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55c9a0b gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"55c9a0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"430\" height=\"450\" viewBox=\"0 0 430 450\" fill=\"none\"><path d=\"M359.609 450H325.547C314.132 450 304.846 440.559 304.846 428.945V243.239C304.846 231.625 314.132 222.184 325.547 222.184H359.609C371.127 222.184 380.492 231.625 380.492 243.239V243.853C385.806 244.398 390.903 245.878 395.662 248.137V192.292C395.662 91.448 314.453 9.399 214.629 9.399C114.805 9.399 33.595 91.448 33.595 192.292V248.137C38.355 245.878 43.452 244.398 48.766 243.853V243.239C48.766 231.625 58.138 222.184 69.657 222.184H103.711C115.125 222.184 124.411 231.625 124.411 243.239V428.945C124.411 440.559 115.125 450 103.711 450H69.657C58.139 450 48.766 440.559 48.766 428.945V428.14C21.48 425.318 0 398.18 0 365.226V306.768C0 284.701 9.632 265.229 24.197 253.935V192.292C24.197 86.263 109.62 0 214.628 0C319.636 0 405.059 86.263 405.059 192.292V253.935C419.624 265.228 429.256 284.7 429.256 306.768V365.226C429.256 398.18 407.777 425.319 380.491 428.14V428.945C380.491 440.559 371.127 450 359.609 450ZM325.547 231.581C319.316 231.581 314.245 236.809 314.245 243.239V428.945C314.245 435.375 319.316 440.603 325.547 440.603H359.609C365.944 440.603 371.093 435.375 371.093 428.945V243.239C371.093 236.809 365.944 231.581 359.609 231.581H325.547ZM58.163 423.683V428.944C58.163 435.374 63.321 440.602 69.656 440.602H103.71C109.941 440.602 115.011 435.374 115.011 428.944V243.239C115.011 236.809 109.94 231.581 103.71 231.581H69.656C63.321 231.581 58.163 236.809 58.163 243.239V423.683ZM380.491 253.312V418.681C402.584 415.808 419.857 392.935 419.857 365.225V306.767C419.857 287.244 411.289 270.126 398.491 260.71C397.903 260.451 397.374 260.079 396.942 259.611C391.957 256.28 386.401 254.082 380.491 253.312ZM30.765 260.711C17.966 270.126 9.399 287.245 9.399 306.768V365.226C9.399 392.936 26.672 415.809 48.766 418.682V253.312C42.855 254.082 37.299 256.28 32.314 259.612C31.882 260.079 31.353 260.452 30.765 260.711ZM237.518 405.077H191.738C189.142 405.077 187.04 402.974 187.04 400.378C187.04 397.782 189.143 395.679 191.738 395.679H209.929V355.836C179.874 353.526 155.807 329.216 153.531 298.876H142.238C139.642 298.876 137.539 296.773 137.539 294.177C137.539 291.581 139.642 289.478 142.238 289.478H158.058C160.654 289.478 162.757 291.581 162.757 294.177C162.757 321.498 183.518 343.998 209.93 346.404V276.315H198.808C196.212 276.315 194.109 274.212 194.109 271.616C194.109 269.02 196.212 266.917 198.808 266.917H230.447C233.043 266.917 235.146 269.02 235.146 271.616C235.146 274.212 233.043 276.315 230.447 276.315H219.326V346.404C245.738 343.998 266.508 321.497 266.508 294.177C266.508 291.581 268.612 289.478 271.207 289.478H287.027C289.623 289.478 291.726 291.581 291.726 294.177C291.726 296.773 289.622 298.876 287.027 298.876H275.734C273.458 329.217 249.391 353.526 219.327 355.836V395.679H237.518C240.114 395.679 242.216 397.782 242.216 400.378C242.216 402.974 240.114 405.077 237.518 405.077ZM356.441 258.651H328.714C326.118 258.651 324.015 256.548 324.015 253.953C324.015 251.356 326.118 249.254 328.714 249.254H356.441C359.037 249.254 361.14 251.357 361.14 253.953C361.141 256.548 359.038 258.651 356.441 258.651ZM100.542 258.651H72.815C70.219 258.651 68.116 256.548 68.116 253.953C68.116 251.356 70.219 249.254 72.815 249.254H100.542C103.138 249.254 105.241 251.357 105.241 253.953C105.241 256.548 103.138 258.651 100.542 258.651Z\" fill=\"#020B0A\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\">  Phone Number:<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                +88015569569             <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7973fb gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"e7973fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"446\" height=\"450\" viewBox=\"0 0 446 450\" fill=\"none\"><path d=\"M222.895 0C99.988 0 0 100.898 0 224.914C0 349.026 99.988 450 222.895 450C345.707 450 445.623 349.026 445.623 224.914C445.622 100.898 345.706 0 222.895 0ZM222.895 441.234C104.825 441.234 8.766 344.194 8.766 224.913C8.766 105.728 104.826 8.766 222.895 8.766C340.875 8.766 436.857 105.728 436.857 224.913C436.857 344.194 340.875 441.234 222.895 441.234Z\" fill=\"#141515\"><\/path><path d=\"M325.268 52.287C324.999 52.024 324.694 51.788 324.354 51.593C324.037 51.411 323.708 51.273 323.373 51.178C294.804 34.681 261.743 25.242 226.542 25.242C191.335 25.242 158.275 34.662 129.693 51.139C129.304 51.232 128.922 51.385 128.557 51.593C128.168 51.815 127.822 52.09 127.528 52.403C98.402 69.696 74.079 94.367 57.096 123.854C57.06 123.905 57.031 123.956 57 124.007C56.959 124.076 56.922 124.147 56.887 124.219C40.246 153.249 30.715 186.929 30.715 222.808C30.715 258.586 40.174 292.178 56.701 321.161C56.784 321.373 56.88 321.579 57 321.783C57.107 321.965 57.228 322.142 57.353 322.303C74.412 351.767 98.797 376.393 127.97 393.623C128.15 393.772 128.347 393.904 128.557 394.023C128.736 394.128 128.922 394.217 129.113 394.292C157.826 410.99 191.096 420.548 226.542 420.548C262.078 420.548 295.431 410.921 324.186 394.116C324.24 394.086 324.299 394.057 324.354 394.024C324.437 393.979 324.516 393.928 324.593 393.878C353.97 376.609 378.522 351.834 395.647 322.173C395.743 322.05 395.826 321.918 395.904 321.784C395.994 321.628 396.071 321.473 396.143 321.311C412.706 292.29 422.189 258.653 422.189 222.809C422.189 150.207 383.203 86.627 325.268 52.287ZM390.45 313.526L370.898 302.118C368.805 300.892 366.126 301.607 364.906 303.693C363.686 305.783 364.392 308.468 366.485 309.687L386.085 321.129C370.556 346.798 349.144 368.453 323.756 384.152L312.443 364.381C311.247 362.285 308.574 361.54 306.463 362.755C304.364 363.957 303.635 366.632 304.837 368.734L316.192 388.586C290.761 402.704 261.755 411.012 230.925 411.732V388.819C230.925 386.397 228.964 384.436 226.542 384.436C224.12 384.436 222.159 386.397 222.159 388.819V411.732C191.269 411.012 162.209 402.688 136.737 388.549L148.074 368.733C149.276 366.631 148.546 363.955 146.447 362.754C144.336 361.546 141.664 362.285 140.468 364.38L129.179 384.115C103.784 368.416 82.372 346.771 66.837 321.116L86.426 309.686C88.518 308.466 89.224 305.785 88.004 303.692C86.784 301.6 84.106 300.882 82.013 302.117L62.472 313.516C48.475 287.775 40.235 258.41 39.529 227.191H62.179C64.601 227.191 66.562 225.23 66.562 222.808C66.562 220.386 64.601 218.425 62.179 218.425H39.529C40.24 187.269 48.456 157.949 62.436 132.252L82.012 143.676C84.111 144.905 86.79 144.19 88.003 142.1C89.223 140.01 88.517 137.325 86.425 136.106L66.801 124.654C82.348 98.975 103.802 77.311 129.238 61.613L140.467 81.237C141.663 83.333 144.33 84.078 146.446 82.864C148.545 81.662 149.275 78.986 148.073 76.885L136.802 57.185C162.257 43.08 191.298 34.78 222.158 34.06V56.973C222.158 59.395 224.119 61.356 226.541 61.356C228.963 61.356 230.924 59.394 230.924 56.973V34.059C261.724 34.779 290.712 43.067 316.125 57.149L304.836 76.884C303.634 78.986 304.363 81.661 306.462 82.863C308.578 84.079 311.251 83.338 312.442 81.236L323.689 61.576C349.131 77.278 370.579 98.942 386.12 124.641L366.483 136.107C364.39 137.327 363.685 140.011 364.904 142.101C366.118 144.188 368.797 144.896 370.896 143.677L390.484 132.244C404.446 157.941 412.662 187.27 413.373 218.426H390.731C388.309 218.426 386.348 220.387 386.348 222.809C386.348 225.231 388.309 227.192 390.731 227.192H413.375C412.67 258.416 404.442 287.781 390.45 313.526Z\" fill=\"#141515\"><\/path><path d=\"M327.547 215.867C326.721 215.039 325.603 214.569 324.432 214.569H255.376C252.476 205.329 245.789 197.795 237.174 193.76V84.672C237.174 83.518 236.719 82.409 235.907 81.59L226.011 71.595C224.361 69.933 221.431 69.933 219.781 71.595L209.891 81.59C209.078 82.409 208.623 83.518 208.623 84.672V193.75C198.164 198.646 190.552 208.719 189.094 220.704H79.359C76.937 220.704 74.976 222.665 74.976 225.087C74.976 227.509 76.937 229.47 79.359 229.47H189.135C191.162 244.823 203.276 257.006 218.512 258.988V365.856C218.512 368.278 220.474 370.239 222.895 370.239C225.316 370.239 227.278 368.278 227.278 365.856V258.987C237.508 257.657 246.315 251.716 251.623 243.318H324.431C325.603 243.318 326.721 242.849 327.546 242.02L337.442 232.028C339.134 230.318 339.134 227.567 337.442 225.857L327.547 215.867ZM217.387 86.475L222.894 80.908L228.407 86.475V191.043C228.398 191.041 228.39 191.042 228.381 191.04C226.591 190.745 224.766 190.552 222.894 190.552C221.016 190.552 219.183 190.734 217.387 191.031V86.475ZM222.895 250.505C208.711 250.505 197.602 239.264 197.602 224.913C197.602 213.324 205.301 203.625 215.757 200.483C216.67 200.216 217.587 199.941 218.458 199.772C219.905 199.511 221.376 199.318 222.896 199.318C224.416 199.318 225.889 199.511 227.336 199.772C228.207 199.942 229.126 200.217 230.041 200.485C238.857 203.134 245.71 210.416 247.633 219.613C247.657 219.774 247.607 219.934 247.649 220.093C247.71 220.315 247.735 220.591 247.785 220.828C247.999 222.166 248.193 223.514 248.193 224.913C248.193 226.538 248.007 228.118 247.719 229.66C247.678 229.883 247.644 230.108 247.597 230.329C247.283 231.794 246.843 233.21 246.292 234.57C246.17 234.867 246.024 235.154 245.89 235.446C241.907 244.303 233.124 250.505 222.895 250.505ZM322.601 234.552H255.608C255.626 234.491 255.631 234.425 255.648 234.364C256.012 233.083 256.276 231.763 256.491 230.427C256.556 230.018 256.613 229.607 256.663 229.194C256.837 227.788 256.959 226.366 256.959 224.914C256.959 224.376 256.947 223.849 256.923 223.336H322.601L328.156 228.945L322.601 234.552Z\" fill=\"#141515\"><\/path><path d=\"M222.895 206.679C212.825 206.679 204.627 214.859 204.627 224.913C204.627 235.06 212.825 243.318 222.895 243.318C232.874 243.318 240.989 235.06 240.989 224.913C240.988 214.859 232.874 206.679 222.895 206.679ZM222.895 234.552C217.657 234.552 213.393 230.229 213.393 224.913C213.393 219.693 217.657 215.445 222.895 215.445C228.127 215.445 232.223 219.603 232.223 224.913C232.222 230.229 228.037 234.552 222.895 234.552Z\" fill=\"#141515\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Opening Hours:<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                Mon-Fri: 08:00 - 17:00 Sat-Sun: Closed             <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b608240 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-service-grid\" data-id=\"b608240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-service-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"rs-addon-services style7  curve-position-\">\r\n\t\t\t<div class=\"services-inner box clip-no\">\r\n                <div class=\"media_wrap\">\r\n                                                            <div class=\"icon_style media-cmn normal\">\r\n                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"442\" height=\"444\" viewBox=\"0 0 442 444\" fill=\"none\"><path d=\"M344.849 418.796C343.943 418.796 343.075 418.436 342.435 417.796C341.795 417.156 341.435 416.287 341.435 415.382V332.52C341.435 331.615 341.795 330.747 342.435 330.107C343.075 329.466 343.943 329.107 344.849 329.107C345.754 329.107 346.622 329.466 347.262 330.107C347.902 330.747 348.262 331.615 348.262 332.52V415.382C348.262 416.287 347.902 417.156 347.262 417.796C346.622 418.436 345.754 418.796 344.849 418.796Z\" fill=\"black\"><\/path><path d=\"M290.198 312.32C289.293 312.32 288.424 311.96 287.784 311.32C287.144 310.68 286.784 309.812 286.784 308.907V236.544C286.784 235.639 287.144 234.771 287.784 234.13C288.424 233.49 289.293 233.131 290.198 233.131C291.103 233.131 291.971 233.49 292.611 234.13C293.252 234.771 293.611 235.639 293.611 236.544V308.907C293.611 309.812 293.252 310.68 292.611 311.32C291.971 311.96 291.103 312.32 290.198 312.32Z\" fill=\"black\"><\/path><path d=\"M344.849 418.796C343.943 418.796 343.075 418.436 342.435 417.796C341.795 417.156 341.435 416.287 341.435 415.382V332.52C341.435 331.615 341.795 330.747 342.435 330.107C343.075 329.466 343.943 329.107 344.849 329.107C345.754 329.107 346.622 329.466 347.262 330.107C347.902 330.747 348.262 331.615 348.262 332.52V415.382C348.262 416.287 347.902 417.156 347.262 417.796C346.622 418.436 345.754 418.796 344.849 418.796Z\" fill=\"black\"><\/path><path d=\"M399.503 312.32C398.598 312.32 397.73 311.96 397.089 311.32C396.449 310.68 396.09 309.812 396.09 308.907V236.544C396.09 235.639 396.449 234.771 397.089 234.13C397.73 233.49 398.598 233.131 399.503 233.131C400.408 233.131 401.277 233.49 401.917 234.13C402.557 234.771 402.916 235.639 402.916 236.544V308.907C402.916 309.812 402.557 310.68 401.917 311.32C401.277 311.96 400.408 312.32 399.503 312.32Z\" fill=\"black\"><\/path><path d=\"M369.786 443.733C364.676 443.729 359.661 442.345 355.272 439.727C350.883 437.11 347.282 433.356 344.849 428.861C342.417 433.356 338.816 437.11 334.428 439.728C330.039 442.346 325.024 443.729 319.914 443.733C311.131 443.722 302.711 440.229 296.5 434.018C290.289 427.807 286.795 419.387 286.784 410.604V324.758C282.727 328.622 277.338 330.774 271.735 330.769H270.271C264.471 330.762 258.912 328.455 254.811 324.354C250.711 320.252 248.404 314.692 248.398 308.893V176.852C248.421 161.615 254.486 147.01 265.263 136.24C276.04 125.47 290.649 119.414 305.886 119.402C306.402 119.402 306.912 119.519 307.377 119.745C307.842 119.971 308.249 120.299 308.568 120.706L344.849 166.82L381.132 120.706C381.452 120.299 381.859 119.971 382.324 119.745C382.789 119.519 383.299 119.402 383.815 119.402C399.052 119.414 413.661 125.47 424.438 136.24C435.215 147.01 441.28 161.615 441.303 176.852V308.907C441.296 314.707 438.99 320.267 434.888 324.368C430.787 328.47 425.227 330.776 419.427 330.783H417.959C412.357 330.787 406.969 328.635 402.913 324.772V410.621C402.898 419.401 399.403 427.817 393.194 434.024C386.984 440.231 378.566 443.723 369.786 443.733ZM348.262 415.382C348.268 421.089 350.538 426.56 354.573 430.595C358.609 434.631 364.08 436.9 369.786 436.907C376.76 436.899 383.445 434.126 388.376 429.196C393.308 424.265 396.082 417.58 396.09 410.607V308.907C396.09 308.001 396.449 307.133 397.089 306.493C397.73 305.853 398.598 305.493 399.503 305.493C400.408 305.493 401.277 305.853 401.917 306.493C402.557 307.133 402.916 308.001 402.916 308.907C402.92 312.896 404.506 316.722 407.327 319.543C410.148 322.364 413.973 323.952 417.962 323.956H419.427C423.417 323.952 427.242 322.365 430.063 319.543C432.885 316.722 434.472 312.897 434.476 308.907V176.852C434.456 163.708 429.333 151.087 420.186 141.648C411.04 132.209 398.586 126.69 385.45 126.256L347.532 174.449C347.2 174.836 346.789 175.148 346.326 175.361C345.863 175.574 345.359 175.685 344.849 175.685C344.339 175.685 343.835 175.574 343.372 175.361C342.909 175.148 342.497 174.836 342.166 174.449L304.247 126.256C291.111 126.69 278.658 132.209 269.512 141.648C260.367 151.087 255.244 163.709 255.225 176.852V308.907C255.228 312.896 256.815 316.722 259.635 319.543C262.456 322.364 266.281 323.952 270.271 323.956H271.735C275.725 323.952 279.551 322.366 282.373 319.544C285.194 316.723 286.781 312.897 286.784 308.907C286.784 308.001 287.144 307.133 287.784 306.493C288.424 305.853 289.293 305.493 290.198 305.493C291.103 305.493 291.971 305.853 292.611 306.493C293.252 307.133 293.611 308.001 293.611 308.907V410.624C293.625 417.594 296.401 424.274 301.331 429.201C306.262 434.128 312.944 436.899 319.914 436.907C325.621 436.9 331.092 434.63 335.126 430.595C339.161 426.56 341.43 421.089 341.435 415.382C341.435 414.477 341.795 413.609 342.435 412.969C343.075 412.328 343.943 411.969 344.849 411.969C345.754 411.969 346.622 412.328 347.262 412.969C347.902 413.609 348.262 414.477 348.262 415.382Z\" fill=\"black\"><\/path><path d=\"M344.852 117.224C315.747 117.224 292.068 90.9414 292.068 58.6138C292.068 26.2861 315.747 0 344.852 0C373.958 0 397.636 26.2827 397.636 58.6138C397.636 90.9449 373.954 117.224 344.852 117.224ZM344.852 6.82667C319.512 6.82667 298.895 30.0578 298.895 58.6138C298.895 87.1697 319.512 110.397 344.852 110.397C370.193 110.397 390.809 87.1663 390.809 58.6138C390.809 30.0612 370.193 6.82667 344.852 6.82667Z\" fill=\"black\"><\/path><path d=\"M110.94 143.258C110.428 143.258 109.923 143.144 109.462 142.924C109.001 142.703 108.595 142.382 108.274 141.984C107.954 141.585 107.727 141.12 107.611 140.622C107.494 140.124 107.491 139.606 107.602 139.107C110.029 128.056 113.059 117.145 116.678 106.424C138.438 41.769 176.568 1.9968 218.671 0.0375457C219.121 0.00799186 219.572 0.0694304 219.998 0.218187C220.423 0.366943 220.814 0.599965 221.147 0.903314C221.481 1.20666 221.749 1.57411 221.937 1.98368C222.125 2.39326 222.229 2.83655 222.242 3.28704C222.263 3.73485 222.196 4.18243 222.044 4.60422C221.892 5.02602 221.658 5.41376 221.357 5.74531C221.055 6.07685 220.691 6.34571 220.285 6.53652C219.879 6.72734 219.44 6.83637 218.992 6.85739C179.804 8.68011 143.974 46.7183 123.149 108.609C119.611 119.097 116.649 129.77 114.275 140.582C114.107 141.341 113.685 142.02 113.078 142.506C112.472 142.993 111.717 143.258 110.94 143.258Z\" fill=\"black\"><\/path><path d=\"M218.835 443.699H218.671C176.606 441.743 138.458 401.971 116.678 337.306C104.538 300.028 98.4845 261.037 98.7508 221.833C98.7499 207.562 99.5076 193.301 101.021 179.111C101.068 178.665 101.203 178.233 101.418 177.84C101.633 177.446 101.923 177.099 102.272 176.817C102.621 176.536 103.022 176.326 103.452 176.199C103.882 176.073 104.333 176.032 104.779 176.08C105.225 176.128 105.657 176.263 106.05 176.478C106.444 176.692 106.791 176.983 107.073 177.332C107.354 177.68 107.564 178.081 107.69 178.512C107.817 178.942 107.858 179.393 107.81 179.838C106.322 193.783 105.576 207.798 105.577 221.822C105.31 260.284 111.242 298.537 123.146 335.111C144.008 397.005 179.838 435.046 218.992 436.866C219.441 436.876 219.882 436.975 220.293 437.156C220.703 437.337 221.073 437.597 221.383 437.921C221.693 438.245 221.935 438.627 222.097 439.045C222.259 439.463 222.337 439.909 222.327 440.358C222.317 440.806 222.218 441.248 222.037 441.658C221.856 442.068 221.596 442.438 221.272 442.748C220.948 443.058 220.566 443.301 220.147 443.463C219.729 443.625 219.284 443.703 218.835 443.692V443.699Z\" fill=\"black\"><\/path><path d=\"M221.924 443.733C220.825 443.733 219.774 443.733 218.668 443.679C160.383 442.846 104.767 419.106 63.8474 377.592C22.9276 336.078 -0.00807088 280.126 2.13046e-06 221.835C0.00807514 163.544 22.9592 107.598 63.8905 66.0949C104.822 24.5921 160.444 0.867487 218.729 0.0512012C219.811 1.17347e-06 220.842 0 221.924 0C222.83 0 223.698 0.359619 224.338 0.999743C224.978 1.63987 225.338 2.50806 225.338 3.41333V440.32C225.338 441.225 224.978 442.093 224.338 442.734C223.698 443.374 222.83 443.733 221.924 443.733ZM218.511 6.88128C162.087 7.78062 108.278 30.8264 68.694 71.0461C29.1102 111.266 6.92493 165.435 6.92493 221.867C6.92493 278.298 29.1102 332.468 68.694 372.687C108.278 412.907 162.087 435.953 218.511 436.852V6.88128Z\" fill=\"black\"><\/path><path d=\"M221.924 225.256H3.4471C2.54183 225.256 1.67363 224.896 1.03351 224.256C0.393386 223.616 0.0337677 222.748 0.0337677 221.843C0.0337677 220.937 0.393386 220.069 1.03351 219.429C1.67363 218.789 2.54183 218.429 3.4471 218.429H221.924C222.83 218.429 223.698 218.789 224.338 219.429C224.978 220.069 225.338 220.937 225.338 221.843C225.338 222.748 224.978 223.616 224.338 224.256C223.698 224.896 222.83 225.256 221.924 225.256Z\" fill=\"black\"><\/path><path d=\"M221.924 110.933H35.7714C34.8661 110.933 33.9979 110.574 33.3578 109.934C32.7176 109.293 32.358 108.425 32.358 107.52C32.358 106.615 32.7176 105.747 33.3578 105.106C33.9979 104.466 34.8661 104.107 35.7714 104.107H221.924C222.83 104.107 223.698 104.466 224.338 105.106C224.978 105.747 225.338 106.615 225.338 107.52C225.338 108.425 224.978 109.293 224.338 109.934C223.698 110.574 222.83 110.933 221.924 110.933Z\" fill=\"black\"><\/path><path d=\"M158.204 339.627H35.7748C34.8695 339.627 34.0013 339.267 33.3612 338.627C32.7211 337.987 32.3614 337.119 32.3614 336.213C32.3614 335.308 32.7211 334.44 33.3612 333.8C34.0013 333.16 34.8695 332.8 35.7748 332.8H158.204C159.109 332.8 159.978 333.16 160.618 333.8C161.258 334.44 161.618 335.308 161.618 336.213C161.618 337.119 161.258 337.987 160.618 338.627C159.978 339.267 159.109 339.627 158.204 339.627Z\" fill=\"black\"><\/path><path d=\"M221.938 339.627H198.454C197.549 339.627 196.681 339.267 196.041 338.627C195.401 337.987 195.041 337.119 195.041 336.213C195.041 335.308 195.401 334.44 196.041 333.8C196.681 333.16 197.549 332.8 198.454 332.8H221.938C222.843 332.8 223.711 333.16 224.352 333.8C224.992 334.44 225.351 335.308 225.351 336.213C225.351 337.119 224.992 337.987 224.352 338.627C223.711 339.267 222.843 339.627 221.938 339.627Z\" fill=\"black\"><\/path><path d=\"M108.731 183.361C104.078 183.36 99.5298 181.98 95.6611 179.394C91.7925 176.809 88.7774 173.134 86.997 168.835C85.2166 164.536 84.751 159.805 85.6589 155.242C86.5669 150.678 88.8076 146.486 92.0979 143.196C95.3882 139.906 99.5801 137.665 104.144 136.757C108.708 135.849 113.438 136.315 117.737 138.095C122.036 139.875 125.711 142.89 128.296 146.759C130.882 150.628 132.262 155.176 132.263 159.829C132.257 166.069 129.777 172.051 125.365 176.463C120.953 180.874 114.971 183.355 108.731 183.361ZM108.731 143.131C105.428 143.132 102.199 144.112 99.4531 145.948C96.707 147.784 94.5668 150.392 93.3034 153.445C92.0399 156.497 91.7098 159.855 92.3549 163.094C93 166.334 94.5913 169.31 96.9275 171.645C99.2637 173.98 102.24 175.57 105.48 176.214C108.72 176.858 112.078 176.526 115.129 175.262C118.181 173.997 120.789 171.856 122.623 169.109C124.458 166.362 125.437 163.133 125.436 159.829C125.429 155.402 123.666 151.158 120.535 148.028C117.404 144.897 113.159 143.137 108.731 143.131Z\" fill=\"black\"><\/path><path d=\"M178.343 359.765C173.688 359.767 169.138 358.388 165.267 355.803C161.397 353.218 158.379 349.543 156.597 345.243C154.815 340.943 154.349 336.211 155.256 331.646C156.164 327.081 158.405 322.887 161.696 319.596C164.987 316.304 169.18 314.063 173.745 313.155C178.31 312.246 183.042 312.712 187.342 314.494C191.642 316.275 195.317 319.292 197.903 323.162C200.489 327.033 201.868 331.583 201.868 336.237C201.861 342.475 199.381 348.455 194.971 352.866C190.56 357.277 184.58 359.758 178.343 359.765ZM178.343 319.532C175.039 319.531 171.808 320.51 169.06 322.344C166.312 324.179 164.17 326.788 162.905 329.84C161.639 332.892 161.308 336.251 161.951 339.492C162.595 342.733 164.186 345.71 166.522 348.047C168.857 350.384 171.834 351.975 175.075 352.621C178.315 353.266 181.674 352.935 184.727 351.671C187.78 350.407 190.389 348.266 192.225 345.519C194.061 342.771 195.041 339.541 195.041 336.237C195.04 331.807 193.281 327.558 190.151 324.422C187.02 321.287 182.773 319.523 178.343 319.515V319.532Z\" fill=\"black\"><\/path><\/svg>                        <\/div>\r\n                                                                    <\/div>\r\n            <div class=\"content_part\">\r\n                    <div class=\"services-title\">\r\n                                    <h4 class=\"title\"> Office Location:<\/h4>\r\n                            <\/div>\r\n                    <div class=\"desc-text\">\r\n                New Jesrsy, 1201, USA             <\/div>\r\n            <\/div>\r\n<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Quality Workmanship Provide our people with a meaningfu&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-7568","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages\/7568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/comments?post=7568"}],"version-history":[{"count":1,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages\/7568\/revisions"}],"predecessor-version":[{"id":13779,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages\/7568\/revisions\/13779"}],"wp:attachment":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/media?parent=7568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}