{"id":4360,"date":"2025-12-29T04:51:05","date_gmt":"2025-12-29T04:51:05","guid":{"rendered":"https:\/\/demo.rstheme.com\/wordpress\/brickz\/?page_id=4360"},"modified":"2026-07-09T10:00:30","modified_gmt":"2026-07-09T02:00:30","slug":"faq","status":"publish","type":"page","link":"https:\/\/warehousetentpro.com\/index.php\/faq\/","title":{"rendered":"Faq"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4360\" class=\"elementor elementor-4360\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6febe07 e-flex e-con-boxed e-con e-parent\" data-id=\"6febe07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1f652a gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-breadcrumb\" data-id=\"d1f652a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"breadcrumb-area style3\"> \n                <div class=\"breadcrumbs-inner\"> \n                                        <span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"\u8f6c\u5230 warehousetentpro.\" href=\"https:\/\/warehousetentpro.com\" class=\"home\" ><span property=\"name\">warehousetentpro<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> &gt; <span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"\u8f6c\u5230 Blog.\" href=\"https:\/\/warehousetentpro.com\/index.php\/blog\/\" class=\"post-root post post-post\" aria-current=\"page\"><span property=\"name\">Blog<\/span><\/a><meta property=\"position\" content=\"2\"><\/span>                <\/div>\n            <\/div> \n          \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db73bf gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rstb-page-title\" data-id=\"1db73bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rstb-page-title.default\">\n\t\t\t\t\t<h1 class=\"rstb-page-title\"><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78120b5 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-divider\" data-id=\"78120b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rs-divider dot-enable\">\n\t\t\t<span> <\/span>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576fdc3 elementor-widget__width-initial elementor-widget-mobile__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"576fdc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default center  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Construction is the process of planning, designing, and building infrastructure such as residential homes, commercial and industrial facilities.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a3261a e-flex e-con-boxed e-con e-parent\" data-id=\"5a3261a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-150c31c e-con-full e-flex e-con e-child\" data-id=\"150c31c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d7067f2 e-con-full e-flex e-con e-child\" data-id=\"d7067f2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a5611ac e-con-full e-flex e-con e-child\" data-id=\"a5611ac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4804187 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"4804187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle1\">\r\n\r\n\t\t\t\t\t\t\t            <div class=\"address-icon icon_1 elementor-repeater-item-c2bdf9a\">\r\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\"><g clip-path=\"url(#clip0_28535_91)\"><path d=\"M12.1643 10.5834C11.6416 10.0673 10.989 10.0673 10.4696 10.5834C10.0734 10.9762 9.67723 11.3691 9.28769 11.7686C9.18114 11.8785 9.09125 11.9018 8.9614 11.8286C8.70503 11.6887 8.43202 11.5755 8.18564 11.4224C7.03698 10.6999 6.07477 9.77097 5.22243 8.72552C4.79959 8.20613 4.42336 7.65011 4.16033 7.02417C4.10706 6.89765 4.11705 6.81442 4.22026 6.7112C4.61647 6.32832 5.00268 5.93544 5.39223 5.54257C5.93493 4.99654 5.93493 4.35728 5.3889 3.80792C5.07926 3.49495 4.76962 3.18865 4.45998 2.87568C4.14036 2.55605 3.82406 2.23309 3.5011 1.9168C2.97838 1.40739 2.32581 1.40739 1.80641 1.92012C1.40688 2.313 1.02399 2.71586 0.617799 3.10208C0.241571 3.45833 0.0517928 3.89449 0.0118394 4.40389C-0.0514202 5.23293 0.151676 6.01535 0.438009 6.77779C1.02399 8.35595 1.91628 9.75765 2.99836 11.0428C4.45998 12.7808 6.20462 14.1559 8.24557 15.148C9.1645 15.5942 10.1167 15.9371 11.1522 15.9937C11.8647 16.0337 12.484 15.8539 12.98 15.2979C13.3196 14.9183 13.7025 14.572 14.0621 14.2091C14.5948 13.6698 14.5982 13.0172 14.0688 12.4845C13.4362 11.8485 12.8003 11.2159 12.1643 10.5834Z\" fill=\"white\"><\/path><path d=\"M11.5281 7.92979L12.7566 7.72003C12.5635 6.59135 12.0308 5.56921 11.2218 4.75682C10.3661 3.90116 9.28402 3.36178 8.09208 3.19531L7.91895 4.43054C8.8412 4.56039 9.68022 4.97657 10.3428 5.63913C10.9687 6.26506 11.3782 7.05747 11.5281 7.92979Z\" fill=\"white\"><\/path><path d=\"M13.4501 2.59031C12.0317 1.17197 10.2372 0.276344 8.25614 0L8.08301 1.23523C9.79434 1.47495 11.3459 2.25071 12.5711 3.47262C13.7331 4.63459 14.4955 6.10288 14.7719 7.71766L16.0004 7.50791C15.6775 5.63676 14.7952 3.93874 13.4501 2.59031Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_28535_91\"><rect width=\"16\" height=\"16\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t            <\/div>\r\n\t\t            \r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\r\n\t\t            \t\t\t\t            \t<div class=\"phone\">\r\n\t\t\t            \t\t\t\t\t\t                \r\n\t\t\t\t                <a href=\"tel:+990123456789\">Call us: +990 123 456 789<\/a>\r\n\t\t\t\t            <\/div>\r\n\t\t\t       \t\t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb97402 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-button\" data-id=\"fb97402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rs-button style1 unique-40630\">\r\n\r\n\t\t\t\r\n\t\t\t\t\t\t\t<a class=\"rs-btn anim-dir-angle \" href=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/contact-us\/\" >\t\r\n\t\t\t\t\t<span class=\"rs-btn-active\"><span>Let&#039;s&#039; Talk<\/span> <\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<em>\r\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 16 17\"><path d=\"M13.338 5.04405L1.88204 16.5L0 14.618L11.4546 3.16201H1.35896V0.5H16V15.141H13.338V5.04405Z\"><\/path><\/svg>\t\t\t\t\t\t<\/em>\t\r\n\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3f9b28 e-con-full e-flex e-con e-child\" data-id=\"f3f9b28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29512e4 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-accordion\" data-id=\"29512e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-accordion accordion default-style\" id=\"rs_accordion_inner_29512e4\">\n\t\t\t                <div class=\"accordion-item \">\n                    <div class=\"accordion-header\" id=\"heading_29512e40\">\n\t\t\t\t\t\t<div class=\"accordion-title collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e40\" aria-controls=\"collapse_29512e40\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">What types of construction projects do you handle?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e40\"\n                             class=\"accordion-collapse collapse \"\n                             aria-labelledby=\"heading_29512e40\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Launching a startup begins with more than just an idea it starts with creating a product that solves a real problem.<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t                <div class=\"accordion-item active\">\n                    <div class=\"accordion-header\" id=\"heading_29512e41\">\n\t\t\t\t\t\t<div class=\"accordion-title \" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e41\" aria-controls=\"collapse_29512e41\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">Do you provide complete design-to-build services?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e41\"\n                             class=\"accordion-collapse collapse show\"\n                             aria-labelledby=\"heading_29512e41\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Securing the right investment is essential for fueling growth and scaling a business. Our fundraising approach is designed<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t                <div class=\"accordion-item \">\n                    <div class=\"accordion-header\" id=\"heading_29512e42\">\n\t\t\t\t\t\t<div class=\"accordion-title collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e42\" aria-controls=\"collapse_29512e42\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">How do you ensure construction quality?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e42\"\n                             class=\"accordion-collapse collapse \"\n                             aria-labelledby=\"heading_29512e42\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Startup consulting helps entrepreneurs turn ideas into thriving businesses. By combining market insights, strategy, and execution<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t                <div class=\"accordion-item \">\n                    <div class=\"accordion-header\" id=\"heading_29512e43\">\n\t\t\t\t\t\t<div class=\"accordion-title collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e43\" aria-controls=\"collapse_29512e43\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">How long does a construction project usually take?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e43\"\n                             class=\"accordion-collapse collapse \"\n                             aria-labelledby=\"heading_29512e43\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Financial planning is the foundation of long-term stability and growth. It helps businesses and individuals make informed<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t                <div class=\"accordion-item \">\n                    <div class=\"accordion-header\" id=\"heading_29512e44\">\n\t\t\t\t\t\t<div class=\"accordion-title collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e44\" aria-controls=\"collapse_29512e44\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">Do you follow safety standards on site?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e44\"\n                             class=\"accordion-collapse collapse \"\n                             aria-labelledby=\"heading_29512e44\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Financial planning is the foundation of long-term stability and growth. It helps businesses and individuals make informed<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t                <div class=\"accordion-item \">\n                    <div class=\"accordion-header\" id=\"heading_29512e45\">\n\t\t\t\t\t\t<div class=\"accordion-title collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e45\" aria-controls=\"collapse_29512e45\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">How do you estimate project costs?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e45\"\n                             class=\"accordion-collapse collapse \"\n                             aria-labelledby=\"heading_29512e45\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Financial planning is the foundation of long-term stability and growth. It helps businesses and individuals make informed<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t                <div class=\"accordion-item \">\n                    <div class=\"accordion-header\" id=\"heading_29512e46\">\n\t\t\t\t\t\t<div class=\"accordion-title collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse_29512e46\" aria-controls=\"collapse_29512e46\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"title-text\">Can you customize projects based on client needs?<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"accordion-icons\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"expand-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 14 12\"><path d=\"M9.10883 11.4447H8.27414C8.11435 8.48238 9.92997 6.92863 10.8474 6.47434H0.09375V5.56597H10.8474C8.64561 4.34758 8.10291 1.98885 8.27529 0.555298H9.10186C8.74429 4.09092 12.4257 5.56146 14.0002 5.56597V6.46591C9.43217 6.99728 8.92742 10.315 9.10883 11.4447Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"collapse-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 15\"><path d=\"M0.0175781 9.56403V8.72934C2.97994 8.56955 4.53369 10.3852 4.98798 11.3026V0.54895H5.89635V11.3026C7.11473 9.10081 9.47347 8.55811 10.907 8.73049V9.55706C7.3714 9.19949 5.90086 12.8809 5.89635 14.4554H4.99641C4.46504 9.88737 1.14729 9.38262 0.0175781 9.56403Z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>                    <\/div>\n\t\t\t\t\t                        <div id=\"collapse_29512e46\"\n                             class=\"accordion-collapse collapse \"\n                             aria-labelledby=\"heading_29512e46\"\n                             data-bs-parent=\"#rs_accordion_inner_29512e4\">\n                            <div class=\"accordion-body\">\n\t\t\t\t\t\t\t\t<p>Financial planning is the foundation of long-term stability and growth. It helps businesses and individuals make informed<\/p>                            <\/div>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n\t\t\t        <\/div>\n        <script>\n            jQuery(document).ready(function ($) {\n                $('#rs_accordion_inner_29512e4 .accordion-collapse').on('show.bs.collapse', function () {\n                    $(this).closest('.accordion-item').addClass('active');\n                });\n\n                $('#rs_accordion_inner_29512e4 .accordion-collapse').on('hide.bs.collapse', function () {\n                    $(this).closest('.accordion-item').removeClass('active');\n                });\n            });\n        <\/script>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b7d3a0 e-con-full e-flex e-con e-parent\" data-id=\"4b7d3a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-25d07e9 e-con-full e-flex e-con e-child\" data-id=\"25d07e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9a938be e-con-full e-flex e-con e-child\" data-id=\"9a938be\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ef1faaa e-con-full e-flex e-con e-child\" data-id=\"ef1faaa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f7c7bd gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-heading\" data-id=\"9f7c7bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"prelements-heading default left  animate-  \">\n\t\t\t<div class=\"title-inner\">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-text \">\n\t\t\t\t\t\tContact with us now\t\t\t\t\t<\/span>\n\t\t\t\t<h2 class=\"title  \">Let\u2019s Collaborate With Us!<\/h2>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"descripti\">\n\t\t\t\t\t<p>Read and update the latest news from us. done eu magna quis felis.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09e59ef e-con-full e-flex e-con e-child\" data-id=\"09e59ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd8f905 gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-cf7\" data-id=\"bd8f905\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1754-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1754\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/4360#wpcf7-f1754-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1754\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1754-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n    <!-- Full Name -->\n    <div class=\"col-md-6\">\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"full-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full Name*\" value=\"\" type=\"text\" name=\"full-name\" \/><\/span>\n    <\/div>\n    <!-- Email Address -->\n    <div class=\"col-md-6\">\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email Address*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n    <\/div>\n\n    <!-- Phone Number -->\n    <div class=\"col-md-6\">\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number*\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n    <\/div>   \n    \n    <!-- Type of Service -->\n    <div class=\"col-md-6\">\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"choose-service\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"choose-service\"><option value=\"\">Your Services<\/option><option value=\"Design &amp; Build\">Design &amp; Build<\/option><option value=\"Project Management\">Project Management<\/option><option value=\"Renovation &amp; Remodeling\">Renovation &amp; Remodeling<\/option><option value=\"Structural Engineering\">Structural Engineering<\/option><option value=\"Finishing Works\">Finishing Works<\/option><\/select><\/span>\n    <\/div>\n    \n    <!-- Message -->\n    <div class=\"col-md-12\">\n        <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message*\" name=\"your-message\"><\/textarea><\/span>\n    <\/div>\n    <!-- Submit Button -->\n    <div class=\"col-md-12\">\n<div class=\"form-btn-area anim-dir-angle\">\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Submit Request\" \/><em> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\"><path d=\"M9.67029 3.6295L1.78054 11.5192L0.484375 10.2231L8.37321 2.33333H1.42029V0.5H11.5036V10.5833H9.67029V3.6295Z\" fill=\"#2B3944\"><\/path><\/svg><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" viewBox=\"0 0 12 12\" fill=\"none\"><path d=\"M9.67029 3.6295L1.78054 11.5192L0.484375 10.2231L8.37321 2.33333H1.42029V0.5H11.5036V10.5833H9.67029V3.6295Z\" fill=\"#2B3944\"><\/path><\/svg><\/em>\n<\/div>\n    <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d491c0c e-con-full e-flex e-con e-child\" data-id=\"d491c0c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ea39fd0 e-con-full e-flex e-con e-child\" data-id=\"ea39fd0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34377a1 elementor-widget-mobile__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"34377a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle1\">\r\n\r\n\t\t\t\t\t\r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\r\n\t\t            \t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t            \t<div class=\"email\">\r\n\t\t\t            \t\t\t\t\t            \t\t <span class=\"label\">Email: <\/span>\r\n\t\t\t            \t\t\t\t\t\t                <a href=\"mailto:brickzconstruction@gmail.com\">brickzconstruction@gmail.com<\/a>\r\n\t\t\t\t            <\/div>\r\n\t\t\t       \t\t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-991ec08 elementor-widget-mobile__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-contact-box\" data-id=\"991ec08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-contact-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\r\n\t\t<!-- Style 1 Start -->\r\n\t\t<div class=\"rs-contact-box\">\r\n\r\n\t\t\t\t\t\t<div class=\"address-item boxstyle1\">\r\n\r\n\t\t\t\t\t\r\n\t\t            <div class=\"address-text\">\r\n\t\t            \t\r\n\t\t            \t\t\t\t            \t<div class=\"phone\">\r\n\t\t\t            \t\t\t\t\t            \t\t <span class=\"label\">Hot Line:<\/span>\r\n\t\t\t            \t\t\t\t\t\t                \r\n\t\t\t\t                <a href=\"tel:+920866660112\">+9 (208) 6666 0112<\/a>\r\n\t\t\t\t            <\/div>\r\n\t\t\t       \t\t\t\t\t\t\t\t   \r\n\r\n\t\t            \t\t\t\t\t\t\t   \r\n\t\t            <\/div>\r\n\t\t\t\t\t<span class=\"des-right-icon\"><\/span>\r\n\t\t        <\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t<!-- Style 1 End -->\t\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-916c0e7 e-con-full e-flex e-con e-child\" data-id=\"916c0e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b8abb0 elementor-widget-laptop__width-inherit gsap-move-no rs-tween_max_btn-no elementor-widget elementor-widget-rs-hotspot\" data-id=\"8b8abb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"rs-hotspots uid-8b8abb0 auto-play\">\n                            <img decoding=\"async\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/map.jpg\" alt=\"map.jpg\">\n                        \n                <div class=\"desktop_item elementor-repeater-item-b71e9c2\">\n                \t<div class=\"rs-hotspot-item hotspot__1\">\n                \t    <div  class=\"rs-hots-figure\">    \n                                                        <div class=\"thumb-box\">\n                                <img decoding=\"async\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/contact-img1-02.jpg\" alt=\"\" \/>\n                            <\/div>\n                                                        <div class=\"content-box\">                      \n                                                            \n                                                                            <div class=\"pre-title\">\n                                            <h4 class=\"title\"> New York Office <\/h4>                                    \n                                        <\/div>\n                                                                    \n                                <!-- Start Description -->\n                                                                                \t            \n                                        <div class=\"hotspot-desc\">\n                                            <p class=\"descripti\"> Address:<br>\n1445 Myrtle. New York<\/p>\n                                        <\/div>            \t            \n                                                                                                    <!-- End Description -->\n                            <\/div>  \n                \t    <\/div>\n                        <div class=\"pre-circle-ripple\">\n                            <div class=\"line\"><\/div>\n                        <\/div>\n                \t<\/div>\n                <\/div>\n                \n                <div class=\"mobile_item elementor-repeater-item-b71e9c2\">\n                    <i class=\"remove-icon ri-close-line\"><\/i>\n                                                \n                                                    <div class=\"pre-title\">\n                                <h4 class=\"title\"> New York Office <\/h4>                                    \n                            <\/div>\n                                                                                                    \t            \n                            <div class=\"hotspot-desc\">\n                                <p class=\"descripti\"> Address:<br>\n1445 Myrtle. New York<\/p>\n                            <\/div>            \t            \n                                                            <\/div>\n            \n                <div class=\"desktop_item elementor-repeater-item-69d8a46\">\n                \t<div class=\"rs-hotspot-item hotspot__2\">\n                \t    <div  class=\"rs-hots-figure\">    \n                                                        <div class=\"thumb-box\">\n                                <img decoding=\"async\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/contact-img1-03.jpg\" alt=\"\" \/>\n                            <\/div>\n                                                        <div class=\"content-box\">                      \n                                                            \n                                                                            <div class=\"pre-title\">\n                                            <h4 class=\"title\"> Canada Office <\/h4>                                    \n                                        <\/div>\n                                                                    \n                                <!-- Start Description -->\n                                                                                \t            \n                                        <div class=\"hotspot-desc\">\n                                            <p class=\"descripti\"> Address:<br>\n29 Fortun Plaza, Atlanta.<\/p>\n                                        <\/div>            \t            \n                                                                                                    <!-- End Description -->\n                            <\/div>  \n                \t    <\/div>\n                        <div class=\"pre-circle-ripple\">\n                            <div class=\"line\"><\/div>\n                        <\/div>\n                \t<\/div>\n                <\/div>\n                \n                <div class=\"mobile_item elementor-repeater-item-69d8a46\">\n                    <i class=\"remove-icon ri-close-line\"><\/i>\n                                                \n                                                    <div class=\"pre-title\">\n                                <h4 class=\"title\"> Canada Office <\/h4>                                    \n                            <\/div>\n                                                                                                    \t            \n                            <div class=\"hotspot-desc\">\n                                <p class=\"descripti\"> Address:<br>\n29 Fortun Plaza, Atlanta.<\/p>\n                            <\/div>            \t            \n                                                            <\/div>\n            \n                <div class=\"desktop_item elementor-repeater-item-1698645\">\n                \t<div class=\"rs-hotspot-item hotspot__3\">\n                \t    <div  class=\"rs-hots-figure\">    \n                                                        <div class=\"thumb-box\">\n                                <img decoding=\"async\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/contact-img1-04.jpg\" alt=\"\" \/>\n                            <\/div>\n                                                        <div class=\"content-box\">                      \n                                                            \n                                                                            <div class=\"pre-title\">\n                                            <h4 class=\"title\"> Mexico Office <\/h4>                                    \n                                        <\/div>\n                                                                    \n                                <!-- Start Description -->\n                                                                                \t            \n                                        <div class=\"hotspot-desc\">\n                                            <p class=\"descripti\"> Address: <br>\nPhiladelphia, PA 19103.<\/p>\n                                        <\/div>            \t            \n                                                                                                    <!-- End Description -->\n                            <\/div>  \n                \t    <\/div>\n                        <div class=\"pre-circle-ripple\">\n                            <div class=\"line\"><\/div>\n                        <\/div>\n                \t<\/div>\n                <\/div>\n                \n                <div class=\"mobile_item elementor-repeater-item-1698645\">\n                    <i class=\"remove-icon ri-close-line\"><\/i>\n                                                \n                                                    <div class=\"pre-title\">\n                                <h4 class=\"title\"> Mexico Office <\/h4>                                    \n                            <\/div>\n                                                                                                    \t            \n                            <div class=\"hotspot-desc\">\n                                <p class=\"descripti\"> Address: <br>\nPhiladelphia, PA 19103.<\/p>\n                            <\/div>            \t            \n                                                            <\/div>\n            \n                <div class=\"desktop_item elementor-repeater-item-adddd7a\">\n                \t<div class=\"rs-hotspot-item hotspot__4\">\n                \t    <div  class=\"rs-hots-figure\">    \n                                                        <div class=\"thumb-box\">\n                                <img decoding=\"async\" src=\"https:\/\/demo.rstheme.com\/wordpress\/brickz\/wp-content\/uploads\/2025\/12\/contact-img1-05.jpg\" alt=\"\" \/>\n                            <\/div>\n                                                        <div class=\"content-box\">                      \n                                                            \n                                                                            <div class=\"pre-title\">\n                                            <h4 class=\"title\">  Washington Office <\/h4>                                    \n                                        <\/div>\n                                                                    \n                                <!-- Start Description -->\n                                                                                \t            \n                                        <div class=\"hotspot-desc\">\n                                            <p class=\"descripti\"> Address: <br>\n Washington, DC 20001<\/p>\n                                        <\/div>            \t            \n                                                                                                    <!-- End Description -->\n                            <\/div>  \n                \t    <\/div>\n                        <div class=\"pre-circle-ripple\">\n                            <div class=\"line\"><\/div>\n                        <\/div>\n                \t<\/div>\n                <\/div>\n                \n                <div class=\"mobile_item elementor-repeater-item-adddd7a\">\n                    <i class=\"remove-icon ri-close-line\"><\/i>\n                                                \n                                                    <div class=\"pre-title\">\n                                <h4 class=\"title\">  Washington Office <\/h4>                                    \n                            <\/div>\n                                                                                                    \t            \n                            <div class=\"hotspot-desc\">\n                                <p class=\"descripti\"> Address: <br>\n Washington, DC 20001<\/p>\n                            <\/div>            \t            \n                                                            <\/div>\n             \n        <\/div>\n        <script>\n            jQuery(document).ready(function($) {\n                $('.desktop_item').each(function(index) {\n                    var uniqueClass = 'desktop_item-' + index;\n                    $(this).addClass(uniqueClass);\n                    var parentHotspots = $(this).closest('.rs-hotspots.uid-8b8abb0');\n                    var targetMobileItem = parentHotspots.find('.mobile_item').eq(index);\n                    $(this).click(function() {\n                        if (targetMobileItem.hasClass('active')) {\n                            targetMobileItem.removeClass('active');\n                        } else {\n                            parentHotspots.find('.mobile_item.active').removeClass('active');\n                            targetMobileItem.addClass('active');\n                        }\n                    });\n                    parentHotspots.on('click', '.remove-icon', function(event) {\n                        event.stopPropagation();\n                        targetMobileItem.removeClass('active');\n                    });\n                });\n\n                \/\/ Ripple Class Switching\n                if ($('.rs-hotspots.uid-8b8abb0').hasClass('auto-play')) {\n                    var switches = $('.rs-hotspots.uid-8b8abb0 .desktop_item');\n                    var currentIndex = 0;\n                    var interval;\n                    var speed = 1500;\n\n                    function startRotation() {\n                        interval = setInterval(function() {\n                            switches.eq(currentIndex).removeClass('ripple');\n                            currentIndex = (currentIndex + 1) % switches.length;\n                            switches.eq(currentIndex).addClass('ripple');\n                        }, speed);\n                    }\n                    function stopRotation() {\n                        clearInterval(interval);\n                        switches.eq(currentIndex).removeClass('ripple');\n                    }\n                    startRotation();\n                    switches.hover(\n                        function() {\n                            stopRotation();\n                        },\n                        function() {\n                            startRotation();\n                        }\n                    );\n                }\n            });\n        <\/script>\n\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home &gt; Blog Construction is the process of planning,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4360","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages\/4360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/comments?post=4360"}],"version-history":[{"count":1,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages\/4360\/revisions"}],"predecessor-version":[{"id":13770,"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/pages\/4360\/revisions\/13770"}],"wp:attachment":[{"href":"https:\/\/warehousetentpro.com\/index.php\/wp-json\/wp\/v2\/media?parent=4360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}